{"id":8193,"date":"2024-08-11T20:10:24","date_gmt":"2024-08-11T20:10:24","guid":{"rendered":"https:\/\/longchangextracts.com\/?p=8193"},"modified":"2024-08-11T20:10:24","modified_gmt":"2024-08-11T20:10:24","slug":"american-ginseng-in-treating-atherosclerosis","status":"publish","type":"post","link":"https:\/\/longchangextracts.com\/fr\/american-ginseng-in-treating-atherosclerosis\/","title":{"rendered":"UPLC-QE-Orbitrap-MS\/MS combin\u00e9e \u00e0 la pharmacologie de r\u00e9seau et \u00e0 la v\u00e9rification exp\u00e9rimentale pour explorer le m\u00e9canisme du ginseng am\u00e9ricain dans le traitement de l'ath\u00e9roscl\u00e9rose"},"content":{"rendered":"<p>UPLC-QE-Orbitrap-MS\/MS combin\u00e9e \u00e0 la pharmacologie de r\u00e9seau et \u00e0 la v\u00e9rification exp\u00e9rimentale pour explorer le m\u00e9canisme du ginseng am\u00e9ricain dans le traitement de l'ath\u00e9roscl\u00e9rose<br \/>\nL'ath\u00e9roscl\u00e9rose (AS) est la principale cause des maladies vasculaires. Ses l\u00e9sions se caract\u00e9risent par un d\u00e9p\u00f4t partiel de lipides dans les art\u00e8res, accompagn\u00e9 d'une prolif\u00e9ration de cellules musculaires lisses et d'une matrice fibreuse, et se transforment progressivement en plaques d'ath\u00e9rome. Les manifestations cliniques de la SA comprennent les cardiopathies isch\u00e9miques, les accidents vasculaires c\u00e9r\u00e9braux isch\u00e9miques et les maladies vasculaires p\u00e9riph\u00e9riques. La pathogen\u00e8se de la SA est tr\u00e8s complexe, avec de multiples voies de signalisation. Des \u00e9tudes exp\u00e9rimentales et cliniques ont montr\u00e9 qu'elle pouvait \u00eatre li\u00e9e \u00e0 l'inflammation, au stress oxydatif, \u00e0 l'immunit\u00e9 inn\u00e9e et adaptative, \u00e0 l'infection et \u00e0 d'autres facteurs. \u00c0 l'heure actuelle, la tendance est \u00e0 la \"th\u00e9orie de l'inflammation de la r\u00e9ponse \u00e0 la blessure\", qui est de nature similaire \u00e0 l'inflammation, mais il n'y a pas encore de consensus.<\/p>\n<p>Panax Quinquefolii Radix est une racine s\u00e9ch\u00e9e du genre Panax de la famille des Araliaceae, riche en gins\u00e9nosides. La recherche a montr\u00e9 que les diff\u00e9rents gins\u00e9nosides ont des activit\u00e9s pharmacologiques telles que l'anti-inflammation, la r\u00e9gulation immunitaire et la protection du syst\u00e8me cardiovasculaire. La m\u00e9thode traditionnelle de s\u00e9chage du ginseng am\u00e9ricain est le s\u00e9chage, mais le produit fini s\u00e9ch\u00e9 pr\u00e9sente une peau rid\u00e9e, une couleur jaune br\u00fbl\u00e9, une texture dure et est difficile \u00e0 trancher ou \u00e0 \u00e9craser. La lyophilisation permet de d\u00e9shydrater et de s\u00e9cher des mat\u00e9riaux \u00e0 basse temp\u00e9rature et sous vide. Le Panacis Quinquefolii Radix (FDPQ) pr\u00e9par\u00e9 par lyophilisation a une peau lisse, une couleur brillante, une texture souple, une bonne capacit\u00e9 de r\u00e9hydratation, une consommation facile, une d\u00e9shydratation compl\u00e8te et une facilit\u00e9 de stockage et de transport. En outre, la teneur totale en gins\u00e9nosides Rg1, Re et Rb1 dans le FDPQ \u00e9tait significativement plus \u00e9lev\u00e9e que dans le ginseng am\u00e9ricain s\u00e9ch\u00e9. Dans l'ensemble, le FDPQ pr\u00e9sente des avantages par rapport au ginseng am\u00e9ricain s\u00e9ch\u00e9 en termes d'apparence et de composition interne, et offre de vastes perspectives de march\u00e9.<br \/>\nLes recherches pr\u00e9c\u00e9dentes du groupe de recherche ont montr\u00e9 que le FDPQ peut am\u00e9liorer les l\u00e9sions dues au stress oxydatif chez les souris ath\u00e9roscl\u00e9rotiques, r\u00e9duire la plaque d'ath\u00e9rome et le d\u00e9p\u00f4t de lipides dans la vo\u00fbte aortique, mais le m\u00e9canisme n'est pas encore clair. La pharmacologie des r\u00e9seaux peut r\u00e9v\u00e9ler les effets r\u00e9gulateurs des m\u00e9dicaments sur l'organisme \u00e0 un niveau syst\u00e9mique, fournissant de nouvelles id\u00e9es pour \u00e9tudier les interrelations entre les composants de la m\u00e9decine traditionnelle chinoise et les maladies. Cet article vise \u00e0 utiliser la technologie UPLC-QE Orbitrap MS\/MS combin\u00e9e \u00e0 la pharmacologie de r\u00e9seau et aux m\u00e9thodes d'ancrage mol\u00e9culaire pour explorer les substances pharmacologiques, les cibles et le potentiel de la FDPQ dans le traitement de la SA.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c0 l'heure actuelle, le nombre de personnes qui meurent chaque ann\u00e9e de maladies cardiovasculaires et c\u00e9r\u00e9brovasculaires isch\u00e9miques est le premier au monde, et l'infarctus du myocarde et l'infarctus c\u00e9r\u00e9bral caus\u00e9s par la SA sont les maladies vasculaires les plus meurtri\u00e8res. Les recherches ant\u00e9rieures du groupe de recherche ont montr\u00e9 que le FDPQ peut avoir un effet d'intervention ou de traitement de l'ath\u00e9roscl\u00e9rose. Par rapport au ginseng am\u00e9ricain s\u00e9ch\u00e9 traditionnel, le FDPQ a augment\u00e9 la teneur de certains composants de saponine, mais on ne sait toujours pas si les types de composants de saponine ont chang\u00e9 en raison des diff\u00e9rentes m\u00e9thodes et m\u00e9canismes de s\u00e9chage. En m\u00eame temps, les sources d'information sur les ingr\u00e9dients actifs dans les bases de donn\u00e9es de la m\u00e9decine traditionnelle chinoise sont uniques et m\u00eame d\u00e9pass\u00e9es, ce qui ne permet pas de refl\u00e9ter pleinement et en temps voulu les ingr\u00e9dients contenus dans le FDPQ. Par cons\u00e9quent, cet article a d'abord identifi\u00e9 les composants de saponine dans le FDPQ par UPLC-QE Orbitrap MS\/MS, puis a explor\u00e9 ses substances th\u00e9rapeutiques et ses m\u00e9canismes de traitement de la SA par le biais de la pharmacologie de r\u00e9seau combin\u00e9e \u00e0 l'amarrage mol\u00e9culaire, compl\u00e9t\u00e9e par des exp\u00e9riences cellulaires pour une v\u00e9rification pr\u00e9liminaire.<br \/>\nL'analyse UPLC-Q Exactive Orbitrap MS\/MS a permis d'identifier 28 types de gins\u00e9nosides, y compris les types de protopanaxadiol tels que Rb1, Rc et Rd, les types de protopanaxatriol tels que Re, Rh1 et Rg4, et le gins\u00e9noside anthropomorphe F11 de type Oktyrone. L'analyse de la base de donn\u00e9es a permis d'obtenir 117 cibles candidates pour le traitement de la SA par la FDPQ, dont 21 cibles principales telles que STAT3, EGFR, MAPK1, AKT1, PIK3CA, VEGFA, etc. Ce qui indique que le traitement de la SA par FDPQ pr\u00e9sente les caract\u00e9ristiques d'un traitement multi-composants et multi-cibles. L'analyse du r\u00e9seau de voies pathologiques cibles des ingr\u00e9dients du m\u00e9dicament montre qu'il existe de nombreuses cibles associ\u00e9es \u00e0 des composants tels que le gins\u00e9noside Rk3, le gins\u00e9noside Rh4, le gins\u00e9noside Rg4, le gins\u00e9noside anthropomorphe F11 et le 20 (R\/S) - gins\u00e9noside Rh1, qui peuvent \u00eatre des composants importants pour le traitement de la SA par le FDPQ. Des \u00e9tudes existantes ont montr\u00e9 que le gins\u00e9noside Rk3 a des effets antioxydants, antiapoptotiques et anti-inflammatoires, r\u00e9duisant de mani\u00e8re significative l'expression de facteurs inflammatoires tels que NF - \u03ba B, TNF - \u03b1, IL-6 et IL-1 \u03b2, abaissant de mani\u00e8re significative les niveaux s\u00e9riques d'AST et d'ALT, et r\u00e9duisant l'occurrence du stress oxydatif. Le gins\u00e9noside Rg4 peut \u00e9liminer de mani\u00e8re significative les ROS et inhiber l'activation de la prot\u00e9ine kinase activ\u00e9e par les mitog\u00e8nes p38 (MAPK) induite par les ROS, ce qui contribue \u00e0 maintenir l'int\u00e9grit\u00e9 des cellules endoth\u00e9liales. Le gins\u00e9noside RF11 de Personification est un composant unique du ginseng am\u00e9ricain. Des \u00e9tudes ont montr\u00e9 qu'il peut exercer des effets neuroprotecteurs sur les accidents vasculaires c\u00e9r\u00e9braux en r\u00e9duisant les d\u00e9fauts d'autophagie\/lysosome et en inhibant la surcharge calcique. Il peut \u00e9galement am\u00e9liorer la fonction neurologique \u00e0 long terme apr\u00e8s un accident vasculaire c\u00e9r\u00e9bral en activant la voie BDNF\/TrkB, promouvoir la neurogen\u00e8se apr\u00e8s un accident vasculaire c\u00e9r\u00e9bral et avoir un grand potentiel dans la r\u00e9\u00e9ducation chronique de l'accident vasculaire c\u00e9r\u00e9bral isch\u00e9mique. Les r\u00e9sultats de l'enrichissement de GO et KEGG sugg\u00e8rent que le m\u00e9canisme du FDPQ dans le traitement de la SA est principalement li\u00e9 \u00e0 la voie de signalisation PI3K Akt, \u00e0 la r\u00e9sistance endocrinienne, aux voies li\u00e9es aux lipides et \u00e0 l'ath\u00e9roscl\u00e9rose, \u00e0 la voie de signalisation MAPK, \u00e0 la voie de signalisation VEGF, etc. Les r\u00e9sultats de l'ancrage mol\u00e9culaire indiquent que le principe actif a une bonne activit\u00e9 de liaison avec les cibles potentielles, et les r\u00e9sultats de l'analyse de la pharmacologie de r\u00e9seau ont un certain degr\u00e9 de fiabilit\u00e9.<br \/>\nDe plus en plus de recherches confirment que la SA est une maladie inflammatoire chronique qui commence par une l\u00e9sion endoth\u00e9liale, et que l'inflammation associ\u00e9e est m\u00e9di\u00e9e par des cytokines pro-inflammatoires, des voies de signalisation inflammatoires, des lipides bioactifs et des mol\u00e9cules d'adh\u00e9sion. Des \u00e9tudes r\u00e9centes ont confirm\u00e9 que la voie de signalisation PI3K\/Akt joue un r\u00f4le important dans les r\u00e9ponses inflammatoires. PI3K est un type de prot\u00e9ine kinase qui catalyse sp\u00e9cifiquement les substances lipidiques phosphatidylinositol, tandis qu'Akt est une prot\u00e9ine kinase s\u00e9rine\/thr\u00e9onine, \u00e9galement connue sous le nom de prot\u00e9ine kinase B. PI3K catalyse sp\u00e9cifiquement la production de PIP3 par PI, qui peut activer pleinement Akt et d\u00e9clencher une r\u00e9action en cascade dans la voie de signalisation PI3K\/Akt, comme la r\u00e9gulation de la lib\u00e9ration de facteurs inflammatoires tels que NF \u03ba B, TNF - \u03b1, IL-6 et IL-1 \u03b2. La r\u00e9gulation de ces voies de signalisation peut avoir pour effet d'inhiber les r\u00e9ponses inflammatoires, d'am\u00e9liorer les dommages caus\u00e9s par le stress oxydatif et de r\u00e9duire les d\u00e9p\u00f4ts de lipides et les l\u00e9sions endoth\u00e9liales. L'activation de la voie NF - \u03ba B joue un r\u00f4le important dans la r\u00e9ponse inflammatoire. La prot\u00e9ine kinase MAPK est une substance importante qui transduit les signaux et d\u00e9clenche les r\u00e9ponses cellulaires. Apr\u00e8s l'activation de la sous-famille MAPK p38MAPK kinase sensible au stress, NF - \u03ba B peut \u00eatre activ\u00e9e par phosphorylation ou par des cytokines pro-inflammatoires (telles que le TNF \u03b1). NF - \u03ba B active \u00e9galement p38MAPK en sens inverse par le biais des cytokines pro-inflammatoires qu'il produit. L'effet bidirectionnel entre les deux acc\u00e9l\u00e8re le d\u00e9veloppement de l'ath\u00e9roscl\u00e9rose. Le facteur de croissance de l'endoth\u00e9lium vasculaire (VEGF) est s\u00e9cr\u00e9t\u00e9 par diverses cellules et se lie au r\u00e9cepteur homologue de la tyrosine kinase VEGF (VEGFR-1, VEGFR-2, VEGFR-3) dans les cellules endoth\u00e9liales, produisant divers effets en aval, favorisant la formation de nouveaux vaisseaux sanguins et la croissance des cellules endoth\u00e9liales vasculaires, promouvant ainsi la r\u00e9cup\u00e9ration fonctionnelle des tissus cardiaques ou c\u00e9r\u00e9braux apr\u00e8s une isch\u00e9mie-reperfusion. Le VEGF Akt est une voie de signalisation classique qui favorise la prolif\u00e9ration des cellules endoth\u00e9liales, inhibe l'apoptose cellulaire et favorise l'angiogen\u00e8se. La recherche a montr\u00e9 que le VEGF inhibe l'apoptose cellulaire par le biais de la cascade de signalisation PI3KAkt en aval via la voie BAD, et favorise la prolif\u00e9ration des cellules endoth\u00e9liales et l'angiogen\u00e8se par le biais de mTORC2 et FOXO1. Dans cette \u00e9tude, le m\u00e9canisme possible examin\u00e9 a \u00e9t\u00e9 v\u00e9rifi\u00e9 par des exp\u00e9riences cellulaires in vitro. Les r\u00e9sultats ont montr\u00e9 que la FDPQ pouvait augmenter le potentiel de membrane mitochondriale des cellules PC12 induites par H2O2, augmenter les activit\u00e9s des enzymes antioxydantes telles que la SOD et la CAT, r\u00e9duire le niveau de MDA dans les cellules et augmenter l'expression de PI3K\/Akt, ce qui sugg\u00e8re que la FDPQ peut \u00eatre li\u00e9e \u00e0 l'am\u00e9lioration des dommages oxydatifs, \u00e0 l'inhibition de l'apoptose et de l'inflammation dans le traitement de l'ath\u00e9roscl\u00e9rose. Cette \u00e9tude fournit une explication pr\u00e9liminaire du m\u00e9canisme d'action de la FDPQ dans le traitement de la SA \u00e0 travers de multiples composants, cibles et voies, mais d'autres v\u00e9rifications exp\u00e9rimentales sont encore n\u00e9cessaires. Cependant, une autre limite de cette \u00e9tude est qu'elle n'a pas inclus les compos\u00e9s mol\u00e9culaires de grande taille tels que les polysaccharides et les prot\u00e9ines, et d'autres recherches sont n\u00e9cessaires.<\/p>","protected":false},"excerpt":{"rendered":"<p>UPLC-QE-Orbitrap-MS\/MS combined with network pharmacology and experimental verification to explore the mechanism of American ginseng in treating atherosclerosis Atherosclerosis (AS) is the main cause of vascular diseases. Its lesions are characterized by partial lipid deposition in arteries, accompanied by proliferation of smooth muscle cells and fibrous matrix, and gradually develop into atherosclerotic plaques. The clinical [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>UPLC-QE-Orbitrap-MS\/MS combined with network pharmacology and experimental verification to explore the mechanism of American ginseng in treating atherosclerosis - China Chemical Manufacturer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/longchangextracts.com\/fr\/american-ginseng-in-treating-atherosclerosis\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UPLC-QE-Orbitrap-MS\/MS combined with network pharmacology and experimental verification to explore the mechanism of American ginseng in treating atherosclerosis - China Chemical Manufacturer\" \/>\n<meta property=\"og:description\" content=\"UPLC-QE-Orbitrap-MS\/MS combined with network pharmacology and experimental verification to explore the mechanism of American ginseng in treating atherosclerosis Atherosclerosis (AS) is the main cause of vascular diseases. Its lesions are characterized by partial lipid deposition in arteries, accompanied by proliferation of smooth muscle cells and fibrous matrix, and gradually develop into atherosclerotic plaques. The clinical [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/longchangextracts.com\/fr\/american-ginseng-in-treating-atherosclerosis\/\" \/>\n<meta property=\"og:site_name\" content=\"China Chemical Manufacturer\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-11T20:10:24+00:00\" \/>\n<meta name=\"author\" content=\"Longchang Chemical\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Longchang Chemical\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/longchangextracts.com\/american-ginseng-in-treating-atherosclerosis\/\",\"url\":\"https:\/\/longchangextracts.com\/american-ginseng-in-treating-atherosclerosis\/\",\"name\":\"UPLC-QE-Orbitrap-MS\/MS combined with network pharmacology and experimental verification to explore the mechanism of American ginseng in treating atherosclerosis - China Chemical Manufacturer\",\"isPartOf\":{\"@id\":\"https:\/\/longchangextracts.com\/#website\"},\"datePublished\":\"2024-08-11T20:10:24+00:00\",\"dateModified\":\"2024-08-11T20:10:24+00:00\",\"author\":{\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\"},\"breadcrumb\":{\"@id\":\"https:\/\/longchangextracts.com\/american-ginseng-in-treating-atherosclerosis\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/longchangextracts.com\/american-ginseng-in-treating-atherosclerosis\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/longchangextracts.com\/american-ginseng-in-treating-atherosclerosis\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/longchangextracts.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UPLC-QE-Orbitrap-MS\/MS combined with network pharmacology and experimental verification to explore the mechanism of American ginseng in treating atherosclerosis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/longchangextracts.com\/#website\",\"url\":\"https:\/\/longchangextracts.com\/\",\"name\":\"China Chemical Manufacturer\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/longchangextracts.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\",\"name\":\"Longchang Chemical\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"caption\":\"Longchang Chemical\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UPLC-QE-Orbitrap-MS\/MS combin\u00e9 \u00e0 la pharmacologie de r\u00e9seau et \u00e0 la v\u00e9rification exp\u00e9rimentale pour explorer le m\u00e9canisme du ginseng am\u00e9ricain dans le traitement de l'ath\u00e9roscl\u00e9rose - China Chemical Manufacturer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/longchangextracts.com\/fr\/american-ginseng-in-treating-atherosclerosis\/","og_locale":"fr_FR","og_type":"article","og_title":"UPLC-QE-Orbitrap-MS\/MS combined with network pharmacology and experimental verification to explore the mechanism of American ginseng in treating atherosclerosis - China Chemical Manufacturer","og_description":"UPLC-QE-Orbitrap-MS\/MS combined with network pharmacology and experimental verification to explore the mechanism of American ginseng in treating atherosclerosis Atherosclerosis (AS) is the main cause of vascular diseases. Its lesions are characterized by partial lipid deposition in arteries, accompanied by proliferation of smooth muscle cells and fibrous matrix, and gradually develop into atherosclerotic plaques. The clinical [&hellip;]","og_url":"https:\/\/longchangextracts.com\/fr\/american-ginseng-in-treating-atherosclerosis\/","og_site_name":"China Chemical Manufacturer","article_published_time":"2024-08-11T20:10:24+00:00","author":"Longchang Chemical","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Longchang Chemical","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/longchangextracts.com\/american-ginseng-in-treating-atherosclerosis\/","url":"https:\/\/longchangextracts.com\/american-ginseng-in-treating-atherosclerosis\/","name":"UPLC-QE-Orbitrap-MS\/MS combin\u00e9 \u00e0 la pharmacologie de r\u00e9seau et \u00e0 la v\u00e9rification exp\u00e9rimentale pour explorer le m\u00e9canisme du ginseng am\u00e9ricain dans le traitement de l'ath\u00e9roscl\u00e9rose - China Chemical Manufacturer","isPartOf":{"@id":"https:\/\/longchangextracts.com\/#website"},"datePublished":"2024-08-11T20:10:24+00:00","dateModified":"2024-08-11T20:10:24+00:00","author":{"@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869"},"breadcrumb":{"@id":"https:\/\/longchangextracts.com\/american-ginseng-in-treating-atherosclerosis\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/longchangextracts.com\/american-ginseng-in-treating-atherosclerosis\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/longchangextracts.com\/american-ginseng-in-treating-atherosclerosis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/longchangextracts.com\/"},{"@type":"ListItem","position":2,"name":"UPLC-QE-Orbitrap-MS\/MS combined with network pharmacology and experimental verification to explore the mechanism of American ginseng in treating atherosclerosis"}]},{"@type":"WebSite","@id":"https:\/\/longchangextracts.com\/#website","url":"https:\/\/longchangextracts.com\/","name":"Fabricant chinois de produits chimiques","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/longchangextracts.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869","name":"Longchang Chemical","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","caption":"Longchang Chemical"}}]}},"_links":{"self":[{"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/posts\/8193"}],"collection":[{"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/comments?post=8193"}],"version-history":[{"count":1,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/posts\/8193\/revisions"}],"predecessor-version":[{"id":8194,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/posts\/8193\/revisions\/8194"}],"wp:attachment":[{"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/media?parent=8193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/categories?post=8193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/tags?post=8193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}