{"id":8187,"date":"2024-08-11T20:07:20","date_gmt":"2024-08-11T20:07:20","guid":{"rendered":"https:\/\/longchangextracts.com\/?p=8187"},"modified":"2024-08-11T20:07:20","modified_gmt":"2024-08-11T20:07:20","slug":"salt-plantain-seeds","status":"publish","type":"post","link":"https:\/\/longchangextracts.com\/fr\/graines-de-plantain-salees\/","title":{"rendered":"\u00c9valuation compl\u00e8te de la qualit\u00e9 des semences de plantain sal\u00e9 sur la base de composants d'indices multiples combin\u00e9s \u00e0 la m\u00e9thode EW-TOPSIS"},"content":{"rendered":"<p>\u00c9valuation compl\u00e8te de la qualit\u00e9 des semences de plantain sal\u00e9 sur la base de composants d'indices multiples combin\u00e9s \u00e0 la m\u00e9thode EW-TOPSIS<br \/>\nLes herbes m\u00e9dicinales chinoises sont des m\u00e9dicaments traditionnels chinois uniques qui jouent un r\u00f4le important dans la pr\u00e9vention et le traitement des maladies. Il existe diff\u00e9rents types et sources de m\u00e9dicaments traditionnels chinois, qui se caract\u00e9risent par une action holistique, une composition vari\u00e9e, une cible d'action complexe et des interactions entre les composants. La qualit\u00e9 des produits de m\u00e9decine traditionnelle chinoise affecte directement l'efficacit\u00e9 clinique de la m\u00e9decine traditionnelle chinoise. Par cons\u00e9quent, un contr\u00f4le efficace de la qualit\u00e9 de la m\u00e9decine traditionnelle chinoise est une condition pr\u00e9alable pour garantir l'efficacit\u00e9 clinique de la m\u00e9decine traditionnelle chinoise. Toutefois, en raison de la teneur g\u00e9n\u00e9ralement faible en composants chimiques de la m\u00e9decine traditionnelle chinoise et de l'instabilit\u00e9 de certains composants chimiques, il est difficile de pr\u00e9parer des normes de r\u00e9f\u00e9rence chimiques pour la m\u00e9decine traditionnelle chinoise et leur co\u00fbt est \u00e9lev\u00e9, ce qui rend difficile la promotion du mode de contr\u00f4le de la qualit\u00e9 \u00e0 indices multiples. Le mode d'\u00e9valuation de la qualit\u00e9 des substances m\u00e9dicinales traditionnelles chinoises repose principalement sur l'exp\u00e9rience traditionnelle, les composants indicateurs multiples, les spectres d'empreintes digitales et les relations d'efficacit\u00e9 spectrale afin d'\u00e9valuer leur qualit\u00e9 de mani\u00e8re exhaustive. Toutefois, les m\u00e9thodes d'\u00e9valuation susmentionn\u00e9es souffrent souvent de facteurs subjectifs, d'exp\u00e9riences complexes et d'une faible reproductibilit\u00e9. \u00c0 l'heure actuelle, le mod\u00e8le d'\u00e9valuation globale multi-index reste le principal axe de recherche pour l'\u00e9valuation de la qualit\u00e9 de la m\u00e9decine traditionnelle chinoise. La m\u00e9thode de contr\u00f4le de la qualit\u00e9 multi-index de l'analyse quantitative de plusieurs composants par un seul fabricant (QAMS) utilise une substance de r\u00e9f\u00e9rence interne facilement disponible et peu co\u00fbteuse pour d\u00e9terminer simultan\u00e9ment plusieurs composants, ce qui permet d'atteindre l'objectif de contr\u00f4le de la qualit\u00e9 globale de la m\u00e9decine traditionnelle chinoise. La chimiom\u00e9trie, m\u00e9thode exp\u00e9rimentale analytique \u00e9mergente des temps modernes, se caract\u00e9rise par l'introduction de m\u00e9thodes multivari\u00e9es dans la recherche chimique, le calcul d'informations sur l'objet de la recherche et la capacit\u00e9 d'identifier et de classer rapidement et compl\u00e8tement de grandes quantit\u00e9s d'\u00e9chantillons au cours du traitement. TOPSIS est une m\u00e9thode d'analyse d\u00e9cisionnelle multicrit\u00e8res qui a \u00e9t\u00e9 largement utilis\u00e9e dans l'\u00e9valuation de la qualit\u00e9 de diverses mati\u00e8res m\u00e9dicinales traditionnelles chinoises. Cette m\u00e9thode permet d'attribuer objectivement des poids \u00e0 chaque indicateur, \u00e9vitant ainsi l'influence de facteurs subjectifs sur l'\u00e9valuation interne de la qualit\u00e9 des produits m\u00e9dicinaux chinois.<br \/>\nPlantago asiatica L. ou Plantago depression Willd. est une graine s\u00e9ch\u00e9e et m\u00fbre de Plantago asiatica L., une plante de la famille Plantago. Elle a pour effet de dissiper la chaleur, de favoriser la diur\u00e8se, d'\u00e9liminer l'humidit\u00e9, d'arr\u00eater la diarrh\u00e9e, d'am\u00e9liorer la vision et d'\u00e9liminer les mucosit\u00e9s. Plantago asiatica poss\u00e8de un large \u00e9ventail d'applications et d'abondantes sources m\u00e9dicinales, avec de vastes perspectives de d\u00e9veloppement et d'utilisation. Le sel Plantago asiatica est un produit transform\u00e9 et un m\u00e9dicament traditionnel chinois couramment utilis\u00e9 en Chine. Il a une longue histoire d'application et des effets th\u00e9rapeutiques pr\u00e9cis. Plantago asiatica contient divers composants chimiques, notamment des terp\u00e8nes cyclohex\u00e8ne-\u00e9ther, des glycosides ph\u00e9nyl\u00e9thano\u00efdes, des flavono\u00efdes, des alcalo\u00efdes, des triterp\u00e8nes et des st\u00e9rols. Cependant, Plantago asiatica appartient \u00e0 une plante m\u00e9dicinale originale \u00e0 base multiple, et les diff\u00e9rences g\u00e9ographiques dans la diversit\u00e9 g\u00e9n\u00e9tique de ses ressources g\u00e9n\u00e9tiques sont assez \u00e9videntes. Il existe des diff\u00e9rences significatives de g\u00e9notype entre les esp\u00e8ces sauvages et cultiv\u00e9es, avec des diff\u00e9rences correspondantes dans la teneur de chaque composant. Les diff\u00e9rents composants ont des effets th\u00e9rapeutiques diff\u00e9rents. Par cons\u00e9quent, l'\u00e9tablissement d'une m\u00e9thode scientifique, pratique et raisonnable d'\u00e9valuation de la qualit\u00e9 pour \u00e9valuer de mani\u00e8re compl\u00e8te et pr\u00e9cise la qualit\u00e9 du Plantago asiatica sal\u00e9 et guider l'utilisation rationnelle des ressources de Plantago asiatica rev\u00eat une grande importance pratique. Li et al. ont optimis\u00e9 la technologie de traitement du Plantago asiatica sal\u00e9 en utilisant la m\u00e9thode de pond\u00e9ration mixte AHP-CRITIC et la m\u00e9thodologie de la surface de r\u00e9ponse, tandis que Gu et al. ont contr\u00f4l\u00e9 quantitativement les niveaux d'acide ginnipponique, de verbascoside et d'isoverbascoside dans les produits Plantago asiatica bruts et sal\u00e9s \u00e0 l'aide de la m\u00e9thode UPLC-Q-TOF\/MS, Li et al. ont utilis\u00e9 la pharmacologie combin\u00e9e \u00e0 la m\u00e9tabolomique pour comparer et \u00e9tudier les effets diur\u00e9tiques du Plantago asiatica cru et sal\u00e9 sur des rats mod\u00e8les charg\u00e9s en solution saline, et pour \u00e9lucider leurs m\u00e9canismes d'action. \u00c0 l'heure actuelle, il existe peu de composants de contr\u00f4le quantitatif pour le Plantago asiatica sal\u00e9 dans la recherche, et aucun rapport de litt\u00e9rature n'a \u00e9t\u00e9 retrouv\u00e9 sur la m\u00e9thode d'\u00e9valuation unique et multiple de ses composants. En outre, l'\u00e9valuation globale de la qualit\u00e9 de Plantago asiatica a \u00e9t\u00e9 r\u00e9alis\u00e9e \u00e0 l'aide de la chimiom\u00e9trie combin\u00e9e \u00e0 la m\u00e9thode de l'entropie et de la distance pond\u00e9rale. Cette \u00e9tude a collect\u00e9 des mati\u00e8res m\u00e9dicinales de Plantago asiatica dans 18 zones de production repr\u00e9sentatives de cinq provinces, \u00e0 savoir Jiangxi, Henan, Anhui, Shandong et Guangxi. Plantago asiatica a \u00e9t\u00e9 trait\u00e9 selon la m\u00eame m\u00e9thode, conform\u00e9ment aux exigences de traitement de Plantago asiatica sal\u00e9 selon la premi\u00e8re partie de l'\u00e9dition 2020 de la pharmacop\u00e9e chinoise et les quatre parties de la m\u00e9thode de torr\u00e9faction saline. La m\u00e9thode HPLC-QAMS a \u00e9t\u00e9 utilis\u00e9e pour d\u00e9terminer la qualit\u00e9 de Plantago asiatica. Il y a 10 composants dans les graines de plantain sal\u00e9es, l'\u00e9valuation compl\u00e8te de la qualit\u00e9 des produits sal\u00e9s Plantago asiatica de diff\u00e9rentes origines en utilisant la chimiom\u00e9trie combin\u00e9e avec la m\u00e9thode TOPSIS de poids d'entropie. Afin de fournir des donn\u00e9es exp\u00e9rimentales scientifiques pour le contr\u00f4le de la qualit\u00e9 globale du Plantago asiatica sal\u00e9, et de fournir des r\u00e9f\u00e9rences pour le d\u00e9veloppement et l'utilisation rationnels des ressources de Plantago asiatica.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Pr\u00e9paration de la solution d'essai. Lors de la pr\u00e9paration de la solution d'essai pour cette exp\u00e9rience, les solvants d'extraction ont d'abord \u00e9t\u00e9 s\u00e9lectionn\u00e9s : 60% m\u00e9thanol, 70% m\u00e9thanol et 70% \u00e9thanol. Les r\u00e9sultats ont montr\u00e9 que le taux d'extraction des 10 composants mesur\u00e9s \u00e9tait plus \u00e9lev\u00e9 lorsqu'ils \u00e9taient extraits avec le m\u00e9thanol 70%. Ensuite, la m\u00e9thode et la dur\u00e9e d'extraction ont \u00e9t\u00e9 \u00e9tudi\u00e9es, en utilisant des ultrasons et en chauffant \u00e0 reflux pendant 40, 50, 60 et 70 minutes, respectivement. Les r\u00e9sultats ont montr\u00e9 que lorsque le m\u00e9thanol 70% \u00e9tait chauff\u00e9 et refroidi pendant 60 minutes, le taux d'extraction des 10 composants \u00e9tait le plus \u00e9lev\u00e9 et l'interf\u00e9rence des impuret\u00e9s \u00e9tait la plus faible. Apr\u00e8s un examen approfondi, la m\u00e9thode d'extraction optimale pour l'\u00e9chantillon de psyllium sal\u00e9 a finalement \u00e9t\u00e9 d\u00e9termin\u00e9e comme \u00e9tant l'extraction \u00e0 reflux pendant 60 minutes avec le m\u00e9thanol 70%.<\/p>\n<p>M\u00e9thode QAMS et \u00e9valuation des r\u00e9sultats chimiom\u00e9triques. Afin d'\u00e9valuer objectivement la qualit\u00e9 des mati\u00e8res m\u00e9dicinales de Plantago asiatica, 18 lots de Plantago asiatica de diff\u00e9rentes origines dans 5 provinces du pays ont \u00e9t\u00e9 s\u00e9lectionn\u00e9s et trait\u00e9s selon la m\u00e9thode du sel de Plantago asiatica de la pharmacop\u00e9e chinoise actuelle. Les m\u00e9thodes QAMS et ESM ont \u00e9t\u00e9 utilis\u00e9es pour analyser quantitativement et d\u00e9tecter 10 composants dans les 18 lots de sel Plantago asiatica. Parall\u00e8lement, la st\u0153chiom\u00e9trie chimique a \u00e9t\u00e9 utilis\u00e9e pour analyser les r\u00e9sultats des tests. Les r\u00e9sultats ont montr\u00e9 que la teneur en 10 composants chimiques, dont l'aucubine, le g\u00e9niposide, le 10 hydroxy glycoside de Plantago asiatica, le glycoside de Plantago asiatica, le verbascoside, l'isoverbascoside, la querc\u00e9tine, le kaempf\u00e9rol, la lut\u00e9oline et l'apig\u00e9nine, dans le Plantago asiatica de diff\u00e9rentes origines fluctuait dans une certaine mesure, mais que la qualit\u00e9 du Plantago asiatica de la m\u00eame origine \u00e9tait relativement stable. Les r\u00e9sultats de l'EW-TOPSIS ont montr\u00e9 que la qualit\u00e9 globale des graines de plantain sal\u00e9 obtenues dans la zone de production de la province de Jiangxi \u00e9tait bonne. La proximit\u00e9 euclidienne moyenne de la solution optimale des graines de plantain sal\u00e9es obtenues dans le comt\u00e9 de Xingan, province de Jiangxi, \u00e9tait plus \u00e9lev\u00e9e que celle des \u00e9chantillons provenant d'autres zones de production, ce qui indique que la qualit\u00e9 globale des produits sal\u00e9s obtenus \u00e0 partir des graines de plantain produites dans le comt\u00e9 de Xingan, province de Jiangxi, \u00e9tait bonne.<\/p>\n<p>En r\u00e9sum\u00e9, cette exp\u00e9rience a utilis\u00e9 la m\u00e9thode HPLC-QAMS combin\u00e9e \u00e0 la chimiom\u00e9trie et \u00e0 la m\u00e9thode TOPSIS \u00e0 poids entropique pour \u00e9valuer de mani\u00e8re exhaustive la qualit\u00e9 du psyllium sal\u00e9 obtenu \u00e0 partir de diff\u00e9rentes origines. Un mode de contr\u00f4le quantitatif de la qualit\u00e9 pour 10 composants indicateurs du psyllium sal\u00e9 a \u00e9t\u00e9 \u00e9tabli, ce qui a augment\u00e9 le nombre de composants mesur\u00e9s quantitativement par rapport aux rapports de la litt\u00e9rature existante. Parall\u00e8lement, la m\u00e9thode HPLC-QAMS a permis de r\u00e9duire efficacement le co\u00fbt de l'inspection, ce qui favorise la popularisation et l'application d'un mode de contr\u00f4le quantitatif des composants indicateurs multiples. Une m\u00e9thode compl\u00e8te d'\u00e9valuation de la qualit\u00e9 combinant la chimiom\u00e9trie et la m\u00e9thode de distance de poids entropique a \u00e9t\u00e9 \u00e9tablie. La m\u00e9thode \u00e9tablie est stable, pr\u00e9cise et r\u00e9alisable, et contr\u00f4le la qualit\u00e9 de l'herbe m\u00e9dicinale sous de multiples aspects et perspectives, fournissant une base exp\u00e9rimentale pour l'\u00e9tablissement de ses normes de qualit\u00e9. Elle permet \u00e9galement d'explorer plus avant les diff\u00e9rences pharmacologiques caus\u00e9es par les composants chimiques du psyllium sal\u00e9 obtenu \u00e0 partir de diff\u00e9rentes origines et des plantes m\u00e9dicinales. L'utilisation rationnelle des ressources permet d'\u00e9tayer les donn\u00e9es. Parall\u00e8lement, les mati\u00e8res premi\u00e8res de la m\u00e9decine traditionnelle chinoise ont \u00e9galement un certain impact sur la qualit\u00e9 de ses produits. Dans cette \u00e9tude, la m\u00eame mati\u00e8re premi\u00e8re de Plantago asiatica a \u00e9t\u00e9 s\u00e9lectionn\u00e9e pour obtenir le sel de Plantago asiatica en vue d'un contr\u00f4le quantitatif \u00e0 plusieurs indices et d'une \u00e9valuation chimiom\u00e9trique compl\u00e8te. \u00c0 l'avenir, diff\u00e9rentes mati\u00e8res premi\u00e8res seront collect\u00e9es pour des recherches plus approfondies.<\/p>","protected":false},"excerpt":{"rendered":"<p>Comprehensive quality evaluation of salt plantain seeds based on multi index components combined with EW-TOPSIS method Chinese medicinal herbs are unique traditional Chinese medicines that play an important role in preventing and treating diseases. There are various types and sources of traditional Chinese medicine, which have the characteristics of holistic action, diverse composition, complex target [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comprehensive quality evaluation of salt plantain seeds based on multi index components combined with EW-TOPSIS method - China Chemical Manufacturer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/longchangextracts.com\/fr\/graines-de-plantain-salees\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comprehensive quality evaluation of salt plantain seeds based on multi index components combined with EW-TOPSIS method - China Chemical Manufacturer\" \/>\n<meta property=\"og:description\" content=\"Comprehensive quality evaluation of salt plantain seeds based on multi index components combined with EW-TOPSIS method Chinese medicinal herbs are unique traditional Chinese medicines that play an important role in preventing and treating diseases. There are various types and sources of traditional Chinese medicine, which have the characteristics of holistic action, diverse composition, complex target [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/longchangextracts.com\/fr\/graines-de-plantain-salees\/\" \/>\n<meta property=\"og:site_name\" content=\"China Chemical Manufacturer\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-11T20:07:20+00:00\" \/>\n<meta name=\"author\" content=\"Longchang Chemical\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Longchang Chemical\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/longchangextracts.com\/salt-plantain-seeds\/\",\"url\":\"https:\/\/longchangextracts.com\/salt-plantain-seeds\/\",\"name\":\"Comprehensive quality evaluation of salt plantain seeds based on multi index components combined with EW-TOPSIS method - China Chemical Manufacturer\",\"isPartOf\":{\"@id\":\"https:\/\/longchangextracts.com\/#website\"},\"datePublished\":\"2024-08-11T20:07:20+00:00\",\"dateModified\":\"2024-08-11T20:07:20+00:00\",\"author\":{\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\"},\"breadcrumb\":{\"@id\":\"https:\/\/longchangextracts.com\/salt-plantain-seeds\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/longchangextracts.com\/salt-plantain-seeds\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/longchangextracts.com\/salt-plantain-seeds\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/longchangextracts.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comprehensive quality evaluation of salt plantain seeds based on multi index components combined with EW-TOPSIS method\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/longchangextracts.com\/#website\",\"url\":\"https:\/\/longchangextracts.com\/\",\"name\":\"China Chemical Manufacturer\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/longchangextracts.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\",\"name\":\"Longchang Chemical\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"caption\":\"Longchang Chemical\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9valuation compl\u00e8te de la qualit\u00e9 des graines de plantain sal\u00e9 sur la base de composants multi-index combin\u00e9s \u00e0 la m\u00e9thode EW-TOPSIS - China Chemical Manufacturer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/longchangextracts.com\/fr\/graines-de-plantain-salees\/","og_locale":"fr_FR","og_type":"article","og_title":"Comprehensive quality evaluation of salt plantain seeds based on multi index components combined with EW-TOPSIS method - China Chemical Manufacturer","og_description":"Comprehensive quality evaluation of salt plantain seeds based on multi index components combined with EW-TOPSIS method Chinese medicinal herbs are unique traditional Chinese medicines that play an important role in preventing and treating diseases. There are various types and sources of traditional Chinese medicine, which have the characteristics of holistic action, diverse composition, complex target [&hellip;]","og_url":"https:\/\/longchangextracts.com\/fr\/graines-de-plantain-salees\/","og_site_name":"China Chemical Manufacturer","article_published_time":"2024-08-11T20:07:20+00:00","author":"Longchang Chemical","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Longchang Chemical","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/longchangextracts.com\/salt-plantain-seeds\/","url":"https:\/\/longchangextracts.com\/salt-plantain-seeds\/","name":"\u00c9valuation compl\u00e8te de la qualit\u00e9 des graines de plantain sal\u00e9 sur la base de composants multi-index combin\u00e9s \u00e0 la m\u00e9thode EW-TOPSIS - China Chemical Manufacturer","isPartOf":{"@id":"https:\/\/longchangextracts.com\/#website"},"datePublished":"2024-08-11T20:07:20+00:00","dateModified":"2024-08-11T20:07:20+00:00","author":{"@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869"},"breadcrumb":{"@id":"https:\/\/longchangextracts.com\/salt-plantain-seeds\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/longchangextracts.com\/salt-plantain-seeds\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/longchangextracts.com\/salt-plantain-seeds\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/longchangextracts.com\/"},{"@type":"ListItem","position":2,"name":"Comprehensive quality evaluation of salt plantain seeds based on multi index components combined with EW-TOPSIS method"}]},{"@type":"WebSite","@id":"https:\/\/longchangextracts.com\/#website","url":"https:\/\/longchangextracts.com\/","name":"Fabricant chinois de produits chimiques","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/longchangextracts.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869","name":"Longchang Chemical","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","caption":"Longchang Chemical"}}]}},"_links":{"self":[{"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/posts\/8187"}],"collection":[{"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/comments?post=8187"}],"version-history":[{"count":1,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/posts\/8187\/revisions"}],"predecessor-version":[{"id":8188,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/posts\/8187\/revisions\/8188"}],"wp:attachment":[{"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/media?parent=8187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/categories?post=8187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/tags?post=8187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}