{"id":8023,"date":"2024-08-11T17:51:51","date_gmt":"2024-08-11T17:51:51","guid":{"rendered":"https:\/\/longchangextracts.com\/?p=8023"},"modified":"2024-08-11T17:51:51","modified_gmt":"2024-08-11T17:51:51","slug":"immunosuppressed-mice","status":"publish","type":"post","link":"https:\/\/longchangextracts.com\/fr\/immunosuppressed-mice\/","title":{"rendered":"Effet de la myric\u00e9tine sur la fonction immunitaire des souris immunod\u00e9prim\u00e9es par le cyclophosphamide"},"content":{"rendered":"<p>Effet de la myric\u00e9tine sur la fonction immunitaire des souris immunod\u00e9prim\u00e9es par le cyclophosphamide<br \/>\nLe syst\u00e8me immunitaire peut prot\u00e9ger les organismes contre les infections caus\u00e9es par des agents pathog\u00e8nes afin de maintenir l'\u00e9quilibre et la sant\u00e9 g\u00e9n\u00e9rale. L'immunosuppression est un dysfonctionnement immunitaire temporaire ou \u00e0 long terme. En raison des dommages subis par le syst\u00e8me immunitaire, les organismes deviennent plus sensibles aux agents pathog\u00e8nes et sont moins r\u00e9sistants. M\u00eame des agents pathog\u00e8nes mineurs qui ne sont g\u00e9n\u00e9ralement pas pris au s\u00e9rieux peuvent facilement provoquer des infections. Actuellement, de nombreux immunomodulateurs utilis\u00e9s en pratique clinique ont des effets secondaires, tels que le l\u00e9vamisole et le Bacillus subtilis. Par cons\u00e9quent, il est toujours n\u00e9cessaire de rechercher et de d\u00e9velopper de nouveaux immunomodulateurs pour aider au traitement des maladies li\u00e9es \u00e0 la suppression du syst\u00e8me immunitaire.<\/p>\n<p>\u00c0 la fin du XVIIIe si\u00e8cle, un cristal jaune clair appel\u00e9 myric\u00e9tine (MYR) a \u00e9t\u00e9 extrait de l'\u00e9corce du Yangmei de la famille des Myriaceae (voir figure 1). La myric\u00e9tine est un compos\u00e9 flavono\u00efde que l'on trouve dans les fruits, les l\u00e9gumes, le th\u00e9 et le vin, et qui constitue un ingr\u00e9dient actif et un additif importants dans de nombreux aliments. La recherche pharmacologique moderne montre que les FMA ont des effets th\u00e9rapeutiques sur une vari\u00e9t\u00e9 de maladies, y compris diff\u00e9rents types de cancer, les maladies inflammatoires, l'ath\u00e9roscl\u00e9rose, la maladie d'Alzheimer et les infections microbiennes pathog\u00e8nes. Toutefois, la fonction de ces flavono\u00efdes n'est pas encore enti\u00e8rement comprise, notamment en ce qui concerne la r\u00e9gulation du syst\u00e8me immunitaire.<\/p>\n<p>Le cyclophosphamide (CTX) est un inducteur immunosuppresseur qui a \u00e9t\u00e9 largement utilis\u00e9 comme chimioth\u00e9rapie et modificateur de la maladie pour combattre certaines tumeurs solides, les lymphomes et certaines maladies auto-immunes. Le CTX peut endommager l'ADN des cellules normales, ce qui est l'une des raisons pour lesquelles il peut exercer une immunosuppression. Actuellement, il est \u00e9galement utilis\u00e9 comme immunosuppresseur en clinique. Le FJM est \u00e9galement un m\u00e9dicament de mod\u00e9lisation couramment utilis\u00e9 par divers laboratoires pour construire des mod\u00e8les animaux id\u00e9aux de d\u00e9ficience immunitaire.<\/p>\n<p>Par cons\u00e9quent, nous avons utilis\u00e9 le CTX pour injecter des souris par voie intrap\u00e9riton\u00e9ale afin de r\u00e9duire leur immunit\u00e9 et d'\u00e9tablir un mod\u00e8le immunosuppresseur. Nous avons trait\u00e9 les souris mod\u00e8les avec des FJM et \u00e9valu\u00e9 les indices de la rate et du thymus, la capacit\u00e9 de prolif\u00e9ration des lymphocytes de la rate, les niveaux d'h\u00e9molysine s\u00e9rique, la capacit\u00e9 des cellules \u00e0 former des anticorps, ainsi que les niveaux de s\u00e9cr\u00e9tion des cytokines s\u00e9riques interleukine-2 (IL-2), interf\u00e9ron - \u03b3 (IFN - \u03b3), interleukine-4 (IL-4), interleukine-6 (IL-6), afin de d\u00e9velopper les FJM en tant que nouvel agent immunomodulateur.<\/p>\n<p>&nbsp;<\/p>\n<p>L'immunosuppression est une manifestation d'un dysfonctionnement immunitaire dans le corps humain. Sous l'influence combin\u00e9e d'un ou de plusieurs facteurs, les dommages immunitaires dans le corps humain peuvent le rendre plus sensible aux infections et entra\u00eener des l\u00e9sions li\u00e9es \u00e0 l'immunit\u00e9. Le FJM est une substance flavono\u00efde que l'on trouve dans de nombreux aliments et qui a des effets tels que la protection du foie, la lutte contre les tumeurs, l'anti-inflammation, l'antithrombose, l'antioxydation, etc. De nombreux rapports ont \u00e9galement \u00e9t\u00e9 publi\u00e9s sur sa r\u00e9gulation immunitaire pr\u00e9clinique. La FJM peut am\u00e9liorer les sympt\u00f4mes des l\u00e9sions cutan\u00e9es induites par le calcitriol chez les souris atteintes de dermatite atopique, r\u00e9guler l'\u00e9quilibre Th1\/Th2 local et r\u00e9parer les barri\u00e8res cutan\u00e9es endommag\u00e9es. Lors d'exp\u00e9riences in vitro, Hou et al. ont constat\u00e9 que les FJM ont un effet inhibiteur sur les facteurs inflammatoires dans les k\u00e9ratinocytes immortalis\u00e9s humains induits par le facteur de n\u00e9crose tumorale \u03b1 (TNF-\u03b1)\/IFN-\u03b3, et peuvent bloquer les voies de signalisation STAT1 et NF- \u03ba B. MYR a augment\u00e9 de mani\u00e8re significative la proportion de cellules Treg et a favoris\u00e9 la restauration de l'\u00e9quilibre immunitaire chez les souris atteintes de colite.<br \/>\nLe CTX est un type d'agent alkylant dot\u00e9 de vastes propri\u00e9t\u00e9s antitumorales. Il a d'abord \u00e9t\u00e9 qualifi\u00e9 de m\u00e9dicament anticanc\u00e9reux \"latent\" \u00e0 large spectre, s\u00e9lectif vis-\u00e0-vis des cellules T et capable d'induire des dommages \u00e0 l'ADN et de le r\u00e9parer in vivo. En raison de sa capacit\u00e9 \u00e0 traiter les maladies auto-immunes et \u00e0 r\u00e9guler l'immunit\u00e9 excessive, ainsi que de sa grande facilit\u00e9 de mod\u00e9lisation et de ses exigences mat\u00e9rielles simples, le CTX est actuellement un inducteur couramment utilis\u00e9 pour les mod\u00e8les animaux immunod\u00e9prim\u00e9s dans les laboratoires. Cette exp\u00e9rience utilise la mod\u00e9lisation CTX pour \u00e9valuer le niveau immunitaire des FJM. Par rapport au groupe de contr\u00f4le normal, les indicateurs li\u00e9s \u00e0 la r\u00e9ponse immunitaire, tels que la rate, l'indice du thymus et le niveau de s\u00e9cr\u00e9tion des cytokines, ont \u00e9t\u00e9 r\u00e9duits de mani\u00e8re significative dans le groupe trait\u00e9 par Mod, ce qui indique que l'\u00e9tablissement du mod\u00e8le de souris immunod\u00e9ficientes a \u00e9t\u00e9 couronn\u00e9 de succ\u00e8s. La fonction immunitaire de l'organisme est \u00e9troitement li\u00e9e et mutuellement influenc\u00e9e par l'\u00e9tat fonctionnel des organes immunitaires tels que la rate et le thymus. Lorsque la capacit\u00e9 immunitaire de l'organisme est supprim\u00e9e, la rate et le thymus diminuent. Dans cette \u00e9tude, on a constat\u00e9 que le FJM att\u00e9nuait l'atrophie des organes immunitaires de la rate et du thymus chez les souris caus\u00e9e par le FJM, entra\u00eenant une augmentation du poids et de l'indice des organes immunitaires. Cela indique que le FJM peut renforcer le niveau immunitaire des souris dans une certaine mesure. Par rapport aux donn\u00e9es du groupe Mod, les trois groupes trait\u00e9s par FJM ont augment\u00e9 de mani\u00e8re significative les indices de la rate et du thymus, et le degr\u00e9 d'augmentation de cette tendance indique une certaine d\u00e9pendance de l'efficacit\u00e9 du traitement par rapport \u00e0 la dose de m\u00e9dicament. Il convient de noter qu'apr\u00e8s l'application de doses \u00e9lev\u00e9es de FJM, les deux valeurs \u00e9taient proches du niveau du groupe t\u00e9moin. Les r\u00e9sultats indiquent que le FJM peut att\u00e9nuer les l\u00e9sions des organes immunitaires caus\u00e9es par le CTX et qu'il a un effet de renforcement immunitaire sur les organes immunitaires.<br \/>\nLe syst\u00e8me immunitaire adaptatif, qui comprend les r\u00e9ponses immunitaires cellulaires et humorales, peut prot\u00e9ger l'organisme contre l'invasion de pathog\u00e8nes sp\u00e9cifiques. La prolif\u00e9ration des lymphocytes joue un r\u00f4le crucial dans l'activation de l'immunit\u00e9 adaptative et est souvent utilis\u00e9e pour \u00e9valuer la capacit\u00e9 de r\u00e9ponse immunitaire des animaux. La ConA et le LPS peuvent stimuler la prolif\u00e9ration des lymphocytes T et B, respectivement. Pour confirmer davantage l'effet immunitaire du FJM, nous avons d\u00e9tect\u00e9 les niveaux de s\u00e9cr\u00e9tion des lymphocytes sous l'action de la ConA et du LPS. Les r\u00e9sultats exp\u00e9rimentaux indiquent que l'application de FJM peut att\u00e9nuer de mani\u00e8re significative l'inhibition de la CTX sur les lymphocytes, et que les changements observ\u00e9s suite \u00e0 l'application de diff\u00e9rentes concentrations de FJM d\u00e9pendent quelque peu du dosage du m\u00e9dicament. La recherche a montr\u00e9 qu'un d\u00e9s\u00e9quilibre dans le rapport entre les lymphocytes CD4+T et les lymphocytes CD8+T a un impact sur la fonction immunitaire. L'analyse par cytom\u00e9trie de flux a r\u00e9v\u00e9l\u00e9 que les sous-groupes CD4+ et CD8+ des souris trait\u00e9es par CTX \u00e9taient significativement r\u00e9duits et que le rapport CD4+\/CD8+ diminuait (P&lt;0,05 ou P&lt;0,01), ce qui indique que les souris se trouvaient dans un \u00e9tat d&#039;immunosuppression. Par rapport au groupe du mod\u00e8le Mod, chaque groupe de dose de FJM peut augmenter le nombre de sous-ensembles de cellules T CD4+ et CD8+, ainsi que le rapport sous-ensemble CD4+\/CD8+ (P&lt;0,05 ou P&lt;0,01), le groupe \u00e0 forte dose montrant un effet dose-d\u00e9pendant significatif. Le FJM peut \u00eatre impliqu\u00e9 dans l&#039;influence des niveaux de cellules CD4+ et CD8+, dans la r\u00e9gulation de leur d\u00e9s\u00e9quilibre immunitaire et dans leur r\u00e9tablissement \u00e0 des niveaux normaux. Par cons\u00e9quent, cela indique que le FJM peut renforcer l&#039;immunit\u00e9 cellulaire et humorale, ce qui est coh\u00e9rent avec la conclusion tir\u00e9e de ses effets sur les indices de la rate et du thymus.<br \/>\nLes variations de l'h\u00e9molysine s\u00e9rique peuvent refl\u00e9ter la quantit\u00e9 d'anticorps produits dans l'organisme au niveau mol\u00e9culaire, et une augmentation de l'h\u00e9molysine s\u00e9rique peut renforcer la r\u00e9ponse sp\u00e9cifique des anticorps aux antig\u00e8nes cellulaires d\u00e9pendants du thymus. Sur la base des r\u00e9sultats de l'exp\u00e9rience de contr\u00f4le, nous avons constat\u00e9 que, par rapport au groupe t\u00e9moin, la teneur en h\u00e9molysine dans le groupe de souris immunosuppressives induites par CTX a diminu\u00e9, de m\u00eame que le nombre de cellules productrices d'anticorps. Diff\u00e9rentes doses de FJM ont augment\u00e9 de mani\u00e8re significative la formation d'h\u00e9molysine s\u00e9rique chez les souris immunod\u00e9pressives induites par CTX, et ont \u00e9galement eu un certain effet d'am\u00e9lioration sur le nombre de cellules produisant des anticorps sp\u00e9cifiques, ce qui indique que le FJM peut am\u00e9liorer la fonction immunitaire cellulaire des souris. Afin d'\u00e9tudier les m\u00e9canismes associ\u00e9s \u00e0 cette am\u00e9lioration, nous avons men\u00e9 une \u00e9tude in vivo plus approfondie sur les effets du FJM sur les lymphocytes et les facteurs inflammatoires.<br \/>\nLes cytokines, l'un des \u00e9l\u00e9ments du syst\u00e8me immunitaire, servent de ponts et de liens entre les cellules dans les r\u00e9ponses immunitaires, jouant un r\u00f4le crucial dans la coordination des r\u00e9ponses immunitaires et inflammatoires. Par exemple, l'augmentation de la s\u00e9cr\u00e9tion de la cytokine anti-inflammatoire IL-4 par les sous-ensembles de cellules TH2 peut contr\u00f4ler l'inflammation et am\u00e9liorer les sympt\u00f4mes de la rhinite allergique. L'IFN - \u03b3 joue un r\u00f4le important dans la r\u00e9gulation des r\u00e9ponses immunitaires, en induisant la g\u00e9n\u00e9ration de cellules T, en activant les macrophages et en assurant la r\u00e9gulation crois\u00e9e des cellules TH1 et TH2. L'IL-2 peut r\u00e9guler les Treg pour exercer des effets immunosuppresseurs ou immunostimulants, jouant ainsi un r\u00f4le crucial dans l'hom\u00e9ostasie immunitaire. L'IL-4 a de multiples effets immunomodulateurs, \u00e0 la fois stimulants et inhibiteurs, et peut stimuler la prolif\u00e9ration des cellules B. Elle est un facteur important dans la promotion de l'h\u00e9moglobine. C'est un facteur important dans la promotion du d\u00e9veloppement et de la diff\u00e9renciation des cellules h\u00e9matopo\u00ef\u00e9tiques, ainsi que dans la formation des immunoglobulines IgG et IgE. L'expression cellulaire sp\u00e9cifique de l'IL-6 peut entra\u00eener diverses r\u00e9actions biologiques, jouant un r\u00f4le m\u00e9diateur important dans les r\u00e9ponses inflammatoires aigu\u00ebs, et peut inhiber les r\u00e9ponses des cellules CD8+T effectrices en r\u00e9duisant la production d'IFN-\u03b3. Les r\u00e9sultats exp\u00e9rimentaux ont montr\u00e9 que les niveaux d'expression des cytokines IL-2 et IL-4, IL-6 et IFN-\u03b3 chez les souris inject\u00e9es avec CTX pr\u00e9sentaient une tendance significative \u00e0 la baisse par rapport au groupe t\u00e9moin, et que les diff\u00e9rences entre les donn\u00e9es des trois autres groupes, \u00e0 l'exception de l'IL-4, \u00e9taient extr\u00eamement significatives. Le FJM peut inverser ce ph\u00e9nom\u00e8ne en ramenant de mani\u00e8re dose-d\u00e9pendante les niveaux de s\u00e9cr\u00e9tion des cytokines IL-2 et IL-4, IL-6 et IFN - \u03b3 proches de la plage normale du groupe t\u00e9moin, et a un bon effet r\u00e9gulateur sur la d\u00e9ficience immunitaire induite par le CTX chez les souris. Parmi eux, les concentrations d'IL-6 et de TNF-\u03b3 dans le groupe ayant re\u00e7u la dose \u00e9lev\u00e9e de m\u00e9dicament ont \u00e9t\u00e9 r\u00e9tablies aux niveaux du groupe t\u00e9moin. Ce r\u00e9sultat indique que le FJM r\u00e9tablit l'\u00e9quilibre du syst\u00e8me immunitaire de l'organisme et am\u00e9liore les sympt\u00f4mes du d\u00e9ficit immunitaire en r\u00e9gulant les interactions entre les cellules immunitaires et les cytokines. Dans l'ensemble, le FJM a un effet plus important sur la production de cytokines IFN - \u03b3 s\u00e9cr\u00e9t\u00e9es par les sous-ensembles de cellules Th1 que sur les cytokines IL-4 et IL-6 s\u00e9cr\u00e9t\u00e9es par les sous-ensembles de cellules Th2, ce qui indique que le FJM am\u00e9liore principalement la fonction immunitaire des souris mod\u00e8les immunod\u00e9prim\u00e9es en renfor\u00e7ant la fonction immunitaire cellulaire.<br \/>\nEn r\u00e9sum\u00e9, l'impact de la FJM sur le syst\u00e8me immunitaire est complexe, car elle peut induire des changements dans l'expression de divers lymphocytes et facteurs inflammatoires, et r\u00e9guler les interactions entre ces facteurs. Sur la base des r\u00e9sultats de cette \u00e9tude, nous concluons que la FJM joue un r\u00f4le positif dans la fonction immunitaire, en particulier dans des conditions de forte dose. Nous avons d\u00e9montr\u00e9 que le FJM peut inverser la suppression immunitaire induite par le CTX. Par cons\u00e9quent, nos r\u00e9sultats exp\u00e9rimentaux fournissent des preuves de l'effet de renforcement immunitaire du FJM et une base scientifique pour son d\u00e9veloppement ult\u00e9rieur et ses applications cliniques potentielles. Dans nos recherches futures, nous esp\u00e9rons continuer \u00e0 explorer l'impact du FJM sur certaines maladies caus\u00e9es par une faible immunit\u00e9 ou des troubles immunitaires.<\/p>","protected":false},"excerpt":{"rendered":"<p>The effect of myricetin on the immune function of cyclophosphamide induced immunosuppressed mice The immune system can protect organisms from infections caused by pathogens to maintain balance and overall health. Immunosuppression is a long-term or temporary immune dysfunction. Due to immune system damage, organisms become more sensitive to pathogens and have lower resistance. Even minor [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>The effect of myricetin on the immune function of cyclophosphamide induced immunosuppressed mice - China Chemical Manufacturer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/longchangextracts.com\/fr\/immunosuppressed-mice\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The effect of myricetin on the immune function of cyclophosphamide induced immunosuppressed mice - China Chemical Manufacturer\" \/>\n<meta property=\"og:description\" content=\"The effect of myricetin on the immune function of cyclophosphamide induced immunosuppressed mice The immune system can protect organisms from infections caused by pathogens to maintain balance and overall health. Immunosuppression is a long-term or temporary immune dysfunction. Due to immune system damage, organisms become more sensitive to pathogens and have lower resistance. Even minor [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/longchangextracts.com\/fr\/immunosuppressed-mice\/\" \/>\n<meta property=\"og:site_name\" content=\"China Chemical Manufacturer\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-11T17:51:51+00:00\" \/>\n<meta name=\"author\" content=\"Longchang Chemical\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Longchang Chemical\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/longchangextracts.com\/immunosuppressed-mice\/\",\"url\":\"https:\/\/longchangextracts.com\/immunosuppressed-mice\/\",\"name\":\"The effect of myricetin on the immune function of cyclophosphamide induced immunosuppressed mice - China Chemical Manufacturer\",\"isPartOf\":{\"@id\":\"https:\/\/longchangextracts.com\/#website\"},\"datePublished\":\"2024-08-11T17:51:51+00:00\",\"dateModified\":\"2024-08-11T17:51:51+00:00\",\"author\":{\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\"},\"breadcrumb\":{\"@id\":\"https:\/\/longchangextracts.com\/immunosuppressed-mice\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/longchangextracts.com\/immunosuppressed-mice\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/longchangextracts.com\/immunosuppressed-mice\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/longchangextracts.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The effect of myricetin on the immune function of cyclophosphamide induced immunosuppressed mice\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/longchangextracts.com\/#website\",\"url\":\"https:\/\/longchangextracts.com\/\",\"name\":\"China Chemical Manufacturer\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/longchangextracts.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\",\"name\":\"Longchang Chemical\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"caption\":\"Longchang Chemical\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Effet de la myric\u00e9tine sur la fonction immunitaire des souris immunod\u00e9prim\u00e9es par le cyclophosphamide - China Chemical Manufacturer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/longchangextracts.com\/fr\/immunosuppressed-mice\/","og_locale":"fr_FR","og_type":"article","og_title":"The effect of myricetin on the immune function of cyclophosphamide induced immunosuppressed mice - China Chemical Manufacturer","og_description":"The effect of myricetin on the immune function of cyclophosphamide induced immunosuppressed mice The immune system can protect organisms from infections caused by pathogens to maintain balance and overall health. Immunosuppression is a long-term or temporary immune dysfunction. Due to immune system damage, organisms become more sensitive to pathogens and have lower resistance. Even minor [&hellip;]","og_url":"https:\/\/longchangextracts.com\/fr\/immunosuppressed-mice\/","og_site_name":"China Chemical Manufacturer","article_published_time":"2024-08-11T17:51:51+00:00","author":"Longchang Chemical","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Longchang Chemical","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/longchangextracts.com\/immunosuppressed-mice\/","url":"https:\/\/longchangextracts.com\/immunosuppressed-mice\/","name":"Effet de la myric\u00e9tine sur la fonction immunitaire des souris immunod\u00e9prim\u00e9es par le cyclophosphamide - China Chemical Manufacturer","isPartOf":{"@id":"https:\/\/longchangextracts.com\/#website"},"datePublished":"2024-08-11T17:51:51+00:00","dateModified":"2024-08-11T17:51:51+00:00","author":{"@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869"},"breadcrumb":{"@id":"https:\/\/longchangextracts.com\/immunosuppressed-mice\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/longchangextracts.com\/immunosuppressed-mice\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/longchangextracts.com\/immunosuppressed-mice\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/longchangextracts.com\/"},{"@type":"ListItem","position":2,"name":"The effect of myricetin on the immune function of cyclophosphamide induced immunosuppressed mice"}]},{"@type":"WebSite","@id":"https:\/\/longchangextracts.com\/#website","url":"https:\/\/longchangextracts.com\/","name":"Fabricant chinois de produits chimiques","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/longchangextracts.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869","name":"Longchang Chemical","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","caption":"Longchang Chemical"}}]}},"_links":{"self":[{"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/posts\/8023"}],"collection":[{"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/comments?post=8023"}],"version-history":[{"count":1,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/posts\/8023\/revisions"}],"predecessor-version":[{"id":8024,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/posts\/8023\/revisions\/8024"}],"wp:attachment":[{"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/media?parent=8023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/categories?post=8023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/tags?post=8023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}