{"id":8005,"date":"2024-08-11T17:40:18","date_gmt":"2024-08-11T17:40:18","guid":{"rendered":"https:\/\/longchangextracts.com\/?p=8005"},"modified":"2024-08-11T17:40:18","modified_gmt":"2024-08-11T17:40:18","slug":"fuzi-ganjiang","status":"publish","type":"post","link":"https:\/\/longchangextracts.com\/fr\/fuzi-ganjiang\/","title":{"rendered":"Exploration du m\u00e9canisme du Fuzi Ganjiang dans la pr\u00e9vention des l\u00e9sions d'isch\u00e9mie-reperfusion du myocarde sur la base de la pharmacologie des r\u00e9seaux et d'exp\u00e9riences in vitro"},"content":{"rendered":"<p>Exploration du m\u00e9canisme du Fuzi Ganjiang dans la pr\u00e9vention des l\u00e9sions d'isch\u00e9mie-reperfusion du myocarde sur la base de la pharmacologie des r\u00e9seaux et d'exp\u00e9riences in vitro<br \/>\nLa cardiopathie isch\u00e9mique est la maladie cardiaque dont le taux d'incidence, le taux d'invalidit\u00e9 et le taux de mortalit\u00e9 sont les plus \u00e9lev\u00e9s en Chine. Avec le d\u00e9veloppement rapide de l'\u00e9conomie sociale et le vieillissement de la population, la cardiopathie isch\u00e9mique appara\u00eet plus jeune et son taux d'incidence augmente d'ann\u00e9e en ann\u00e9e. Les l\u00e9sions d'isch\u00e9mie-reperfusion du myocarde sont un ph\u00e9nom\u00e8ne in\u00e9vitable pendant le traitement de la cardiopathie isch\u00e9mique, qui entra\u00eene l'extension de la zone d'infarctus du myocarde et l'arythmie. Les l\u00e9sions d'isch\u00e9mie-r\u00e9perfusion constituent un probl\u00e8me urgent qui doit \u00eatre r\u00e9solu par la m\u00e9decine moderne, mais il n'existe pas encore de m\u00e9dicament sp\u00e9cifique.<br \/>\nL'infarctus du myocarde et l'angine de poitrine appartiennent \u00e0 la cat\u00e9gorie des obstructions thoraciques de la m\u00e9decine traditionnelle chinoise. La m\u00e9decine traditionnelle chinoise met l'accent sur une approche holistique et dispose d'une exp\u00e9rience et d'avantages uniques dans le traitement de l'obstruction thoracique. Des \u00e9tudes ant\u00e9rieures ont montr\u00e9 que la m\u00e9decine traditionnelle chinoise avait de bons effets th\u00e9rapeutiques dans le traitement de l'obstruction thoracique, notamment Sini Tang, Yiqi Huoxue Tang et Gualou Xiebai Tang. Aconiti Lateralis Radix Preparata Zingiberis Rhizama (AZ) est la paire de m\u00e9dicaments de base du Sini Tang. Des \u00e9tudes ant\u00e9rieures men\u00e9es par notre groupe de recherche ont montr\u00e9 que le groupe AZ a le meilleur effet th\u00e9rapeutique apr\u00e8s le d\u00e9montage du Sini Tang, mais son m\u00e9canisme sp\u00e9cifique n'est pas encore clair. En outre, notre groupe de recherche a \u00e9galement d\u00e9montr\u00e9 que la combinaison d'AZ peut r\u00e9duire le taux d'apoptose des cellules myocardiques pendant l'IM\/IR, mais son m\u00e9canisme sp\u00e9cifique n'a pas encore \u00e9t\u00e9 \u00e9tudi\u00e9. La composition complexe et le m\u00e9canisme d'action peu clair de l'AZ entravent s\u00e9rieusement son application clinique et le d\u00e9veloppement de nouveaux m\u00e9dicaments. Il est donc urgent d'\u00e9tudier le m\u00e9canisme de l'effet anti-IM\/IR de l'AZ.<br \/>\nLa pharmacologie des r\u00e9seaux est un outil important pour l'analyse des formules de m\u00e9decine traditionnelle chinoise. La pharmacologie des r\u00e9seaux a \u00e9t\u00e9 largement utilis\u00e9e pour analyser les processus biologiques et les voies de signalisation des traitements des maladies par les compos\u00e9s de la m\u00e9decine traditionnelle chinoise. Pour \u00e9tudier le m\u00e9canisme d'action de l'AZ contre l'infarctus du myocarde et l'iris, cette \u00e9tude entend utiliser la pharmacologie des r\u00e9seaux pour pr\u00e9dire le m\u00e9canisme d'action de l'AZ contre l'infarctus du myocarde et l'iris, et v\u00e9rifier les r\u00e9sultats pr\u00e9dits par la pharmacologie des r\u00e9seaux au moyen d'\u00e9tudes in vitro, jetant ainsi les bases de la recherche pour le prochain d\u00e9veloppement de l'AZ.<\/p>\n<p>&nbsp;<\/p>\n<p>Les l\u00e9sions d'isch\u00e9mie-reperfusion du myocarde font partie du champ d'application de l'obstruction thoracique et des maux de c\u0153ur de la m\u00e9decine traditionnelle chinoise. L'obstruction thoracique est souvent li\u00e9e \u00e0 des facteurs tels que l'invasion de pathog\u00e8nes froids, la perte de contr\u00f4le \u00e9motionnel, la vieillesse et la faiblesse physique. Le fuzi et le gingembre s\u00e9ch\u00e9 ont des propri\u00e9t\u00e9s m\u00e9dicinales chaudes et sont des m\u00e9dicaments repr\u00e9sentatifs pour r\u00e9chauffer le corps. Le Fuzi sans gingembre s\u00e9ch\u00e9 n'est pas chaud, et l'AZ combin\u00e9 au r\u00e9chauffement du corps a de meilleurs effets th\u00e9rapeutiques. En m\u00eame temps, l'AZ est utilis\u00e9 pour traiter l'obstruction thoracique parce qu'il a pour effet de r\u00e9chauffer le yang et de favoriser la circulation sanguine. Le r\u00e9chauffement du yang fait r\u00e9f\u00e9rence \u00e0 l'am\u00e9lioration du m\u00e9tabolisme \u00e9nerg\u00e9tique des cellules du myocarde, tandis que la promotion de la circulation sanguine fait r\u00e9f\u00e9rence au rel\u00e2chement des vaisseaux sanguins. L'AZ peut am\u00e9liorer le m\u00e9tabolisme \u00e9nerg\u00e9tique et d\u00e9tendre les vaisseaux sanguins pour exercer des effets th\u00e9rapeutiques. Pour v\u00e9rifier si l'AZ traite l'IM\/IR en am\u00e9liorant le m\u00e9tabolisme \u00e9nerg\u00e9tique et en relaxant les vaisseaux sanguins, nous avons choisi la pharmacologie de r\u00e9seau pour pr\u00e9dire les processus biologiques et les m\u00e9canismes sp\u00e9cifiques des effets anti-IM\/IR de l'AZ.<\/p>\n<p>En utilisant la pharmacologie des r\u00e9seaux pour analyser les ingr\u00e9dients actifs de l'AZ et construire un r\u00e9seau cible d'ingr\u00e9dients actifs, les principaux composants cl\u00e9s du r\u00e9seau ont \u00e9t\u00e9 identifi\u00e9s comme \u00e9tant l'aconitine dans l'Aconitum carmichaelii, le \u03b2 - sitost\u00e9rol et le 10 ging\u00e9rol dans le gingembre s\u00e9ch\u00e9. Des \u00e9tudes pharmacologiques modernes ont montr\u00e9 que l'aconitine a des effets cardiotoniques et antiarythmiques ; le \u03b2 - sitost\u00e9rol a des effets antioxydants et antitumoraux ; le 10 ging\u00e9rol a des propri\u00e9t\u00e9s anti-inflammatoires et am\u00e9liore la viabilit\u00e9 des cellules myocardiques dans les l\u00e9sions H\/R. Ces r\u00e9sultats indiquent que les composants pr\u00e9dits sont susceptibles d'\u00eatre les ingr\u00e9dients actifs cl\u00e9s de l'activit\u00e9 anti-infarctus\/IR de l'AZ.<\/p>\n<p>Dix processus biologiques cl\u00e9s ont \u00e9t\u00e9 identifi\u00e9s gr\u00e2ce \u00e0 l'analyse GO-BP des cibles cl\u00e9s. La r\u00e9gulation positive du processus de biosynth\u00e8se de l'oxyde nitrique, la r\u00e9gulation n\u00e9gative du processus d'apoptose, la r\u00e9ponse au stress oxydatif, l'impact de la voie de signalisation de l'apoptose sur les l\u00e9sions de l'ADN, la voie de signalisation m\u00e9di\u00e9e par le lipopolysaccharide et d'autres processus biologiques sont li\u00e9s \u00e0 la vasodilatation, \u00e0 l'apoptose, \u00e0 l'inflammation et aux l\u00e9sions oxydatives. La recherche a montr\u00e9 que la r\u00e9duction de l'apoptose cellulaire, de la r\u00e9ponse inflammatoire, des dommages oxydatifs et la promotion de la vasodilatation peuvent att\u00e9nuer l'infarctus du myocarde et l'angine de poitrine. Les r\u00e9sultats GO-BP pr\u00e9dits par la pharmacologie de r\u00e9seau sont fondamentalement coh\u00e9rents avec les rapports de la litt\u00e9rature connus sur l'infarctus du myocarde et l'iris du myocarde, ce qui indique que leurs r\u00e9sultats ont une certaine faisabilit\u00e9. Par ailleurs, cette \u00e9tude a \u00e9galement montr\u00e9 que l'AZ peut augmenter le taux de survie des cellules RVEC ayant subi des l\u00e9sions H\/R, r\u00e9duire le taux d'apoptose et les dommages oxydatifs.<\/p>\n<p>Afin d'explorer plus avant le m\u00e9canisme de l'AZ anti MI\/RI, l'analyse des voies de signalisation KEGG a r\u00e9v\u00e9l\u00e9 que l'AZ anti MI\/RI exerce principalement des effets th\u00e9rapeutiques par la voie de signalisation HIF, la voie de signalisation PI3-AKT et la voie de signalisation TNF, qui sont consid\u00e9r\u00e9es comme des voies de signalisation potentielles pour l'AZ anti MI\/RI. La voie de signalisation HIF joue un r\u00f4le important au cours de l'IM\/IR. Le facteur inductible par l'hypoxie HIF \u03b1 est activ\u00e9 lors de la d\u00e9tection de l'hypoxie dans l'organisme, et le HIF \u03b1 activ\u00e9 augmente l'expression en aval du VEGF et de l'eNOS. Le VEGF est un inducteur de l'angiogen\u00e8se qui peut promouvoir la prolif\u00e9ration des cellules endoth\u00e9liales et am\u00e9liorer l'hom\u00e9ostasie vasculaire. L'oxyde nitrique synthase eNOS peut promouvoir la lib\u00e9ration de NO, entra\u00eenant une vasodilatation et une augmentation du flux sanguin art\u00e9riel. L'activation du VEGF et de la eNOS pendant l'hypoxie du tissu myocardique peut favoriser la vasodilatation et l'angiogen\u00e8se, fournissant ainsi suffisamment d'oxyg\u00e8ne au tissu myocardique. La voie de signalisation PI3K-AKT r\u00e9duit l'apoptose des cardiomyocytes pendant l'IM\/IR. La voie de signalisation du TNF r\u00e9duit la r\u00e9ponse inflammatoire pendant l'IM\/IR. Des \u00e9tudes ant\u00e9rieures ont \u00e9galement montr\u00e9 que la promotion de la vasodilatation par la voie de signalisation HIF, l'am\u00e9lioration du m\u00e9tabolisme \u00e9nerg\u00e9tique des cellules myocardiques par la voie de signalisation PI3K-AKT et la r\u00e9duction de la r\u00e9ponse inflammatoire par la voie de signalisation TNF sont des voies de signalisation importantes pour le traitement de l'infarctus du myocarde et de l'irruption c\u00e9r\u00e9brale. L'AZ a pour effet de r\u00e9chauffer le yang et de favoriser la circulation sanguine, le r\u00e9chauffement du yang faisant r\u00e9f\u00e9rence \u00e0 l'am\u00e9lioration du m\u00e9tabolisme \u00e9nerg\u00e9tique du myocarde et \u00e0 la r\u00e9duction de l'apoptose des cellules myocardiques. Il a \u00e9t\u00e9 confirm\u00e9 qu'il favorise la vasodilatation et exerce des effets th\u00e9rapeutiques, mais ces effets ne sont toujours pas clairs. Cette \u00e9tude a confirm\u00e9 que l'AZ peut stimuler la voie HIF \u03b1\/VEGF\/eNOS, augmenter l'expression des prot\u00e9ines HIF \u03b1, VEGF et NOS dans les cellules RVEC endommag\u00e9es par H\/R et promouvoir la vasodilatation\/prolif\u00e9ration des cellules endoth\u00e9liales. Il convient de noter que l'effet th\u00e9rapeutique du groupe \u00e0 forte dose n'est pas significatif dans l'indice WB, ce qui peut \u00eatre d\u00fb au gradient de dose d\u00e9raisonnable que nous avons \u00e9tabli et aux effets toxiques des ingr\u00e9dients actifs de l'Aconitum. L'\u00e9quipe de recherche sera attentive \u00e0 cette question dans les \u00e9tudes futures.<\/p>\n<p>En r\u00e9sum\u00e9, cette \u00e9tude a permis d'obtenir 16 principes actifs et 171 cibles th\u00e9rapeutiques de l'AZ ; l'analyse graphique a r\u00e9v\u00e9l\u00e9 que l'AKT1, l'IL6 et le TNF sont des cibles potentielles ; l'analyse d'enrichissement GO a r\u00e9v\u00e9l\u00e9 que l'AZ peut exercer des effets th\u00e9rapeutiques par le biais de l'apoptose, de l'inflammation et de la vasodilatation ; L'analyse KEGG a r\u00e9v\u00e9l\u00e9 que l'AZ peut exercer des effets th\u00e9rapeutiques par le biais de la voie de signalisation PI3K-AKT, de la voie de signalisation TNF et de la voie de signalisation HIF. Des \u00e9tudes in vitro ont montr\u00e9 que l'AZ peut augmenter le taux de survie, r\u00e9duire le taux d'apoptose et les dommages oxydatifs des cellules RVEC endommag\u00e9es par H\/R. Il augmente l'expression des prot\u00e9ines HIF-\u03b1, VEGF et eNOS. L'AZ active la voie de signalisation HIF\/VEGF\/eNOS pour r\u00e9duire les dommages oxydatifs et l'apoptose des cellules endoth\u00e9liales, favoriser la vasodilatation\/prolif\u00e9ration des cellules endoth\u00e9liales et exercer des effets anti-l\u00e9sion myocardique par isch\u00e9mie-reperfusion, ce qui est conforme aux r\u00e9sultats pr\u00e9dits par la pharmacologie des r\u00e9seaux. L'AZ peut favoriser la vasodilatation et la prolif\u00e9ration des cellules endoth\u00e9liales par le biais de la voie de signalisation HIF pour exercer des effets th\u00e9rapeutiques, ce qui constitue une base de recherche pour le d\u00e9veloppement ult\u00e9rieur de l'AZ.<\/p>","protected":false},"excerpt":{"rendered":"<p>Exploring the mechanism of Fuzi Ganjiang in preventing myocardial ischemia-reperfusion injury based on network pharmacology and in vitro experiments Ischemic heart disease (IHD) is the heart disease with the highest incidence rate, disability rate and mortality in China. With the rapid development of social economy and the aging of the population, IHD appears younger and [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Exploring the mechanism of Fuzi Ganjiang in preventing myocardial ischemia-reperfusion injury based on network pharmacology and in vitro experiments - China Chemical Manufacturer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/longchangextracts.com\/fr\/fuzi-ganjiang\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exploring the mechanism of Fuzi Ganjiang in preventing myocardial ischemia-reperfusion injury based on network pharmacology and in vitro experiments - China Chemical Manufacturer\" \/>\n<meta property=\"og:description\" content=\"Exploring the mechanism of Fuzi Ganjiang in preventing myocardial ischemia-reperfusion injury based on network pharmacology and in vitro experiments Ischemic heart disease (IHD) is the heart disease with the highest incidence rate, disability rate and mortality in China. With the rapid development of social economy and the aging of the population, IHD appears younger and [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/longchangextracts.com\/fr\/fuzi-ganjiang\/\" \/>\n<meta property=\"og:site_name\" content=\"China Chemical Manufacturer\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-11T17:40:18+00:00\" \/>\n<meta name=\"author\" content=\"Longchang Chemical\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Longchang Chemical\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/longchangextracts.com\/fuzi-ganjiang\/\",\"url\":\"https:\/\/longchangextracts.com\/fuzi-ganjiang\/\",\"name\":\"Exploring the mechanism of Fuzi Ganjiang in preventing myocardial ischemia-reperfusion injury based on network pharmacology and in vitro experiments - China Chemical Manufacturer\",\"isPartOf\":{\"@id\":\"https:\/\/longchangextracts.com\/#website\"},\"datePublished\":\"2024-08-11T17:40:18+00:00\",\"dateModified\":\"2024-08-11T17:40:18+00:00\",\"author\":{\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\"},\"breadcrumb\":{\"@id\":\"https:\/\/longchangextracts.com\/fuzi-ganjiang\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/longchangextracts.com\/fuzi-ganjiang\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/longchangextracts.com\/fuzi-ganjiang\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/longchangextracts.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exploring the mechanism of Fuzi Ganjiang in preventing myocardial ischemia-reperfusion injury based on network pharmacology and in vitro experiments\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/longchangextracts.com\/#website\",\"url\":\"https:\/\/longchangextracts.com\/\",\"name\":\"China Chemical Manufacturer\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/longchangextracts.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\",\"name\":\"Longchang Chemical\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"caption\":\"Longchang Chemical\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exploration du m\u00e9canisme du Fuzi Ganjiang dans la pr\u00e9vention des l\u00e9sions d'isch\u00e9mie-reperfusion du myocarde sur la base de la pharmacologie des r\u00e9seaux et d'exp\u00e9riences in vitro - China Chemical Manufacturer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/longchangextracts.com\/fr\/fuzi-ganjiang\/","og_locale":"fr_FR","og_type":"article","og_title":"Exploring the mechanism of Fuzi Ganjiang in preventing myocardial ischemia-reperfusion injury based on network pharmacology and in vitro experiments - China Chemical Manufacturer","og_description":"Exploring the mechanism of Fuzi Ganjiang in preventing myocardial ischemia-reperfusion injury based on network pharmacology and in vitro experiments Ischemic heart disease (IHD) is the heart disease with the highest incidence rate, disability rate and mortality in China. With the rapid development of social economy and the aging of the population, IHD appears younger and [&hellip;]","og_url":"https:\/\/longchangextracts.com\/fr\/fuzi-ganjiang\/","og_site_name":"China Chemical Manufacturer","article_published_time":"2024-08-11T17:40:18+00:00","author":"Longchang Chemical","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Longchang Chemical","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/longchangextracts.com\/fuzi-ganjiang\/","url":"https:\/\/longchangextracts.com\/fuzi-ganjiang\/","name":"Exploration du m\u00e9canisme du Fuzi Ganjiang dans la pr\u00e9vention des l\u00e9sions d'isch\u00e9mie-reperfusion du myocarde sur la base de la pharmacologie des r\u00e9seaux et d'exp\u00e9riences in vitro - China Chemical Manufacturer","isPartOf":{"@id":"https:\/\/longchangextracts.com\/#website"},"datePublished":"2024-08-11T17:40:18+00:00","dateModified":"2024-08-11T17:40:18+00:00","author":{"@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869"},"breadcrumb":{"@id":"https:\/\/longchangextracts.com\/fuzi-ganjiang\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/longchangextracts.com\/fuzi-ganjiang\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/longchangextracts.com\/fuzi-ganjiang\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/longchangextracts.com\/"},{"@type":"ListItem","position":2,"name":"Exploring the mechanism of Fuzi Ganjiang in preventing myocardial ischemia-reperfusion injury based on network pharmacology and in vitro experiments"}]},{"@type":"WebSite","@id":"https:\/\/longchangextracts.com\/#website","url":"https:\/\/longchangextracts.com\/","name":"Fabricant chinois de produits chimiques","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/longchangextracts.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869","name":"Longchang Chemical","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","caption":"Longchang Chemical"}}]}},"_links":{"self":[{"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/posts\/8005"}],"collection":[{"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/comments?post=8005"}],"version-history":[{"count":1,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/posts\/8005\/revisions"}],"predecessor-version":[{"id":8006,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/posts\/8005\/revisions\/8006"}],"wp:attachment":[{"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/media?parent=8005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/categories?post=8005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/tags?post=8005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}