{"id":3377,"date":"2024-04-19T09:07:14","date_gmt":"2024-04-19T09:07:14","guid":{"rendered":"https:\/\/longchangextracts.com\/?p=3377"},"modified":"2024-04-19T09:07:14","modified_gmt":"2024-04-19T09:07:14","slug":"evaluation-of-a-new-process-of-qingdianxia","status":"publish","type":"post","link":"https:\/\/longchangextracts.com\/fr\/evaluation-dun-nouveau-procede-de-qingdianxia\/","title":{"rendered":"\u00c9valuation d'un nouveau proc\u00e9d\u00e9 de concoction de Qingdianxia bas\u00e9 sur la coh\u00e9rence de la qualit\u00e9 avant et apr\u00e8s la concoction"},"content":{"rendered":"<p>Le rhizome de pinellia (RP) est le tubercule s\u00e9ch\u00e9 de Pinellia ternata (Thunb.) Breit. Il a pour effet d'ass\u00e9cher l'humidit\u00e9 et de r\u00e9soudre les mucosit\u00e9s, de ma\u00eetriser la r\u00e9bellion, d'arr\u00eater les vomissements, d'\u00e9liminer les grumeaux et de disperser les n\u0153uds. Pinelliae Rhizoma Praeparatum cum Alumine (PRPA) est un comprim\u00e9 concoct\u00e9 \u00e0 partir de Pinelliae Rhizoma Praeparatum tremp\u00e9 dans de l'alun ou bouilli, qui a pour effet de dissiper le froid et les mucosit\u00e9s par rapport au Pinelliae Rhizoma brut. La relation de transfert de masse entre les deux peut \u00eatre r\u00e9sum\u00e9e comme suit : les acides organiques libres ont augment\u00e9, les sucres totaux, les alcalo\u00efdes totaux et certains nucl\u00e9osides et prot\u00e9ines ont diminu\u00e9 apr\u00e8s que les demi-sommets bruts ont \u00e9t\u00e9 concoct\u00e9s. Les changements des composants individuels dans les acides organiques et les nucl\u00e9osides sont rarement signal\u00e9s, et on manque d'analyses syst\u00e9matiques des sch\u00e9mas de changement des principaux composants de l'h\u00e9michrysanth\u00e8me et de l'h\u00e9michrysanth\u00e8me Qing.<br \/>\nLa m\u00e9thode de pr\u00e9paration du Qingdianxia est relativement fixe et, dans l'\u00e9dition 2015 de la pharmacop\u00e9e de la R\u00e9publique populaire de Chine (ci-apr\u00e8s d\u00e9nomm\u00e9e \"pharmacop\u00e9e chinoise\"), le Qingdianxia est fabriqu\u00e9 par trempage dans une solution d'alun 8%, tandis que l'\u00e9dition 2020 de la pharmacop\u00e9e chinoise ajoute le Qingdianxia bouilli sur cette base. Toutefois, outre les m\u00e9thodes de trempage et d'\u00e9bullition de l'alun pour la fabrication des comprim\u00e9s de Qingdianxia, certaines entreprises tentent d'utiliser la m\u00e9thode de vaporisation de l'alun pour am\u00e9liorer le processus de production des comprim\u00e9s de Qingdianxia.<br \/>\nLa m\u00e9thode de cuisson \u00e0 la vapeur \u00e0 haute temp\u00e9rature est consid\u00e9r\u00e9e comme un nouveau proc\u00e9d\u00e9 de concoction pr\u00e9sentant les avantages d'un processus contr\u00f4lable, d'un gain de temps et de main-d'\u0153uvre, ainsi que d'un meilleur effet de r\u00e9duction de la toxicit\u00e9 des herbes toxiques. Mo et Li ont \u00e9tabli une pr\u00e9paration stable de Pinellia ternata \u00e0 la vapeur \u00e0 haute pression, et Xiao a utilis\u00e9 une pr\u00e9paration \u00e0 la vapeur pour obtenir du Pinellia ternata, qui pr\u00e9sentait une augmentation de la teneur en acide organique total, une diminution significative de la teneur en cristaux d'oxalate de calcium, et une limite d'alun conforme \u00e0 la norme de la pharmacop\u00e9e. La teneur en cristaux d'oxalate de calcium en aiguilles a \u00e9t\u00e9 significativement r\u00e9duite et la limite d'alun est conforme \u00e0 la norme de la pharmacop\u00e9e. Toutefois, la m\u00e9thode de cuisson \u00e0 la vapeur soul\u00e8ve encore de nombreuses questions, telles que la stabilit\u00e9 de la qualit\u00e9 du Qingdianxia obtenu par cuisson \u00e0 la vapeur, l'efficacit\u00e9 du Qingdianxia obtenu par cuisson \u00e0 la vapeur, la coh\u00e9rence de la qualit\u00e9 du Qingdianxia obtenu par cuisson \u00e0 la vapeur par rapport \u00e0 celle obtenue par trempage et \u00e9bullition.<br \/>\nDans la pr\u00e9sente \u00e9tude, les herbes de Pinellia ternata de diff\u00e9rentes origines ont \u00e9t\u00e9 transform\u00e9es en comprim\u00e9s de Pinellia ternata selon la m\u00e9thode d'immersion, la m\u00e9thode d'\u00e9bullition et la m\u00e9thode de cuisson \u00e0 la vapeur respectivement, et les m\u00e9thodes de d\u00e9termination du contenu \u00e9tablies par l'\u00e9quipe \u00e0 l'\u00e9tape pr\u00e9c\u00e9dente ont \u00e9t\u00e9 utilis\u00e9es pour analyser la relation de transfert de masse entre le Pinellia ternata brut et le Pinellia ternata en termes de lixiviat, d'acides organiques, de polysaccharides, de nucl\u00e9osides et de prot\u00e9ines, et pour \u00e9tudier la coh\u00e9rence de la qualit\u00e9 entre le Pinellia ternata cuit \u00e0 la vapeur et par immersion et le Pinellia ternata bouillant, afin de jeter les bases d'\u00e9tudes ult\u00e9rieures sur l'effet pharmacologique et le m\u00e9canisme de d\u00e9sintoxication du Pinellia ternata. Cela permettra de jeter les bases d'une recherche plus approfondie sur les m\u00e9canismes pharmacologiques et de d\u00e9sintoxication du Qingbianxia.<\/p>\n<p>Dans cette \u00e9tude, nous avons compar\u00e9 les diff\u00e9rences entre trois concoctions de Qingdianxia du point de vue du transfert de masse et \u00e9valu\u00e9 la m\u00e9thode de cuisson \u00e0 la vapeur, un nouveau proc\u00e9d\u00e9 de concoction. Sur la base de l'\u00e9tude des facteurs d'influence du transfert de masse mentionn\u00e9s ci-dessus, l'\u00e9tape cl\u00e9 qui diff\u00e9rencie la m\u00e9thode de cuisson \u00e0 la vapeur des m\u00e9thodes d'immersion et d'\u00e9bullition devrait \u00eatre la cuisson \u00e0 la vapeur, et la temp\u00e9rature \u00e9lev\u00e9e de l'\u00e9tape de cuisson \u00e0 la vapeur ainsi que l'absence de contact direct avec la masse d'eau ont directement conduit \u00e0 la r\u00e9tention et \u00e0 l'augmentation du lixiviat, de l'acide oxalique et des polysaccharides. En combinant tous les indicateurs de test et diverses m\u00e9thodes d'analyse, on peut constater que l'effet de la cuisson \u00e0 la vapeur sur la qualit\u00e9 intrins\u00e8que des produits d'artillerie et le traditionnel \"Qing half-summer\" produit une diff\u00e9rence significative dans les produits d'artillerie ; la question de savoir si les produits d'artillerie peuvent \u00eatre appel\u00e9s \"Qing half-summer\" est d\u00e9battue.<br \/>\nToutefois, les indices de qualit\u00e9 du Bianxia et du Qingbianxia n'ont pas encore \u00e9t\u00e9 d\u00e9termin\u00e9s, et l'\u00e9dition 2020 de la pharmacop\u00e9e chinoise n'utilise que le lixiviat comme indice de qualit\u00e9. L'acide citrique, l'acide L-malique et l'ad\u00e9nine, qui \u00e9taient positivement corr\u00e9l\u00e9s avec la teneur en lixiviat, \u00e9taient \u00e9galement des composantes positives fondamentalement importantes des premi\u00e8re et deuxi\u00e8me composantes principales de l'analyse en composantes principales. Ce r\u00e9sultat sugg\u00e8re la possibilit\u00e9 d'appliquer les composants de l'acide citrique, de l'acide L-malique et de l'ad\u00e9nine \u00e0 l'\u00e9valuation de la qualit\u00e9 de l'h\u00e9michrysanth\u00e8me brut, et en m\u00eame temps, selon les m\u00e9thodes d'\u00e9valuation de la qualit\u00e9 actuellement \u00e9tablies, la m\u00e9thode de cuisson \u00e0 la vapeur a d\u00e9montr\u00e9 une meilleure qualit\u00e9 que celle d\u00e9montr\u00e9e par les m\u00e9thodes de lixiviation et d'\u00e9bullition des produits concoct\u00e9s. En outre, en ce qui concerne le rendement des comprim\u00e9s de boisson et la limite de l'alun, la m\u00e9thode de cuisson \u00e0 la vapeur pr\u00e9sente un avantage sup\u00e9rieur \u00e0 la m\u00e9thode d'\u00e9bullition en termes d'efficacit\u00e9 de production et de s\u00e9curit\u00e9, respectivement.<br \/>\nLa qualit\u00e9 des comprim\u00e9s pr\u00e9par\u00e9s par la m\u00e9thode d'immersion et la m\u00e9thode d'\u00e9bullition \u00e9tait coh\u00e9rente, et la qualit\u00e9 des comprim\u00e9s pr\u00e9par\u00e9s par la m\u00e9thode de cuisson \u00e0 la vapeur diff\u00e9rait consid\u00e9rablement, mais les effets cliniques des produits obtenus par les trois m\u00e9thodes de pr\u00e9paration n'ont pas encore \u00e9t\u00e9 compar\u00e9s. La m\u00e9thode d'\u00e9bullition est incluse dans les sp\u00e9cifications des concoctions locales de comprim\u00e9s de m\u00e9decine chinoise (par exemple, Beijing, Inner Mongolia, Jilin, Henan, etc.) et dans l'\u00e9dition 1963 de la pharmacop\u00e9e chinoise, mais la m\u00e9thode de cuisson \u00e0 la vapeur a \u00e9t\u00e9 signal\u00e9e moins fr\u00e9quemment et n'a pas \u00e9t\u00e9 incluse dans la pharmacop\u00e9e ou dans les normes locales. D'apr\u00e8s les r\u00e9sultats de cette \u00e9tude, la m\u00e9thode de cuisson \u00e0 la vapeur est souhaitable en termes de contenu compositionnel et de stabilit\u00e9, et la question de savoir si elle peut \u00eatre incluse en tant que m\u00e9thode officielle de concoction n\u00e9cessite une \u00e9tude plus approfondie.<br \/>\nLa m\u00e9thode de cuisson \u00e0 la vapeur peut \u00eatre utilis\u00e9e pour raccourcir le temps de concoction gr\u00e2ce \u00e0 la temp\u00e9rature \u00e9lev\u00e9e, et elle montre une tendance \u00e0 un taux de changement de contenu plus stable dans cette \u00e9tude, ce qui pr\u00e9sente un grand potentiel en termes d'\u00e9conomie de temps et de main-d'\u0153uvre. L'\u00e9tape suivante pourrait consister \u00e0 optimiser davantage le processus de cuisson \u00e0 la vapeur : le temps de trempage peut-il \u00eatre raccourci et la vapeur \u00e0 haute temp\u00e9rature peut-elle \u00eatre utilis\u00e9e pour obtenir simultan\u00e9ment l'effet de p\u00e9n\u00e9tration du c\u0153ur ? En outre, le contenu intrins\u00e8que des artefacts cuits \u00e0 la vapeur diff\u00e8re de celui du processus traditionnel, et les effets pharmacologiques et l'efficacit\u00e9 clinique des artefacts pourraient \u00eatre compar\u00e9s \u00e0 ceux des artefacts traditionnels de Qingdianxia sur la base des diff\u00e9rences de contenu, ce qui permettrait d'explorer le m\u00e9canisme de l'efficacit\u00e9 pharmacologique de Qingdianxia et de fournir une base pour l'\u00e9lucidation de la scientificit\u00e9 des artefacts.<\/p>\n<p>&nbsp;<\/p>\n<p>Catalyseurs \u00e0 base de carbone quaternaire et de fer bon march\u00e9 : une perc\u00e9e dans la fabrication de m\u00e9dicaments<\/p>\n<p>Le 5 avril 2024, une nouvelle d\u00e9couverte en chimie m\u00e9dicinale a \u00e9t\u00e9 publi\u00e9e dans la prestigieuse revue Science : l'\u00e9tude montre que les chimistes de Scripps Research \u00e0 La Jolla, Californie, \u00c9tats-Unis, peuvent convertir des produits chimiques de base en carbone quaternaire \u00e0 l'aide d'un catalyseur simple, unique et peu co\u00fbteux \u00e0 base de fer.<\/p>\n<p>C'est peut-\u00eatre un petit pas dans l'histoire de la chimie, mais c'est un grand pas dans l'industrialisation des futurs produits chimiques pharmaceutiques.<br \/>\nPourquoi en est-il ainsi ? Cet article en fait une analyse d\u00e9taill\u00e9e. Les compos\u00e9s \u00e0 petites mol\u00e9cules constituent le courant principal des m\u00e9dicaments, la production industrielle de masse permet de r\u00e9duire les co\u00fbts dans le monde d'aujourd'hui, les compos\u00e9s \u00e0 petites mol\u00e9cules constituent l'un des courants principaux du d\u00e9veloppement des m\u00e9dicaments. Par rapport aux grandes biomol\u00e9cules (telles que les prot\u00e9ines et les anticorps), les petites mol\u00e9cules ont des volumes mol\u00e9culaires plus petits et des structures plus simples, ce qui les rend plus faciles \u00e0 synth\u00e9tiser et \u00e0 adapter, et donc plus aptes \u00e0 \u00eatre utilis\u00e9es comme candidats-m\u00e9dicaments. En outre, la production chimique de masse peut r\u00e9duire consid\u00e9rablement le co\u00fbt de production des m\u00e9dicaments.<\/p>\n<p>&nbsp;<\/p>\n<p>La production \u00e0 grande \u00e9chelle permet d'obtenir des rendements plus \u00e9lev\u00e9s et de r\u00e9duire le co\u00fbt unitaire du processus de production, ce qui rend les m\u00e9dicaments plus \u00e9conomiques et plus abordables. Par cons\u00e9quent, la production chimique de masse est tr\u00e8s importante pour les m\u00e9dicaments \u00e0 petites mol\u00e9cules afin de les rendre plus accessibles \u00e0 la production de masse et \u00e0 l'utilisation g\u00e9n\u00e9ralis\u00e9e, offrant ainsi aux patients un plus grand choix et des options th\u00e9rapeutiques plus abordables.<br \/>\nLa synth\u00e8se de petites mol\u00e9cules \u00e0 structure de carbone quaternaire est l'une des difficult\u00e9s de la pharmacie chimique. La structure de carbone quaternaire est une structure sp\u00e9ciale de l'atome de carbone dans les compos\u00e9s organiques, qui se r\u00e9f\u00e8re \u00e0 une structure dans laquelle un atome de carbone forme quatre liaisons covalentes avec quatre autres atomes de carbone. Elle pr\u00e9sente g\u00e9n\u00e9ralement une morphologie similaire aux membres d'un atome de carbone, et est donc \u00e9galement connue sous le nom d'atome de carbone saisonnier. En chimie organique, la structure de carbone saisonni\u00e8re est l'un des interm\u00e9diaires importants couramment utilis\u00e9s dans la synth\u00e8se de m\u00e9dicaments, de pesticides et de mat\u00e9riaux polym\u00e8res. Comme les structures de carbone quaternaire am\u00e9liorent la stabilit\u00e9 et l'activit\u00e9 biologique des mol\u00e9cules, elles jouent un r\u00f4le important dans la synth\u00e8se organique et la d\u00e9couverte de m\u00e9dicaments.<\/p>\n<p>&nbsp;<\/p>\n<p>Cependant, certains m\u00e9dicaments n\u00e9cessitent de petites mol\u00e9cules contenant des structures de carbone quaternaire comme l'un de leurs ingr\u00e9dients actifs, ce qui pose un d\u00e9fi au processus de fabrication dans la production chimique pharmaceutique de masse. Le carbone quaternaire \u00e9tant un atome de carbone li\u00e9 \u00e0 quatre autres atomes de carbone, il joue un r\u00f4le crucial dans de nombreux m\u00e9dicaments. Toutefois, la fabrication de ces petites mol\u00e9cules contenant des structures de carbone quaternaire est difficile en raison de la complexit\u00e9 et du co\u00fbt \u00e9lev\u00e9 de leur synth\u00e8se.<\/p>\n<p>&nbsp;<\/p>\n<p>Les r\u00e9sultats de cette \u00e9tude, qui viennent d'\u00eatre publi\u00e9s, offrent une nouvelle solution \u00e0 ce probl\u00e8me. Les scientifiques de Scripps Research ont d\u00e9couvert que des catalyseurs en fer peu co\u00fbteux peuvent \u00eatre utilis\u00e9s pour convertir des produits chimiques de base en compos\u00e9s contenant des structures de carbone quaternaire. La caract\u00e9ristique la plus importante de cette m\u00e9thode est qu'elle est extr\u00eamement \u00e9conomique, ce qui en fait une approche potentiellement rentable. En outre, l'introduction du carbone quaternaire pr\u00e9sente l'avantage d'une augmentation exponentielle de l'espace chimique, ce qui devrait permettre de surmonter le goulot d'\u00e9tranglement que constitue le manque de diversit\u00e9 de l'ossature mol\u00e9culaire des m\u00e9dicaments.<\/p>\n<p>&nbsp;<\/p>\n<p>Plus pr\u00e9cis\u00e9ment, les acides carboxyliques et les ol\u00e9fines peuvent \u00eatre convertis en compos\u00e9s contenant des structures de carbone quaternaire \u00e0 l'aide de catalyseurs \u00e0 base de fer dans des conditions de r\u00e9action chimique simples. En outre, l'abondance et le faible co\u00fbt de ces produits chimiques de base permettent \u00e0 cette approche non seulement de r\u00e9duire le co\u00fbt de production, mais aussi de simplifier le processus de production.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Quels sont les m\u00e9dicaments co\u00fbteux en raison de leur structure de carbone quaternaire ?<\/p>\n<p>&nbsp;<\/p>\n<p>Les structures de carbone quaternaire sont largement pr\u00e9sentes dans les mol\u00e9cules de m\u00e9dicaments et les produits naturels (par exemple, le v\u00e9rapamil, etc.). Toutefois, la construction de centres chiraux \u00e0 carbone quaternaire a constitu\u00e9 un grand d\u00e9fi en synth\u00e8se organique en raison de l'encombrement du site et de la flexibilit\u00e9 de la conformation. Les m\u00e9dicaments contenant des structures \u00e0 carbone quaternaire, tels que certains anticanc\u00e9reux, antibiotiques, antiviraux et antipsychotiques, sont co\u00fbteux \u00e0 produire en raison de leur processus de synth\u00e8se complexe, qui n\u00e9cessite des r\u00e9actions de synth\u00e8se en plusieurs \u00e9tapes et un co\u00fbt \u00e9lev\u00e9 des mati\u00e8res premi\u00e8res. Le processus de synth\u00e8se de ces m\u00e9dicaments peut impliquer des interm\u00e9diaires contenant des structures de carbone quaternaire, ce qui augmente la difficult\u00e9 et le co\u00fbt de la synth\u00e8se. C'est pourquoi les scientifiques ont essay\u00e9 de trouver de nouvelles m\u00e9thodes de synth\u00e8se plus rentables afin de r\u00e9duire le co\u00fbt de production de ces m\u00e9dicaments et de les rendre plus abordables et plus populaires.<\/p>\n<p>&nbsp;<\/p>\n<p>Pourquoi les m\u00e9dicaments \u00e0 petites mol\u00e9cules constituent-ils toujours le courant principal des produits pharmaceutiques, aujourd'hui et \u00e0 l'avenir ?<\/p>\n<p>&nbsp;<\/p>\n<p>Les m\u00e9dicaments \u00e0 petites mol\u00e9cules sont et resteront le pilier du d\u00e9veloppement et de la th\u00e9rapie m\u00e9dicamenteuse en raison de leur polyvalence chimique, de leur faible co\u00fbt de production, de leur facilit\u00e9 d'administration par voie orale, de leurs excellentes propri\u00e9t\u00e9s pharmacocin\u00e9tiques et de leur large \u00e9ventail d'applications. Leurs structures chimiques flexibles leur permettent d'\u00eatre ajust\u00e9es et optimis\u00e9es par des m\u00e9thodes synth\u00e9tiques pour r\u00e9pondre aux besoins th\u00e9rapeutiques de diff\u00e9rentes maladies, tout en pr\u00e9sentant les avantages de cibles m\u00e9dicamenteuses plus larges et d'une production de masse plus facile, offrant ainsi aux patients des options de traitement plus \u00e9conomiques, plus pratiques et plus efficaces. En outre, par rapport aux m\u00e9dicaments \u00e0 grandes mol\u00e9cules (par exemple, les m\u00e9dicaments \u00e0 base de prot\u00e9ines), les m\u00e9dicaments \u00e0 petites mol\u00e9cules peuvent g\u00e9n\u00e9ralement \u00eatre administr\u00e9s par voie orale, ce qui est plus pratique, plus facile \u00e0 accepter et plus facile \u00e0 suivre les conseils m\u00e9dicaux, avec une plus grande observance.<\/p>","protected":false},"excerpt":{"rendered":"<p>Le rhizome de pinellia (RP) est le tubercule s\u00e9ch\u00e9 de Pinellia ternata (Thunb.) Breit. Il a pour effet d'ass\u00e9cher l'humidit\u00e9 et de r\u00e9soudre les mucosit\u00e9s, de ma\u00eetriser la r\u00e9bellion, d'arr\u00eater les vomissements, d'\u00e9liminer les grumeaux et de disperser les n\u0153uds. Pinelliae Rhizoma Praeparatum cum Alumine (PRPA) est un comprim\u00e9 concoct\u00e9 \u00e0 partir de [...]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Evaluation of a new process of Qingdianxia concoction based on quality consistency before and after concoction - China Chemical Manufacturer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/longchangextracts.com\/fr\/evaluation-dun-nouveau-procede-de-qingdianxia\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evaluation of a new process of Qingdianxia concoction based on quality consistency before and after concoction - China Chemical Manufacturer\" \/>\n<meta property=\"og:description\" content=\"Pinellia Rhizoma (PR) is the dried tuber of Pinellia ternata (Thunb.) Breit. It has the effects of drying dampness and resolving phlegm, subduing rebelliousness, stopping vomiting, eliminating lumps and dispersing knots, and is one of the commonly used traditional Chinese medicines in clinical practice. Pinelliae Rhizoma Praeparatum cum Alumine (PRPA) is a concocted tablet of [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/longchangextracts.com\/fr\/evaluation-dun-nouveau-procede-de-qingdianxia\/\" \/>\n<meta property=\"og:site_name\" content=\"China Chemical Manufacturer\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-19T09:07:14+00:00\" \/>\n<meta name=\"author\" content=\"longcha9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"longcha9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/longchangextracts.com\/evaluation-of-a-new-process-of-qingdianxia\/\",\"url\":\"https:\/\/longchangextracts.com\/evaluation-of-a-new-process-of-qingdianxia\/\",\"name\":\"Evaluation of a new process of Qingdianxia concoction based on quality consistency before and after concoction - China Chemical Manufacturer\",\"isPartOf\":{\"@id\":\"https:\/\/longchangextracts.com\/#website\"},\"datePublished\":\"2024-04-19T09:07:14+00:00\",\"dateModified\":\"2024-04-19T09:07:14+00:00\",\"author\":{\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\"},\"breadcrumb\":{\"@id\":\"https:\/\/longchangextracts.com\/evaluation-of-a-new-process-of-qingdianxia\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/longchangextracts.com\/evaluation-of-a-new-process-of-qingdianxia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/longchangextracts.com\/evaluation-of-a-new-process-of-qingdianxia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/longchangextracts.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Evaluation of a new process of Qingdianxia concoction based on quality consistency before and after concoction\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/longchangextracts.com\/#website\",\"url\":\"https:\/\/longchangextracts.com\/\",\"name\":\"China Chemical Manufacturer\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/longchangextracts.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\",\"name\":\"longcha9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"caption\":\"longcha9\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9valuation d'un nouveau proc\u00e9d\u00e9 de concoction de Qingdianxia bas\u00e9 sur la coh\u00e9rence de la qualit\u00e9 avant et apr\u00e8s la concoction - China Chemical Manufacturer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/longchangextracts.com\/fr\/evaluation-dun-nouveau-procede-de-qingdianxia\/","og_locale":"fr_FR","og_type":"article","og_title":"Evaluation of a new process of Qingdianxia concoction based on quality consistency before and after concoction - China Chemical Manufacturer","og_description":"Pinellia Rhizoma (PR) is the dried tuber of Pinellia ternata (Thunb.) Breit. It has the effects of drying dampness and resolving phlegm, subduing rebelliousness, stopping vomiting, eliminating lumps and dispersing knots, and is one of the commonly used traditional Chinese medicines in clinical practice. Pinelliae Rhizoma Praeparatum cum Alumine (PRPA) is a concocted tablet of [&hellip;]","og_url":"https:\/\/longchangextracts.com\/fr\/evaluation-dun-nouveau-procede-de-qingdianxia\/","og_site_name":"China Chemical Manufacturer","article_published_time":"2024-04-19T09:07:14+00:00","author":"longcha9","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"longcha9","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/longchangextracts.com\/evaluation-of-a-new-process-of-qingdianxia\/","url":"https:\/\/longchangextracts.com\/evaluation-of-a-new-process-of-qingdianxia\/","name":"\u00c9valuation d'un nouveau proc\u00e9d\u00e9 de concoction de Qingdianxia bas\u00e9 sur la coh\u00e9rence de la qualit\u00e9 avant et apr\u00e8s la concoction - China Chemical Manufacturer","isPartOf":{"@id":"https:\/\/longchangextracts.com\/#website"},"datePublished":"2024-04-19T09:07:14+00:00","dateModified":"2024-04-19T09:07:14+00:00","author":{"@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869"},"breadcrumb":{"@id":"https:\/\/longchangextracts.com\/evaluation-of-a-new-process-of-qingdianxia\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/longchangextracts.com\/evaluation-of-a-new-process-of-qingdianxia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/longchangextracts.com\/evaluation-of-a-new-process-of-qingdianxia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/longchangextracts.com\/"},{"@type":"ListItem","position":2,"name":"Evaluation of a new process of Qingdianxia concoction based on quality consistency before and after concoction"}]},{"@type":"WebSite","@id":"https:\/\/longchangextracts.com\/#website","url":"https:\/\/longchangextracts.com\/","name":"Fabricant chinois de produits chimiques","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/longchangextracts.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869","name":"longcha9","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","caption":"longcha9"}}]}},"_links":{"self":[{"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/posts\/3377"}],"collection":[{"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/comments?post=3377"}],"version-history":[{"count":2,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/posts\/3377\/revisions"}],"predecessor-version":[{"id":3379,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/posts\/3377\/revisions\/3379"}],"wp:attachment":[{"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/media?parent=3377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/categories?post=3377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/longchangextracts.com\/fr\/wp-json\/wp\/v2\/tags?post=3377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}