{"id":8466,"date":"2024-08-14T15:11:33","date_gmt":"2024-08-14T15:11:33","guid":{"rendered":"https:\/\/longchangextracts.com\/?p=8466"},"modified":"2024-08-14T15:11:33","modified_gmt":"2024-08-14T15:11:33","slug":"tau-protein-hyperphosphorylation","status":"publish","type":"post","link":"https:\/\/longchangextracts.com\/es\/hiperfosforilacion-de-la-proteina-tau\/","title":{"rendered":"Avances en la investigaci\u00f3n sobre la regulaci\u00f3n de la hiperfosforilaci\u00f3n de la prote\u00edna tau en la enfermedad de Alzheimer mediante la medicina tradicional china"},"content":{"rendered":"<p>Avances en la investigaci\u00f3n sobre la regulaci\u00f3n de la hiperfosforilaci\u00f3n de la prote\u00edna tau en la enfermedad de Alzheimer mediante la medicina tradicional china<br \/>\nEn la actualidad, el patr\u00f3n demogr\u00e1fico mundial muestra una tendencia al envejecimiento, y la incidencia de la enfermedad de Alzheimer (EA) aumenta a\u00f1o tras a\u00f1o. En 30 a\u00f1os, el n\u00famero total de pacientes ancianos con demencia en todo el mundo alcanzar\u00e1 los 138 millones, y la gran mayor\u00eda ser\u00e1n pacientes con EA. Afectado por la actual epidemia de nuevos coronavirus, el n\u00famero de trabajadores de enfermer\u00eda para pacientes con EA ha disminuido dr\u00e1sticamente, aumentando la presi\u00f3n del enorme grupo de pacientes con EA sobre los individuos, las familias y toda la sociedad. El inicio y la progresi\u00f3n de la EA a\u00fan no son controlables, y los trastornos emocionales y cognitivos progresivos, as\u00ed como el deterioro de la memoria, son sus manifestaciones cl\u00ednicas m\u00e1s significativas. La sobrefosforilaci\u00f3n de la prote\u00edna tau es el principal factor que da lugar a los ovillos neurofibrilares (NFT), que son la principal caracter\u00edstica patol\u00f3gica de la EA. La prote\u00edna tau es una prote\u00edna asociada a microt\u00fabulos que se une a \u00e9stos para mantener su estabilidad estructural y su funci\u00f3n fisiol\u00f3gica. Las treoninas (Thr), serinas (Ser) y tirosinas (Tyr) localizadas en la prote\u00edna tau se denominan sitios de fosforilaci\u00f3n, que sufren fosforilaci\u00f3n bajo la acci\u00f3n de quinasas para formar prote\u00edna tau fosforilada; la prote\u00edna tau fosforilada se disocia de los microt\u00fabulos unidos, lo que conduce a una disminuci\u00f3n de la estabilidad de los microt\u00fabulos y provoca el colapso del citoesqueleto. La prote\u00edna tau fosforilada disociada forma una estructura de doble h\u00e9lice y posteriormente forma NFTs; La fosfatasa puede eliminar los grupos fosfato de la prote\u00edna tau fosforilada y restaurar su funci\u00f3n fisiol\u00f3gica (ver Figura 1). En resumen, el nivel de fosforilaci\u00f3n de la prote\u00edna tau depende de la regulaci\u00f3n conjunta de la cinasa y la fosfatasa.<\/p>\n<p>La EA pertenece a la categor\u00eda de \"demencia\" en la medicina tradicional china, que tiene las caracter\u00edsticas de diferenciaci\u00f3n y tratamiento de s\u00edndrome, concepto hol\u00edstico y combinaci\u00f3n de enfermedad y s\u00edndrome. El uso de la medicina tradicional china tiene ventajas \u00fanicas en la prevenci\u00f3n y el tratamiento de la EA. Seg\u00fan los estudios cl\u00ednicos y con animales existentes, la medicina tradicional china tiene la ventaja de inhibir la hiperfosforilaci\u00f3n de la prote\u00edna tau a trav\u00e9s de m\u00faltiples v\u00edas en la prevenci\u00f3n y el tratamiento de la enfermedad de Alzheimer (v\u00e9anse las Tablas 1 y 2). Por ejemplo, la medicina tradicional china regula la actividad de quinasas y fosfatasas para reducir los niveles de fosforilaci\u00f3n de la prote\u00edna tau, frenando as\u00ed la formaci\u00f3n de NFT. Por lo tanto, este art\u00edculo explora el mecanismo de intervenci\u00f3n de la medicina tradicional china en la hiperfosforilaci\u00f3n de la prote\u00edna tau y la prevenci\u00f3n y el tratamiento de la EA desde la perspectiva de la regulaci\u00f3n de quinasas y fosfatasas.<\/p>\n<p>&nbsp;<\/p>\n<p>Aunque en la actualidad no existe una forma madura de intervenir en el inicio y la progresi\u00f3n de la enfermedad de Alzheimer, un gran n\u00famero de experimentos cl\u00ednicos, animales y celulares con medicina tradicional china han confirmado que tiene un cierto efecto en la intervenci\u00f3n sobre la hiperfosforilaci\u00f3n de la prote\u00edna tau en la enfermedad de Alzheimer. La medicina tradicional china considera que la EA se localiza en el cerebro y est\u00e1 estrechamente relacionada con los cuatro \u00f3rganos del coraz\u00f3n, el h\u00edgado, el bazo y los ri\u00f1ones. Bajo la direcci\u00f3n del coraz\u00f3n, el bazo transporta los nutrientes, el h\u00edgado regula el organismo, los ri\u00f1ones almacenan la esencia y los distintos \u00f3rganos cooperan para garantizar el funcionamiento normal del sistema nervioso. Se ha confirmado que una serie de f\u00f3rmulas herbales con los efectos de nutrir el h\u00edgado y el ri\u00f1\u00f3n, nutrir el qi y promover la circulaci\u00f3n sangu\u00ednea, nutrir la m\u00e9dula y la inteligencia, despejar el calor y desintoxicar tienen un mejor efecto regulador sobre las quinasas. Al debilitar la actividad de quinasas como GSK-3 \u03b2, CDK5, JNK, ERK y regular las v\u00edas de se\u00f1alizaci\u00f3n correspondientes, se inhibe la fosforilaci\u00f3n de los sitios correspondientes de la prote\u00edna tau, frenando as\u00ed la conversi\u00f3n de la prote\u00edna tau en prote\u00edna tau fosforilada. Aunque todav\u00eda no es posible detectar completamente los sitios de fosforilaci\u00f3n de la prote\u00edna tau fosforilada, pueden demostrarse las diferencias en los efectos de las distintas quinasas sobre la fosforilaci\u00f3n de la prote\u00edna tau. Adem\u00e1s, la \"teor\u00eda del s\u00edndrome sangu\u00edneo\" afirma: \"Si hay estasis sangu\u00ednea en el coraz\u00f3n, tambi\u00e9n puede causar olvido\". Se cree que la estasis sangu\u00ednea es uno de los principales factores patog\u00e9nicos de la EA. Los experimentos han demostrado que las recetas con los efectos de tonificar el qi, promover la circulaci\u00f3n sangu\u00ednea, calentar el yang y eliminar la estasis sangu\u00ednea tienen mejores efectos terap\u00e9uticos en la EA, especialmente en la regulaci\u00f3n de la fosforilaci\u00f3n excesiva de la prote\u00edna tau; Puede regular directamente la actividad de la fosfatasa, aumentar el efecto de desfosforilaci\u00f3n en la prote\u00edna tau fosforilada, reducir la producci\u00f3n de NFT y prevenir y tratar la EA. Adem\u00e1s, en los \"Registros secretos de la C\u00e1mara de Piedra\" se afirma: \"La flema es lo m\u00e1s abundante, y el estancamiento lo m\u00e1s profundo\". Durante la dinast\u00eda Qing, Chen Shiduo cre\u00eda que el \"estancamiento\" estaba estrechamente relacionado con la \"flema\". Los experimentos han demostrado que las f\u00f3rmulas con los efectos de tonificar el h\u00edgado y los ri\u00f1ones, nutrir el qi y el yang, promover la circulaci\u00f3n sangu\u00ednea y eliminar la estasis sangu\u00ednea, y resolver la flema y abrir los orificios tienen un efecto regulador conjunto sobre las quinasas y las fosfatasas. Debido al efecto de fosforilaci\u00f3n m\u00e1s fuerte de GSK-3 \u03b2 en las quinasas y el efecto de desfosforilaci\u00f3n m\u00e1s fuerte de PP2A en las fosfatasas, la mayor\u00eda de los estudios se centran en GSK-3 \u03b2 y PP2A como los principales objetivos de detecci\u00f3n para revelar el mecanismo de la regulaci\u00f3n de m\u00faltiples v\u00edas de la medicina tradicional china de la fosforilaci\u00f3n de la prote\u00edna tau.<\/p>\n<p>La medicina tradicional china puede regular el nivel de fosforilaci\u00f3n de la prote\u00edna tau afectando a las quinasas, a las fosfatasas o a ambas, logrando el objetivo de prevenir y tratar la EA. En cuanto a la investigaci\u00f3n actual sobre la medicina tradicional china, el autor cree que todav\u00eda se puede avanzar en los siguientes aspectos: (1) El tratamiento de la medicina tradicional china tiene las caracter\u00edsticas de la diferenciaci\u00f3n y el tratamiento del s\u00edndrome, que pueden reflejarse en el proceso de diferenciaci\u00f3n de la enfermedad en un gran n\u00famero de experimentos, pero las caracter\u00edsticas de la diferenciaci\u00f3n del s\u00edndrome no se han demostrado plenamente. Por lo tanto, el contenido de la diferenciaci\u00f3n del s\u00edndrome para los sujetos experimentales se puede a\u00f1adir en los experimentos con animales; (2) La medicina tradicional china y las recetas compuestas tienen un efecto terap\u00e9utico definido en la EA, pero debido a su compleja composici\u00f3n, el mecanismo de acci\u00f3n a\u00fan no se ha dilucidado, y su credibilidad de promoci\u00f3n es baja. La tecnolog\u00eda moderna de investigaci\u00f3n m\u00e9dica puede combinarse con la medicina tradicional china para la prevenci\u00f3n y el tratamiento de la EA. Por un lado, se pueden purificar y analizar los ingredientes eficaces de la medicina tradicional china y, por otro, se pueden explorar las reglas de compatibilidad de la medicina tradicional china para regular las quinasas y las fosfatasas, intentando explicar el significado de la compatibilidad de los f\u00e1rmacos a nivel molecular; (3) M\u00faltiples tipos de quinasas y fosfatasas exhiben una interacci\u00f3n en forma de red para regular el nivel de fosforilaci\u00f3n de la prote\u00edna tau. Sin embargo, actualmente, en el mismo experimento, debido a la detecci\u00f3n incompleta de los tipos de quinasas y fosfatasas y los sitios de fosforilaci\u00f3n de la prote\u00edna tau fosforilada, no es suficiente para construir una comprensi\u00f3n global de los efectos de la medicina tradicional china sobre las quinasas y fosfatasas. Al aumentar los tipos de quinasas y fosfatasas detectadas, as\u00ed como los sitios de fosforilaci\u00f3n de la prote\u00edna tau fosforilada, se pueden encontrar m\u00e1s pruebas suficientes para demostrar la red como el sistema de regulaci\u00f3n de la medicina tradicional china sobre las quinasas y fosfatasas; (4) Algunos estudios s\u00f3lo analizan cuantitativamente la prote\u00edna tau y la prote\u00edna tau fosforilada, descuidando la detecci\u00f3n de enlaces intermedios (quinasas, fosfatasas, u otros indicadores), lo que resulta en la falta de cadenas de pruebas y s\u00f3lo mostrar los resultados sin elaborar sobre las razones. En investigaciones posteriores, la detecci\u00f3n de pruebas intermedias puede a\u00f1adirse adecuadamente para formar una cadena de pruebas completa; (5) Un gran n\u00famero de experimentos cl\u00ednicos y con animales han demostrado que la medicina tradicional china tiene mejores efectos terap\u00e9uticos, pero los efectos secundarios t\u00f3xicos de la medicina tradicional china a\u00fan no est\u00e1n claros. Se recomienda aumentar los experimentos toxicol\u00f3gicos sobre la medicina tradicional china relacionada para proporcionar una orientaci\u00f3n m\u00e1s segura para su uso cl\u00ednico.<\/p>","protected":false},"excerpt":{"rendered":"<p>Research progress on the regulation of tau protein hyperphosphorylation in Alzheimer&#8217;s disease by traditional Chinese medicine At present, the global population pattern is showing an aging trend, and the incidence of Alzheimer&#8217;s disease (AD) is increasing year by year. In 30 years, the total number of elderly dementia patients worldwide will reach 138 million, with [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Research progress on the regulation of tau protein hyperphosphorylation in Alzheimer&#039;s disease by traditional Chinese medicine - China Chemical Manufacturer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/longchangextracts.com\/es\/hiperfosforilacion-de-la-proteina-tau\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Research progress on the regulation of tau protein hyperphosphorylation in Alzheimer&#039;s disease by traditional Chinese medicine - China Chemical Manufacturer\" \/>\n<meta property=\"og:description\" content=\"Research progress on the regulation of tau protein hyperphosphorylation in Alzheimer&#8217;s disease by traditional Chinese medicine At present, the global population pattern is showing an aging trend, and the incidence of Alzheimer&#8217;s disease (AD) is increasing year by year. In 30 years, the total number of elderly dementia patients worldwide will reach 138 million, with [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/longchangextracts.com\/es\/hiperfosforilacion-de-la-proteina-tau\/\" \/>\n<meta property=\"og:site_name\" content=\"China Chemical Manufacturer\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-14T15:11:33+00:00\" \/>\n<meta name=\"author\" content=\"Longchang Chemical\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Longchang Chemical\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/longchangextracts.com\/tau-protein-hyperphosphorylation\/\",\"url\":\"https:\/\/longchangextracts.com\/tau-protein-hyperphosphorylation\/\",\"name\":\"Research progress on the regulation of tau protein hyperphosphorylation in Alzheimer's disease by traditional Chinese medicine - China Chemical Manufacturer\",\"isPartOf\":{\"@id\":\"https:\/\/longchangextracts.com\/#website\"},\"datePublished\":\"2024-08-14T15:11:33+00:00\",\"dateModified\":\"2024-08-14T15:11:33+00:00\",\"author\":{\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\"},\"breadcrumb\":{\"@id\":\"https:\/\/longchangextracts.com\/tau-protein-hyperphosphorylation\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/longchangextracts.com\/tau-protein-hyperphosphorylation\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/longchangextracts.com\/tau-protein-hyperphosphorylation\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/longchangextracts.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Research progress on the regulation of tau protein hyperphosphorylation in Alzheimer&#8217;s disease by traditional Chinese medicine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/longchangextracts.com\/#website\",\"url\":\"https:\/\/longchangextracts.com\/\",\"name\":\"China Chemical Manufacturer\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/longchangextracts.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\",\"name\":\"Longchang Chemical\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"caption\":\"Longchang Chemical\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Progreso de la investigaci\u00f3n sobre la regulaci\u00f3n de la hiperfosforilaci\u00f3n de la prote\u00edna tau en la enfermedad de Alzheimer por la medicina tradicional china - China Fabricante de Productos Qu\u00edmicos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/longchangextracts.com\/es\/hiperfosforilacion-de-la-proteina-tau\/","og_locale":"es_ES","og_type":"article","og_title":"Research progress on the regulation of tau protein hyperphosphorylation in Alzheimer's disease by traditional Chinese medicine - China Chemical Manufacturer","og_description":"Research progress on the regulation of tau protein hyperphosphorylation in Alzheimer&#8217;s disease by traditional Chinese medicine At present, the global population pattern is showing an aging trend, and the incidence of Alzheimer&#8217;s disease (AD) is increasing year by year. In 30 years, the total number of elderly dementia patients worldwide will reach 138 million, with [&hellip;]","og_url":"https:\/\/longchangextracts.com\/es\/hiperfosforilacion-de-la-proteina-tau\/","og_site_name":"China Chemical Manufacturer","article_published_time":"2024-08-14T15:11:33+00:00","author":"Longchang Chemical","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Longchang Chemical","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/longchangextracts.com\/tau-protein-hyperphosphorylation\/","url":"https:\/\/longchangextracts.com\/tau-protein-hyperphosphorylation\/","name":"Progreso de la investigaci\u00f3n sobre la regulaci\u00f3n de la hiperfosforilaci\u00f3n de la prote\u00edna tau en la enfermedad de Alzheimer por la medicina tradicional china - China Fabricante de Productos Qu\u00edmicos","isPartOf":{"@id":"https:\/\/longchangextracts.com\/#website"},"datePublished":"2024-08-14T15:11:33+00:00","dateModified":"2024-08-14T15:11:33+00:00","author":{"@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869"},"breadcrumb":{"@id":"https:\/\/longchangextracts.com\/tau-protein-hyperphosphorylation\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/longchangextracts.com\/tau-protein-hyperphosphorylation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/longchangextracts.com\/tau-protein-hyperphosphorylation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/longchangextracts.com\/"},{"@type":"ListItem","position":2,"name":"Research progress on the regulation of tau protein hyperphosphorylation in Alzheimer&#8217;s disease by traditional Chinese medicine"}]},{"@type":"WebSite","@id":"https:\/\/longchangextracts.com\/#website","url":"https:\/\/longchangextracts.com\/","name":"China Fabricante de productos qu\u00edmicos","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/longchangextracts.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869","name":"Longchang Chemical","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","caption":"Longchang Chemical"}}]}},"_links":{"self":[{"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/posts\/8466"}],"collection":[{"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/comments?post=8466"}],"version-history":[{"count":1,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/posts\/8466\/revisions"}],"predecessor-version":[{"id":8467,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/posts\/8466\/revisions\/8467"}],"wp:attachment":[{"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/media?parent=8466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/categories?post=8466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/tags?post=8466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}