{"id":8237,"date":"2024-08-11T20:54:50","date_gmt":"2024-08-11T20:54:50","guid":{"rendered":"https:\/\/longchangextracts.com\/?p=8237"},"modified":"2024-08-11T20:54:50","modified_gmt":"2024-08-11T20:54:50","slug":"bitter-water-rose","status":"publish","type":"post","link":"https:\/\/longchangextracts.com\/es\/bitter-water-rose\/","title":{"rendered":"An\u00e1lisis de la composici\u00f3n qu\u00edmica del extracto alcoh\u00f3lico de rosa de agua amarga mediante UPLC-Q-TOF-MS"},"content":{"rendered":"<p>An\u00e1lisis de la composici\u00f3n qu\u00edmica del extracto alcoh\u00f3lico de rosa de agua amarga mediante UPLC-Q-TOF-MS<br \/>\nLa rosa (Rosa rugosa Thunb) es un arbusto de hoja perenne o caduca de la familia de las ros\u00e1ceas que se planta en diversas partes del pa\u00eds. Entre las variedades m\u00e1s famosas se encuentran la Rosa Pingyin de Shandong, la Rosa Kushui de Gansu, la Rosa Miaofengshan de Pek\u00edn, etc. Entre ellas, Rosa sertata \u00d7 Rosa rugosa es un h\u00edbrido natural de rosa china y Rosa obtusifolia, que tiene los efectos de ayudar a dormir, contra la ansiedad, etc., y el aceite de rosa extra\u00eddo de los p\u00e9talos tambi\u00e9n puede utilizarse como importante materia prima para esencias avanzadas, perfumes, perfumes y cosm\u00e9ticos, lo que est\u00e1 estrechamente relacionado con su composici\u00f3n qu\u00edmica. Estudios anteriores han demostrado que hay m\u00e1s de cien componentes qu\u00edmicos en las rosas, incluyendo principalmente aceites vol\u00e1tiles, flavonoides, polifenoles, polisac\u00e1ridos y otros compuestos. El aceite vol\u00e1til es la principal clase de compuestos del aceite esencial de rosa, y contiene principalmente componentes qu\u00edmicos como el citronelol y el geraniol. Los polifenoles y los flavonoides son los principales ingredientes activos de las rosas, que tienen las funciones de eliminar los radicales libres y la deposici\u00f3n de pigmentos, y son importantes sustancias antioxidantes.<\/p>\n<p>En la actualidad, hay muchos estudios sobre la composici\u00f3n qu\u00edmica de los aceites vol\u00e1tiles en el aceite esencial de rosa, pero el an\u00e1lisis de flavonoides, polifenoles y otros compuestos en rosas a\u00fan no est\u00e1 completo, y hay pocos informes sobre la composici\u00f3n qu\u00edmica de las variedades de rosa de agua amarga. Por lo tanto, en este estudio, se utiliz\u00f3 la t\u00e9cnica de espectrometr\u00eda de masas de tiempo de vuelo cuadrupolar de cromatograf\u00eda l\u00edquida de ultra alto rendimiento (UPLC-Q-TOF-MS) con alta sensibilidad, selectividad, estabilidad, resoluci\u00f3n y amplio rango de exploraci\u00f3n para analizar e identificar 63 componentes qu\u00edmicos principales del extracto de etanol de Rosa rugosa. En comparaci\u00f3n con estudios anteriores, este estudio mejor\u00f3 a\u00fan m\u00e1s la identificaci\u00f3n de la composici\u00f3n qu\u00edmica de flavonoides y polifenoles en rosas de agua amarga, y por primera vez, 28 compuestos fueron identificados en este g\u00e9nero, proporcionando referencia y base te\u00f3rica para el control de calidad y la investigaci\u00f3n farmacol\u00f3gica base de sustancias de rosas de agua amarga.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Este estudio utiliza la tecnolog\u00eda UPLC-Q-TOF-MS, que tiene las caracter\u00edsticas de alta sensibilidad, alta precisi\u00f3n y alta resoluci\u00f3n, y puede identificar de forma m\u00e1s exhaustiva y r\u00e1pida los componentes qu\u00edmicos de las rosas de agua amarga. Nuestro grupo de investigaci\u00f3n investig\u00f3 los picos de espectrometr\u00eda de masas y las respuestas i\u00f3nicas del extracto de agua de rosas y del extracto de alcohol en modo de iones negativos antes del estudio. Bas\u00e1ndose en el an\u00e1lisis de picos, se descubri\u00f3 que el extracto de alcohol de agua de rosas ten\u00eda una buena separaci\u00f3n y una alta respuesta en el cromatograma de iones de espectrometr\u00eda de masas (-) ESI-MS. Por lo tanto, se utiliz\u00f3 UPLC-Q-TOF-MS para analizar sistem\u00e1ticamente los componentes qu\u00edmicos en el extracto de alcohol de agua de rosas, mejorando a\u00fan m\u00e1s la identificaci\u00f3n de los componentes qu\u00edmicos del agua de rosas.<br \/>\nEn este estudio se identificaron 26 flavonoides, 11 polifenoles (incluidos 4 \u00e1cidos fen\u00f3licos y 7 taninos), 7 triterpenoides, 4 fenilpropanoides, 1 terpeno de \u00e9ter ciclohexeno, 1 aceite vol\u00e1til y 8 compuestos de \u00e1cidos org\u00e1nicos del extracto alcoh\u00f3lico de rosa de agua amarga. Entre ellos, los \u00e1cidos fen\u00f3licos, los taninos y los flavonoides son sus principales ingredientes activos. Los resultados muestran que los flavonoides identificados se componen principalmente de compuestos con quercetina y kaempferol como agliconas, lo que es similar a los resultados de identificaci\u00f3n anteriores. Los cuatro compuestos \u00e1cidos fen\u00f3licos identificados pertenecen todos a la clase del \u00e1cido g\u00e1lico y tienen efectos de secado de la humedad, astringencia, eliminaci\u00f3n del calor y reducci\u00f3n de la inflamaci\u00f3n, enfriamiento de la sangre y detenci\u00f3n de las hemorragias. Los compuestos t\u00e1nicos, excepto los compuestos 16 y 17, tambi\u00e9n son taninos de \u00e1cido g\u00e1lico, que tienen actividades farmacol\u00f3gicas como efectos antitumorales y antioxidantes, junto con los flavonoides. Adem\u00e1s, los compuestos polifen\u00f3licos tienen altos valores de respuesta en la espectrometr\u00eda de masas, lo que demuestra una vez m\u00e1s que las rosas de agua amarga tienen excelentes efectos antioxidantes y antitumorales. Seg\u00fan la bibliograf\u00eda, las rosas tambi\u00e9n contienen compuestos pigmentarios como cianidina-3,5-digluc\u00f3sido, delfinidina-3-gluc\u00f3sido, etc. Sin embargo, esto no se identific\u00f3 en los resultados de este estudio, lo que puede estar relacionado con el tratamiento o las condiciones de calidad del l\u00edquido de las rosas de agua amarga y requiere m\u00e1s investigaci\u00f3n. Y tambi\u00e9n se encontr\u00f3 a partir del diagrama TIC del modo de iones negativos de la rosa de agua amarga que algunos compuestos con picos de alta respuesta no pudieron ser identificados con precisi\u00f3n debido a las f\u00f3rmulas estructurales irrazonables emparejadas por la base de datos en l\u00ednea, tales como los picos 10, 14, 21, 24, y 43, lo que indica que todav\u00eda hay algunos compuestos desconocidos en la rosa de agua amarga, que pueden ser los principales componentes de la rosa de agua amarga y necesitan m\u00e1s investigaci\u00f3n y an\u00e1lisis.<br \/>\nEste estudio estableci\u00f3 un m\u00e9todo de an\u00e1lisis r\u00e1pido utilizando la tecnolog\u00eda UPLC-Q-TOF-MS para las rosas de agua amarga. Bas\u00e1ndose en el peso molecular relativo exacto, la informaci\u00f3n sobre fragmentos de espectrometr\u00eda de masas y la bibliograf\u00eda y bases de datos pertinentes, se analiz\u00f3 e identific\u00f3 de forma m\u00e1s exhaustiva la composici\u00f3n qu\u00edmica de las rosas de agua amarga. Se identificaron 58 compuestos, 28 de los cuales se identificaron por primera vez en este g\u00e9nero. Esto proporciona una referencia y una base cient\u00edfica para la investigaci\u00f3n b\u00e1sica sobre los efectos farmacol\u00f3gicos y los principios activos de las rosas de agua amarga.<\/p>","protected":false},"excerpt":{"rendered":"<p>Chemical composition analysis of bitter water rose alcohol extract based on UPLC-Q-TOF-MS Rose (Rosa rugose Thunb) is an evergreen or deciduous shrub of the Rosaceae family, and is planted in various parts of the country. Famous varieties include Shandong Pingyin Rose, Gansu Kushui Rose, Beijing Miaofengshan Rose, etc. Among them, Rosa sertata \u00d7 Rosa rugosa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Chemical composition analysis of bitter water rose alcohol extract based on UPLC-Q-TOF-MS - China Chemical Manufacturer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/longchangextracts.com\/es\/bitter-water-rose\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chemical composition analysis of bitter water rose alcohol extract based on UPLC-Q-TOF-MS - China Chemical Manufacturer\" \/>\n<meta property=\"og:description\" content=\"Chemical composition analysis of bitter water rose alcohol extract based on UPLC-Q-TOF-MS Rose (Rosa rugose Thunb) is an evergreen or deciduous shrub of the Rosaceae family, and is planted in various parts of the country. Famous varieties include Shandong Pingyin Rose, Gansu Kushui Rose, Beijing Miaofengshan Rose, etc. Among them, Rosa sertata \u00d7 Rosa rugosa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/longchangextracts.com\/es\/bitter-water-rose\/\" \/>\n<meta property=\"og:site_name\" content=\"China Chemical Manufacturer\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-11T20:54:50+00:00\" \/>\n<meta name=\"author\" content=\"Longchang Chemical\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Longchang Chemical\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/longchangextracts.com\/bitter-water-rose\/\",\"url\":\"https:\/\/longchangextracts.com\/bitter-water-rose\/\",\"name\":\"Chemical composition analysis of bitter water rose alcohol extract based on UPLC-Q-TOF-MS - China Chemical Manufacturer\",\"isPartOf\":{\"@id\":\"https:\/\/longchangextracts.com\/#website\"},\"datePublished\":\"2024-08-11T20:54:50+00:00\",\"dateModified\":\"2024-08-11T20:54:50+00:00\",\"author\":{\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\"},\"breadcrumb\":{\"@id\":\"https:\/\/longchangextracts.com\/bitter-water-rose\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/longchangextracts.com\/bitter-water-rose\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/longchangextracts.com\/bitter-water-rose\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/longchangextracts.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chemical composition analysis of bitter water rose alcohol extract based on UPLC-Q-TOF-MS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/longchangextracts.com\/#website\",\"url\":\"https:\/\/longchangextracts.com\/\",\"name\":\"China Chemical Manufacturer\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/longchangextracts.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\",\"name\":\"Longchang Chemical\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"caption\":\"Longchang Chemical\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"An\u00e1lisis de la composici\u00f3n qu\u00edmica del extracto alcoh\u00f3lico de rosa de agua amarga basado en UPLC-Q-TOF-MS - China Fabricante de Productos Qu\u00edmicos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/longchangextracts.com\/es\/bitter-water-rose\/","og_locale":"es_ES","og_type":"article","og_title":"Chemical composition analysis of bitter water rose alcohol extract based on UPLC-Q-TOF-MS - China Chemical Manufacturer","og_description":"Chemical composition analysis of bitter water rose alcohol extract based on UPLC-Q-TOF-MS Rose (Rosa rugose Thunb) is an evergreen or deciduous shrub of the Rosaceae family, and is planted in various parts of the country. Famous varieties include Shandong Pingyin Rose, Gansu Kushui Rose, Beijing Miaofengshan Rose, etc. Among them, Rosa sertata \u00d7 Rosa rugosa [&hellip;]","og_url":"https:\/\/longchangextracts.com\/es\/bitter-water-rose\/","og_site_name":"China Chemical Manufacturer","article_published_time":"2024-08-11T20:54:50+00:00","author":"Longchang Chemical","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Longchang Chemical","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/longchangextracts.com\/bitter-water-rose\/","url":"https:\/\/longchangextracts.com\/bitter-water-rose\/","name":"An\u00e1lisis de la composici\u00f3n qu\u00edmica del extracto alcoh\u00f3lico de rosa de agua amarga basado en UPLC-Q-TOF-MS - China Fabricante de Productos Qu\u00edmicos","isPartOf":{"@id":"https:\/\/longchangextracts.com\/#website"},"datePublished":"2024-08-11T20:54:50+00:00","dateModified":"2024-08-11T20:54:50+00:00","author":{"@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869"},"breadcrumb":{"@id":"https:\/\/longchangextracts.com\/bitter-water-rose\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/longchangextracts.com\/bitter-water-rose\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/longchangextracts.com\/bitter-water-rose\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/longchangextracts.com\/"},{"@type":"ListItem","position":2,"name":"Chemical composition analysis of bitter water rose alcohol extract based on UPLC-Q-TOF-MS"}]},{"@type":"WebSite","@id":"https:\/\/longchangextracts.com\/#website","url":"https:\/\/longchangextracts.com\/","name":"China Fabricante de productos qu\u00edmicos","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/longchangextracts.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869","name":"Longchang Chemical","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","caption":"Longchang Chemical"}}]}},"_links":{"self":[{"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/posts\/8237"}],"collection":[{"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/comments?post=8237"}],"version-history":[{"count":1,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/posts\/8237\/revisions"}],"predecessor-version":[{"id":8238,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/posts\/8237\/revisions\/8238"}],"wp:attachment":[{"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/media?parent=8237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/categories?post=8237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/tags?post=8237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}