{"id":8102,"date":"2024-08-11T19:09:06","date_gmt":"2024-08-11T19:09:06","guid":{"rendered":"https:\/\/longchangextracts.com\/?p=8102"},"modified":"2024-08-11T19:09:06","modified_gmt":"2024-08-11T19:09:06","slug":"study-on-pharmacokinetics-and-tissue-distribution-of-hydroxybenzoic-acid-and-its-sodium-salt-in-mice-and-crab-eating-macaques","status":"publish","type":"post","link":"https:\/\/longchangextracts.com\/es\/estudio-sobre-la-farmacocinetica-y-la-distribucion-tisular-del-acido-hidroxibenzoico-y-su-sal-sodica-en-ratones-y-macacos-cangrejeros\/","title":{"rendered":"Estudio de la farmacocin\u00e9tica y la distribuci\u00f3n tisular del \u00e1cido hidroxibenzoico y su sal s\u00f3dica en ratones y macacos cangrejeros"},"content":{"rendered":"<p>Estudio de la farmacocin\u00e9tica y la distribuci\u00f3n tisular del \u00e1cido hidroxibenzoico y su sal s\u00f3dica en ratones y macacos cangrejeros<br \/>\nEl \u00e1cido p-hidroxibenzoico (p-HBA) es un \u00e1cido monofen\u00f3lico com\u00fan en la naturaleza, que se encuentra en plantas superiores, microorganismos, musgos y el suelo. Tiene diversas actividades farmacol\u00f3gicas, como propiedades antibacterianas, antioxidantes, antiinflamatorias y anticancer\u00edgenas. Estudios anteriores han descubierto que el p-HBA es el metabolito activo del hidroxibenzaldeh\u00eddo, un ingrediente activo de las verduras molidas, que ejerce efectos anti colitis al inhibir las reacciones inflamatorias y mejorar el da\u00f1o de la mucosa intestinal. Se puede observar que el p-HBA puede servir como compuesto potencial para el tratamiento de la colitis ulcerosa y tiene buenas perspectivas de desarrollo. Sin embargo, los resultados preliminares del grupo de investigaci\u00f3n mostraron que el p-HBA tiene una escasa solubilidad en agua y va acompa\u00f1ado de reacciones adversas como la esplenomegalia, lo que afecta seriamente a su desarrollo posterior. Por lo tanto, el equipo de investigaci\u00f3n realiz\u00f3 un estudio sobre su sal s\u00f3dica, el p-hidroxibenzoato s\u00f3dico (s-HBA), y descubri\u00f3 que tiene buena estabilidad, ning\u00fan efecto secundario evidente y buena solubilidad en agua. Desde el punto de vista del metabolismo de los medicamentos, el cuerpo humano absorbe y utiliza m\u00e1s f\u00e1cilmente los f\u00e1rmacos salados. Al mismo tiempo, con el fin de comprender mejor los patrones de absorci\u00f3n y distribuci\u00f3n de p-HBA y s-HBA in vivo, este trabajo realiz\u00f3 un estudio sistem\u00e1tico sobre la farmacocin\u00e9tica y las caracter\u00edsticas de distribuci\u00f3n tisular de pHBA y s-HBA, proporcionando una base cient\u00edfica para el desarrollo y la utilizaci\u00f3n de s-HBA.<\/p>\n<p>&nbsp;<\/p>\n<p>Este estudio se basa en experimentos farmacol\u00f3gicos previos y, en una fase posterior, continuar\u00e1n los estudios farmacocin\u00e9ticos en ratones con colitis ulcerosa para investigar los efectos de su estado patol\u00f3gico en la farmacocin\u00e9tica del p-HBA y el s-HBA. Para mantener la coherencia con los estudios farmacol\u00f3gicos, se seguir\u00e1n utilizando ratones C57BL\/6, que son los m\u00e1s parecidos a la colitis humana en t\u00e9rminos de histopatolog\u00eda, para los experimentos farmacocin\u00e9ticos. En el experimento preliminar, este estudio dise\u00f1\u00f3 puntos de muestreo densos con una duraci\u00f3n de muestreo de 24 horas. Bas\u00e1ndose en los resultados del experimento preliminar, se llevaron a cabo dise\u00f1os experimentales sobre la fase de absorci\u00f3n, la fase de distribuci\u00f3n y la fase de eliminaci\u00f3n de p-HBA y s-HBA. La duraci\u00f3n formal del muestreo experimental fue de 4 horas, con un total de 8 puntos de muestreo. Bas\u00e1ndose en experimentos farmacol\u00f3gicos y de seguridad, se determin\u00f3 que la dosis final de p-HBA era de 20mg\/kg, y la dosis de sHBA tras la correcci\u00f3n del coeficiente de sal fue de 20, 50 y 100mg\/kg. En los estudios farmacocin\u00e9ticos, se administraron dos f\u00e1rmacos a la misma dosis de 20mg\/kg; en el estudio de distribuci\u00f3n organizativa, se seleccionaron ambos f\u00e1rmacos para la dosis \u00f3ptima. Como la dosis \u00f3ptima para el p-HBA era de 20mg\/kg y la dosis \u00f3ptima para el s-HBA era de 100mg\/kg, se eligieron el p-HBA (20mg\/kg) y el sHBA (100mg\/kg) con una diferencia de dosis de 5 veces para su administraci\u00f3n \u00fanica a fin de investigar su distribuci\u00f3n tisular. Adem\u00e1s, se dise\u00f1aron experimentos farmacocin\u00e9ticos de s-HBA en macacos cangrejeros. Tras la conversi\u00f3n de dosis equivalentes, se determin\u00f3 que las dosis finales eran de 4, 10 y 20mg\/kg, con un tiempo de muestreo de 6 horas y un total de 13 puntos temporales.<br \/>\nEl grado de absorci\u00f3n de los f\u00e1rmacos en el organismo afecta directamente a su eficacia, y la velocidad de eliminaci\u00f3n est\u00e1 estrechamente relacionada con su duraci\u00f3n de acci\u00f3n. A partir de los experimentos farmacocin\u00e9ticos en ratones, tanto el p-HBA como el s-HBA mostraron buenos procesos farmacocin\u00e9ticos tras la administraci\u00f3n oral, con una r\u00e1pida absorci\u00f3n y eliminaci\u00f3n en plasma, y sin acumulaci\u00f3n evidente in vivo. A la misma dosis, la Cmax y el AUC del s-HBA fueron ligeramente superiores a los del p-HBA, mientras que el V y el Cl fueron ligeramente inferiores, pero la diferencia no fue estad\u00edsticamente significativa. Esto puede deberse a la escasa hidrosolubilidad del p-HBA, que, al derivarse en sales de sodio, aumenta considerablemente la hidrosolubilidad del s-HBA. Tras la administraci\u00f3n oral, puede distribuirse m\u00e1s uniformemente en varias capas de la mucosa g\u00e1strica y absorberse m\u00e1s completamente. El S-HBA tambi\u00e9n exhibe buenos procesos farmacocin\u00e9ticos en macacos cangrejeros, y se absorbe y elimina r\u00e1pidamente; Bajo tres dosis de administraci\u00f3n oral, la Cmax y la AUC0-t del s-HBA en ratones y monos cangrejeros mostraron una buena relaci\u00f3n lineal con la dosis. Adem\u00e1s, el MRT0-t, V y Cl del s-HBA en ratones fueron ligeramente inferiores a los de los monos cangrejeros, con una diferencia de 2 a 3 veces, y la diferencia no fue demasiado significativa. En general, el proceso del s-HBA en roedores y no roedores es relativamente estable, sin absorci\u00f3n ni eliminaci\u00f3n espec\u00edficas.<br \/>\nTras entrar en el organismo, los f\u00e1rmacos ser\u00e1n transportados a diversos tejidos a trav\u00e9s del sistema circulatorio. Debido a las diferencias en la distribuci\u00f3n de los f\u00e1rmacos en el cuerpo, puede afectar al efecto terap\u00e9utico, la acumulaci\u00f3n y los efectos secundarios t\u00f3xicos de los f\u00e1rmacos. Por lo tanto, el estudio de la distribuci\u00f3n de los f\u00e1rmacos en diversos tejidos es de gran importancia para el desarrollo y la mejora de los f\u00e1rmacos. Los resultados de la distribuci\u00f3n organizativa mostraron que tras la administraci\u00f3n de p-HBA y s-HBA, ambos se distribuyeron y eliminaron r\u00e1pidamente en el tejido, con tiempos pico concentrados entre 0,03-0,17 horas y una eliminaci\u00f3n superior a 80% despu\u00e9s de 1 hora. El PHBA se distribuye ampliamente en los tejidos, con la mayor concentraci\u00f3n en los ri\u00f1ones y el h\u00edgado, seguidos de los pulmones, el coraz\u00f3n y el bazo. Estos tejidos son todos tejidos con abundante flujo sangu\u00edneo y peque\u00f1as barreras capilares, lo que puede ser una de las razones de la distribuci\u00f3n de la alta concentraci\u00f3n. Adem\u00e1s, se especula que el p-HBA puede ser excretado principalmente por los ri\u00f1ones y metabolizado por el h\u00edgado en el organismo; tambi\u00e9n puede ser el principal sitio de acumulaci\u00f3n del f\u00e1rmaco, lo que concuerda con la leve toxicidad renal y hep\u00e1tica observada en estudios anteriores con la dosis m\u00e1xima tolerada de s-HBA. Se detect\u00f3 cierta concentraci\u00f3n de p-HBA en el tejido cerebral, lo que indica que puede atravesar la barrera hematoencef\u00e1lica. Una situaci\u00f3n bastante especial es que existe una diferencia significativa en la concentraci\u00f3n de p-HBA en el colon tras la administraci\u00f3n de p-HBA y s-HBA. El tama\u00f1o de la distribuci\u00f3n tisular tras la administraci\u00f3n de p-HBA es ri\u00f1\u00f3n&gt;h\u00edgado&gt;pulm\u00f3n&gt;colon&gt;coraz\u00f3n&gt;bazo&gt;cerebro, mientras que tras la administraci\u00f3n de s-HBA, es ri\u00f1\u00f3n&gt;h\u00edgado&gt;pulm\u00f3n&gt;coraz\u00f3n&gt;bazo&gt;colon&gt;cerebro. La raz\u00f3n a\u00fan no est\u00e1 clara, y puede estar relacionada con el hecho de que el p-HBA y el s-HBA son f\u00e1rmacos potenciales para tratar la colitis, mientras que el colon es el principal \u00f3rgano implicado en las lesiones de colitis. Los experimentos posteriores seguir\u00e1n verific\u00e1ndolo.<br \/>\nEn resumen, tanto el p-HBA como el s-HBA tienen buenos procesos farmacocin\u00e9ticos, con una r\u00e1pida absorci\u00f3n y eliminaci\u00f3n in vivo. Se distribuyen ampliamente en los tejidos, con la concentraci\u00f3n m\u00e1s alta en los ri\u00f1ones y el h\u00edgado, lo que indica la orientaci\u00f3n tisular y la capacidad de atravesar la barrera hematoencef\u00e1lica. Todo ello demuestra las prometedoras perspectivas de desarrollo del p-HBA y el s-HBA. Hay estudios que indican que las condiciones patol\u00f3gicas repercuten en m\u00faltiples procesos farmacol\u00f3gicos. El equipo de investigaci\u00f3n estudiar\u00e1 ahora si la farmacocin\u00e9tica y la distribuci\u00f3n tisular del p-HBA y el s-HBA cambian en condiciones patol\u00f3gicas, lo que proporcionar\u00e1 m\u00e1s referencias para estudios posteriores.<\/p>","protected":false},"excerpt":{"rendered":"<p>Study on pharmacokinetics and tissue distribution of hydroxybenzoic acid and its sodium salt in mice and crab eating macaques P-hydroxybenzoic acid (p-HBA) is a monophenolic acid commonly found in nature, found in higher plants, microorganisms, mosses, and soil. It has various pharmacological activities such as antibacterial, antioxidant, anti-inflammatory, and anticancer properties. Previous studies have found [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Study on pharmacokinetics and tissue distribution of hydroxybenzoic acid and its sodium salt in mice and crab eating macaques - China Chemical Manufacturer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/longchangextracts.com\/es\/estudio-sobre-la-farmacocinetica-y-la-distribucion-tisular-del-acido-hidroxibenzoico-y-su-sal-sodica-en-ratones-y-macacos-cangrejeros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Study on pharmacokinetics and tissue distribution of hydroxybenzoic acid and its sodium salt in mice and crab eating macaques - China Chemical Manufacturer\" \/>\n<meta property=\"og:description\" content=\"Study on pharmacokinetics and tissue distribution of hydroxybenzoic acid and its sodium salt in mice and crab eating macaques P-hydroxybenzoic acid (p-HBA) is a monophenolic acid commonly found in nature, found in higher plants, microorganisms, mosses, and soil. It has various pharmacological activities such as antibacterial, antioxidant, anti-inflammatory, and anticancer properties. Previous studies have found [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/longchangextracts.com\/es\/estudio-sobre-la-farmacocinetica-y-la-distribucion-tisular-del-acido-hidroxibenzoico-y-su-sal-sodica-en-ratones-y-macacos-cangrejeros\/\" \/>\n<meta property=\"og:site_name\" content=\"China Chemical Manufacturer\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-11T19:09:06+00:00\" \/>\n<meta name=\"author\" content=\"Longchang Chemical\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Longchang Chemical\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/longchangextracts.com\/study-on-pharmacokinetics-and-tissue-distribution-of-hydroxybenzoic-acid-and-its-sodium-salt-in-mice-and-crab-eating-macaques\/\",\"url\":\"https:\/\/longchangextracts.com\/study-on-pharmacokinetics-and-tissue-distribution-of-hydroxybenzoic-acid-and-its-sodium-salt-in-mice-and-crab-eating-macaques\/\",\"name\":\"Study on pharmacokinetics and tissue distribution of hydroxybenzoic acid and its sodium salt in mice and crab eating macaques - China Chemical Manufacturer\",\"isPartOf\":{\"@id\":\"https:\/\/longchangextracts.com\/#website\"},\"datePublished\":\"2024-08-11T19:09:06+00:00\",\"dateModified\":\"2024-08-11T19:09:06+00:00\",\"author\":{\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\"},\"breadcrumb\":{\"@id\":\"https:\/\/longchangextracts.com\/study-on-pharmacokinetics-and-tissue-distribution-of-hydroxybenzoic-acid-and-its-sodium-salt-in-mice-and-crab-eating-macaques\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/longchangextracts.com\/study-on-pharmacokinetics-and-tissue-distribution-of-hydroxybenzoic-acid-and-its-sodium-salt-in-mice-and-crab-eating-macaques\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/longchangextracts.com\/study-on-pharmacokinetics-and-tissue-distribution-of-hydroxybenzoic-acid-and-its-sodium-salt-in-mice-and-crab-eating-macaques\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/longchangextracts.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Study on pharmacokinetics and tissue distribution of hydroxybenzoic acid and its sodium salt in mice and crab eating macaques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/longchangextracts.com\/#website\",\"url\":\"https:\/\/longchangextracts.com\/\",\"name\":\"China Chemical Manufacturer\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/longchangextracts.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\",\"name\":\"Longchang Chemical\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"caption\":\"Longchang Chemical\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudio de la farmacocin\u00e9tica y distribuci\u00f3n tisular del \u00e1cido hidroxibenzoico y su sal s\u00f3dica en ratones y macacos cangrejeros - China Fabricante de Productos Qu\u00edmicos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/longchangextracts.com\/es\/estudio-sobre-la-farmacocinetica-y-la-distribucion-tisular-del-acido-hidroxibenzoico-y-su-sal-sodica-en-ratones-y-macacos-cangrejeros\/","og_locale":"es_ES","og_type":"article","og_title":"Study on pharmacokinetics and tissue distribution of hydroxybenzoic acid and its sodium salt in mice and crab eating macaques - China Chemical Manufacturer","og_description":"Study on pharmacokinetics and tissue distribution of hydroxybenzoic acid and its sodium salt in mice and crab eating macaques P-hydroxybenzoic acid (p-HBA) is a monophenolic acid commonly found in nature, found in higher plants, microorganisms, mosses, and soil. It has various pharmacological activities such as antibacterial, antioxidant, anti-inflammatory, and anticancer properties. Previous studies have found [&hellip;]","og_url":"https:\/\/longchangextracts.com\/es\/estudio-sobre-la-farmacocinetica-y-la-distribucion-tisular-del-acido-hidroxibenzoico-y-su-sal-sodica-en-ratones-y-macacos-cangrejeros\/","og_site_name":"China Chemical Manufacturer","article_published_time":"2024-08-11T19:09:06+00:00","author":"Longchang Chemical","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Longchang Chemical","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/longchangextracts.com\/study-on-pharmacokinetics-and-tissue-distribution-of-hydroxybenzoic-acid-and-its-sodium-salt-in-mice-and-crab-eating-macaques\/","url":"https:\/\/longchangextracts.com\/study-on-pharmacokinetics-and-tissue-distribution-of-hydroxybenzoic-acid-and-its-sodium-salt-in-mice-and-crab-eating-macaques\/","name":"Estudio de la farmacocin\u00e9tica y distribuci\u00f3n tisular del \u00e1cido hidroxibenzoico y su sal s\u00f3dica en ratones y macacos cangrejeros - China Fabricante de Productos Qu\u00edmicos","isPartOf":{"@id":"https:\/\/longchangextracts.com\/#website"},"datePublished":"2024-08-11T19:09:06+00:00","dateModified":"2024-08-11T19:09:06+00:00","author":{"@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869"},"breadcrumb":{"@id":"https:\/\/longchangextracts.com\/study-on-pharmacokinetics-and-tissue-distribution-of-hydroxybenzoic-acid-and-its-sodium-salt-in-mice-and-crab-eating-macaques\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/longchangextracts.com\/study-on-pharmacokinetics-and-tissue-distribution-of-hydroxybenzoic-acid-and-its-sodium-salt-in-mice-and-crab-eating-macaques\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/longchangextracts.com\/study-on-pharmacokinetics-and-tissue-distribution-of-hydroxybenzoic-acid-and-its-sodium-salt-in-mice-and-crab-eating-macaques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/longchangextracts.com\/"},{"@type":"ListItem","position":2,"name":"Study on pharmacokinetics and tissue distribution of hydroxybenzoic acid and its sodium salt in mice and crab eating macaques"}]},{"@type":"WebSite","@id":"https:\/\/longchangextracts.com\/#website","url":"https:\/\/longchangextracts.com\/","name":"China Fabricante de productos qu\u00edmicos","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/longchangextracts.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869","name":"Longchang Chemical","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","caption":"Longchang Chemical"}}]}},"_links":{"self":[{"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/posts\/8102"}],"collection":[{"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/comments?post=8102"}],"version-history":[{"count":1,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/posts\/8102\/revisions"}],"predecessor-version":[{"id":8103,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/posts\/8102\/revisions\/8103"}],"wp:attachment":[{"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/media?parent=8102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/categories?post=8102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/tags?post=8102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}