{"id":8025,"date":"2024-08-11T17:52:52","date_gmt":"2024-08-11T17:52:52","guid":{"rendered":"https:\/\/longchangextracts.com\/?p=8025"},"modified":"2024-08-11T17:52:52","modified_gmt":"2024-08-11T17:52:52","slug":"shengcao-phenol","status":"publish","type":"post","link":"https:\/\/longchangextracts.com\/es\/shengcao-phenol\/","title":{"rendered":"Efecto del fenol Shengcao regulando la v\u00eda Akt\/mTOR sobre la autofagia en c\u00e9lulas de glioma"},"content":{"rendered":"<p>Efecto del fenol Shengcao regulando la v\u00eda Akt\/mTOR sobre la autofagia en c\u00e9lulas de glioma. El glioblastoma multimodal (GBM) es el tumor maligno m\u00e1s frecuente en el sistema nervioso central, con una alta malignidad e invasividad. Incluso tras un tratamiento exhaustivo con cirug\u00eda, radioterapia y quimioterapia, sigue presentando riesgo de recurrencia y met\u00e1stasis. La temozolomida (TMZ) es un f\u00e1rmaco de primera l\u00ednea contra el glioma en la pr\u00e1ctica cl\u00ednica. Sin embargo, debido a sus graves reacciones adversas, como la toxicidad sangu\u00ednea, esto limita enormemente el uso cl\u00ednico de la TMZ y afecta seriamente a su eficacia. Por lo tanto, la b\u00fasqueda de nuevos f\u00e1rmacos eficaces y de baja toxicidad contra el glioma es de gran importancia.<br \/>\nLa autofagia, como mecanismo de muerte celular programada, es un sistema din\u00e1mico de degradaci\u00f3n y circulaci\u00f3n. La autofagia es un proceso din\u00e1mico que implica tres estados: fagoforos, autofagosomas y autolisosomas. En los \u00faltimos a\u00f1os, la investigaci\u00f3n ha descubierto que las anomal\u00edas en la autofagia celular est\u00e1n estrechamente relacionadas con la aparici\u00f3n y el desarrollo de tumores. En los gliomas, la regulaci\u00f3n anormal de la autofagia puede promover el crecimiento tumoral, mientras que intervenir en la autofagia puede conducir a la muerte de las c\u00e9lulas del glioma e inhibir as\u00ed la progresi\u00f3n tumoral. Por lo tanto, la exploraci\u00f3n de nuevos m\u00e9todos de tratamiento del glioma dirigidos a la autofagia es una direcci\u00f3n de investigaci\u00f3n muy prometedora.<br \/>\nLa estructura qu\u00edmica del eriodictiol (ERD) se muestra en la Figura 1. Se trata de un flavonoide natural comestible que se encuentra ampliamente en verduras y frutas, especialmente en el agua de los c\u00edtricos, donde es m\u00e1s abundante. Las investigaciones han demostrado que el resveratrol tiene m\u00faltiples efectos farmacol\u00f3gicos, incluidos efectos antioxidantes, antiinflamatorios y antitumorales. Nuestra investigaci\u00f3n anterior encontr\u00f3 que el resveratrol puede inducir la apoptosis e inhibir la met\u00e1stasis de las c\u00e9lulas de glioma, pero su efecto sobre la autofagia a\u00fan no se ha estudiado. El objetivo de este estudio es explorar los efectos del resveratrol en la proliferaci\u00f3n y la autofagia de c\u00e9lulas de glioma a trav\u00e9s de experimentos, e investigar m\u00e1s a fondo los posibles mecanismos moleculares, proporcionando una base para dilucidar el mecanismo farmacol\u00f3gico de resveratrol contra el glioma.<\/p>\n<p>&nbsp;<\/p>\n<p>Los gliomas son tumores del sistema nervioso central con las mayores tasas de incidencia y mortalidad, caracterizados por una fuerte invasividad, una r\u00e1pida progresi\u00f3n maligna y unas tasas de curaci\u00f3n extremadamente bajas, con una mediana de supervivencia inferior a un a\u00f1o. Debido a las caracter\u00edsticas biol\u00f3gicas del crecimiento altamente invasivo del GBM, es casi imposible garantizar la resecci\u00f3n completa del tumor durante la cirug\u00eda, y la tasa de recurrencia postoperatoria es extremadamente alta. Por lo tanto, en la pr\u00e1ctica cl\u00ednica se suele adoptar un enfoque de tratamiento integral de cirug\u00eda+radioterapia y quimioterapia.<\/p>\n<p>En la actualidad, no existe un f\u00e1rmaco terap\u00e9utico ideal para el glioma. Los f\u00e1rmacos m\u00e1s utilizados en la pr\u00e1ctica cl\u00ednica incluyen principalmente agentes alquilantes biol\u00f3gicos, f\u00e1rmacos antitumorales dirigidos e inhibidores de puntos de control inmunitario. La TMZ es un f\u00e1rmaco quimioter\u00e1pico de primera l\u00ednea para el tratamiento del GBM, pero su selectividad es escasa, es propensa a la farmacorresistencia y tiene fuertes efectos secundarios, lo que a menudo da lugar a resultados insatisfactorios del tratamiento. Los f\u00e1rmacos antitumorales dirigidos y los inhibidores de los puntos de control inmunitario se caracterizan por su alta selectividad y sus m\u00ednimos efectos secundarios, y se han convertido gradualmente en los principales f\u00e1rmacos antitumorales en el extranjero. Sin embargo, los f\u00e1rmacos dirigidos y los inhibidores de puntos de control inmunitarios son caros, y su uso a largo plazo supone una pesada carga econ\u00f3mica y una gran presi\u00f3n para los pacientes. Por lo tanto, la b\u00fasqueda de nuevos f\u00e1rmacos eficaces, de baja toxicidad y asequibles contra el glioma es actualmente un tema candente en el campo de la investigaci\u00f3n del glioma. La medicina tradicional china y los productos activos naturales de nuestro pa\u00eds tienen abundantes fuentes, numerosos tipos, efectos secundarios t\u00f3xicos relativamente peque\u00f1os, y poseen las caracter\u00edsticas de amplias dimensiones, multinivel y efectos integrales multiobjetivo, que tienen ventajas \u00fanicas en el tratamiento antitumoral. Por lo tanto, la exploraci\u00f3n de ingredientes eficaces contra el glioma a partir de productos activos naturales y de la medicina tradicional china puede ser una forma eficaz de resolver el dilema actual.<\/p>\n<p>El ERD, como flavonoide natural, ha atra\u00eddo la atenci\u00f3n y la investigaci\u00f3n debido a su amplia gama de actividades biol\u00f3gicas. En el pasado, la investigaci\u00f3n sobre el ERD se centraba principalmente en los efectos antiinflamatorios y antioxidantes, pero nuestro estudio reciente descubri\u00f3 que el resveratrol puede inhibir significativamente la met\u00e1stasis de las c\u00e9lulas de glioma e inducir su apoptosis. Adem\u00e1s, el estudio de Tang et al. demostr\u00f3 que en las c\u00e9lulas del carcinoma nasofar\u00edngeo CNE1, la ERD inhib\u00eda significativamente la proliferaci\u00f3n celular a trav\u00e9s de la mediaci\u00f3n de la autofagia. Wang et al. descubrieron que la ERD desempe\u00f1a un papel protector en la lesi\u00f3n por isquemia-reperfusi\u00f3n cerebral en ratas mediante la regulaci\u00f3n de la autofagia. Los resultados de las investigaciones anteriores sugieren que la ERD tiene un efecto regulador sobre la autofagia celular y puede ejercer efectos anticancer\u00edgenos al afectar a la autofagia.<\/p>\n<p>Este estudio investig\u00f3 el efecto de la ERD sobre la autofagia en gliomas. En primer lugar, confirmamos mediante el reactivo CCK-8 y experimentos de formaci\u00f3n de clones que la ERD tiene un buen efecto inhibidor sobre las c\u00e9lulas de glioma, lo que concuerda con los resultados de nuestras investigaciones anteriores. A continuaci\u00f3n, para investigar si la ERD tiene un efecto sobre la autofagia en los gliomas, medimos los niveles de expresi\u00f3n de las prote\u00ednas relacionadas con la autofagia LC3, Beclin 1 y ATG5, y observamos el n\u00famero de autofagosomas mediante fluorescencia. Los resultados mostraron que la expresi\u00f3n de LC3B, Beclin 1, y ATG5 se increment\u00f3 significativamente en las c\u00e9lulas de glioma tratadas con ERD, y el n\u00famero de autofagosomas tambi\u00e9n se increment\u00f3 significativamente. La ERD induce la autofagia en c\u00e9lulas de glioma. La autofagia es un proceso din\u00e1mico que incluye tres estados: autofagosomas, autofagosomas y autolisosomas. Cuando las c\u00e9lulas experimentan autofagia, primero se forman los autofagosomas, que luego se fusionan con los lisosomas para formar los autolisosomas, y posteriormente degradan las prote\u00ednas y otras sustancias encerradas en ellos. Transfectamos la l\u00ednea celular con el pl\u00e1smido fluorescente dual GFP-mRFP-LC3B para construir c\u00e9lulas estables que expresaran la prote\u00edna fluorescente verde roja. Observamos el flujo de autofagia utilizando la caracter\u00edstica de reducci\u00f3n de la intensidad de fluorescencia de la prote\u00edna fluorescente GFP en condiciones de pH bajo. Cuando los autofagosomas se fusionan con los lisosomas para formar autolisosomas, el valor del pH en el interior de las ves\u00edculas disminuye y, tras la combinaci\u00f3n de fluorescencia roja y verde, las c\u00e9lulas muestran una fluorescencia rojiza. De lo contrario, tienden a volverse amarillas. Los resultados mostraron que, tras el tratamiento con ERD, las c\u00e9lulas de glioma mostraban una fluorescencia amarilla brillante y una mayor expresi\u00f3n de la prote\u00edna P62, que es un sustrato de los autofagosomas. Sin embargo, cuando la ERD se trat\u00f3 conjuntamente con el inductor de la autofagia RAP, el efecto de la ERD se invirti\u00f3 parcialmente. Los resultados experimentales anteriores sugieren que la ERD promueve la formaci\u00f3n de autofagosomas en las c\u00e9lulas de glioma, pero inhibe el flujo autof\u00e1gico.<\/p>\n<p>La v\u00eda de se\u00f1alizaci\u00f3n Akt\/mTOR desempe\u00f1a un papel regulador crucial en la autofagia celular y es una diana potencial para la terapia de tumores. Por lo tanto, para investigar m\u00e1s a fondo el mecanismo potencial de la ERD que afecta a la autofagia en c\u00e9lulas de glioma, examinamos el efecto de la ERD sobre la expresi\u00f3n de prote\u00ednas relacionadas con la v\u00eda Akt\/mTOR. Los resultados mostraron que la ERD pod\u00eda inhibir la expresi\u00f3n de p-Ak y p-mTOR, y este efecto fue parcialmente revertido por el agonista de Akt 740 Y-P. Esto sugiere que la ERD puede afectar al proceso de autofagia de las c\u00e9lulas de glioma mediante la regulaci\u00f3n a la baja de la v\u00eda Akt\/mTOR. Por \u00faltimo, observamos el efecto de la ERD sobre la autofagia del glioma in vivo utilizando un modelo tumoral de transplante subcut\u00e1neo en rat\u00f3n desnudo, y los resultados experimentales fueron coherentes con los obtenidos in vitro e in vivo.<\/p>\n<p>En resumen, este estudio explor\u00f3 preliminarmente el efecto de la ERD sobre la autofagia en c\u00e9lulas de glioma. Se descubri\u00f3 que la ERD puede inhibir parcialmente la v\u00eda Akt\/mTOR, regular la expresi\u00f3n de las prote\u00ednas relacionadas con la autofagia ATG5, Beclin1, LC3 y P62, afectar al proceso de autofagia de las c\u00e9lulas de glioma, inhibiendo as\u00ed la proliferaci\u00f3n de c\u00e9lulas de glioma y, en \u00faltima instancia, ejerciendo efectos antiglioma. Sin embargo, el mecanismo molecular por el que la ERD regula el flujo autof\u00e1gico no se ha dilucidado completamente en este estudio, lo que requiere m\u00e1s investigaci\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>The effect of Shengcao phenol regulating the Akt\/mTOR pathway on autophagy in glioma cells. Glioblastoma multimodal (GBM) is the most common malignant tumor in the central nervous system, with high malignancy and invasiveness. Even after comprehensive treatment with surgery, radiotherapy, and chemotherapy, it still faces the risk of recurrence and metastasis. Temozolomide (TMZ) is a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>The effect of Shengcao phenol regulating Akt\/mTOR pathway on autophagy in glioma cells - China Chemical Manufacturer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/longchangextracts.com\/es\/shengcao-phenol\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The effect of Shengcao phenol regulating Akt\/mTOR pathway on autophagy in glioma cells - China Chemical Manufacturer\" \/>\n<meta property=\"og:description\" content=\"The effect of Shengcao phenol regulating the Akt\/mTOR pathway on autophagy in glioma cells. Glioblastoma multimodal (GBM) is the most common malignant tumor in the central nervous system, with high malignancy and invasiveness. Even after comprehensive treatment with surgery, radiotherapy, and chemotherapy, it still faces the risk of recurrence and metastasis. Temozolomide (TMZ) is a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/longchangextracts.com\/es\/shengcao-phenol\/\" \/>\n<meta property=\"og:site_name\" content=\"China Chemical Manufacturer\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-11T17:52:52+00:00\" \/>\n<meta name=\"author\" content=\"Longchang Chemical\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Longchang Chemical\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/longchangextracts.com\/shengcao-phenol\/\",\"url\":\"https:\/\/longchangextracts.com\/shengcao-phenol\/\",\"name\":\"The effect of Shengcao phenol regulating Akt\/mTOR pathway on autophagy in glioma cells - China Chemical Manufacturer\",\"isPartOf\":{\"@id\":\"https:\/\/longchangextracts.com\/#website\"},\"datePublished\":\"2024-08-11T17:52:52+00:00\",\"dateModified\":\"2024-08-11T17:52:52+00:00\",\"author\":{\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\"},\"breadcrumb\":{\"@id\":\"https:\/\/longchangextracts.com\/shengcao-phenol\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/longchangextracts.com\/shengcao-phenol\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/longchangextracts.com\/shengcao-phenol\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/longchangextracts.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The effect of Shengcao phenol regulating Akt\/mTOR pathway on autophagy in glioma cells\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/longchangextracts.com\/#website\",\"url\":\"https:\/\/longchangextracts.com\/\",\"name\":\"China Chemical Manufacturer\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/longchangextracts.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\",\"name\":\"Longchang Chemical\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"caption\":\"Longchang Chemical\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El efecto de Shengcao fenol regulaci\u00f3n de la v\u00eda Akt\/mTOR en la autofagia en c\u00e9lulas de glioma - China Fabricante de Productos Qu\u00edmicos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/longchangextracts.com\/es\/shengcao-phenol\/","og_locale":"es_ES","og_type":"article","og_title":"The effect of Shengcao phenol regulating Akt\/mTOR pathway on autophagy in glioma cells - China Chemical Manufacturer","og_description":"The effect of Shengcao phenol regulating the Akt\/mTOR pathway on autophagy in glioma cells. Glioblastoma multimodal (GBM) is the most common malignant tumor in the central nervous system, with high malignancy and invasiveness. Even after comprehensive treatment with surgery, radiotherapy, and chemotherapy, it still faces the risk of recurrence and metastasis. Temozolomide (TMZ) is a [&hellip;]","og_url":"https:\/\/longchangextracts.com\/es\/shengcao-phenol\/","og_site_name":"China Chemical Manufacturer","article_published_time":"2024-08-11T17:52:52+00:00","author":"Longchang Chemical","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Longchang Chemical","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/longchangextracts.com\/shengcao-phenol\/","url":"https:\/\/longchangextracts.com\/shengcao-phenol\/","name":"El efecto de Shengcao fenol regulaci\u00f3n de la v\u00eda Akt\/mTOR en la autofagia en c\u00e9lulas de glioma - China Fabricante de Productos Qu\u00edmicos","isPartOf":{"@id":"https:\/\/longchangextracts.com\/#website"},"datePublished":"2024-08-11T17:52:52+00:00","dateModified":"2024-08-11T17:52:52+00:00","author":{"@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869"},"breadcrumb":{"@id":"https:\/\/longchangextracts.com\/shengcao-phenol\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/longchangextracts.com\/shengcao-phenol\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/longchangextracts.com\/shengcao-phenol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/longchangextracts.com\/"},{"@type":"ListItem","position":2,"name":"The effect of Shengcao phenol regulating Akt\/mTOR pathway on autophagy in glioma cells"}]},{"@type":"WebSite","@id":"https:\/\/longchangextracts.com\/#website","url":"https:\/\/longchangextracts.com\/","name":"China Fabricante de productos qu\u00edmicos","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/longchangextracts.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869","name":"Longchang Chemical","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","caption":"Longchang Chemical"}}]}},"_links":{"self":[{"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/posts\/8025"}],"collection":[{"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/comments?post=8025"}],"version-history":[{"count":1,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/posts\/8025\/revisions"}],"predecessor-version":[{"id":8026,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/posts\/8025\/revisions\/8026"}],"wp:attachment":[{"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/media?parent=8025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/categories?post=8025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/tags?post=8025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}