{"id":8017,"date":"2024-08-11T17:47:22","date_gmt":"2024-08-11T17:47:22","guid":{"rendered":"https:\/\/longchangextracts.com\/?p=8017"},"modified":"2024-08-11T17:47:22","modified_gmt":"2024-08-11T17:47:22","slug":"white-bauhinia-flower","status":"publish","type":"post","link":"https:\/\/longchangextracts.com\/es\/white-bauhinia-flower\/","title":{"rendered":"Estudio sobre la composici\u00f3n qu\u00edmica y la actividad inhibidora de la lipasa pancre\u00e1tica de la flor de bauhinia blanca"},"content":{"rendered":"<p>Investigaci\u00f3n sobre la composici\u00f3n qu\u00edmica y la actividad inhibidora de la lipasa pancre\u00e1tica de la flor de Bauhinia blanca del g\u00e9nero Leguminosae Existen unas 600 especies de plantas Bauhinia de la familia Leguminosae, distribuidas en regiones tropicales de todo el mundo. En China, hay 40 especies, 4 subespecies y 11 variedades, producidas principalmente en las regiones meridional y suroccidental. Por su elegante copa y sus grandes y fragantes flores, tiene un gran valor ornamental y es f\u00e1cil de cultivar. Suele cultivarse en jardines y bordes de caminos para contemplarla y es una buena planta ornamental. Como medicina tradicional china, las plantas de Zanthoxylum se utilizan ampliamente para tratar la diabetes, como antibacteriano y antiinflamatorio, analgesia, hemostasis y diuresis. Bauhinia variegata var. candida es una variante de Bauhinia variegata L., un \u00e1rbol caducifolio perteneciente a la familia de las Fabaceae. Sus flores tienen un sabor amargo, astringente y plano, y pueden utilizarse como medicina para tratar la indigesti\u00f3n, la tos por el calor del viento y la hepatitis. Debido a sus hermosas y densas flores, as\u00ed como a su fragante aroma, se utilizan com\u00fanmente en la medicina popular para recubrir la harina para fre\u00edr o como caldo de verduras. Sin embargo, no existen informes sobre la composici\u00f3n qu\u00edmica y la farmacolog\u00eda comestible de la flor blanca de Bauhinia. Con el fin de comprender plenamente la base material de la flor blanca de Bauhinia y proporcionar una base cient\u00edfica para su comestibilidad, este estudio aisl\u00f3 y purific\u00f3 sistem\u00e1ticamente el extracto etan\u00f3lico de la flor blanca de Bauhinia. Los compuestos identificados eran principalmente flavonoides, de los que se hab\u00eda informado en la literatura que ten\u00edan una buena actividad inhibidora de la lipasa pancre\u00e1tica. Por lo tanto, se estudi\u00f3 la actividad inhibidora de la lipasa pancre\u00e1tica de los compuestos aislados para proporcionar una base cient\u00edfica para el desarrollo, la utilizaci\u00f3n y el descubrimiento de nuevos usos de esta planta.<\/p>\n<p>&nbsp;<\/p>\n<p>Los principales componentes de 17 compuestos aislados de la flor blanca de Bauhinia son flavonoides, y se ha informado de que la mayor\u00eda de ellos tienen ciertas actividades biol\u00f3gicas, principalmente centradas en la protecci\u00f3n antioxidante, antiinflamatoria, cardiovascular y la regulaci\u00f3n de la glucosa en sangre. Por ejemplo, el compuesto gluc\u00f3sido \u03b2 - D-metilgluc\u00f3sido (1) tiene el efecto de aumentar la contractilidad mioc\u00e1rdica, mejorar la distensibilidad mioc\u00e1rdica y la funci\u00f3n sist\u00f3lica del ventr\u00edculo izquierdo, aumentar el gasto card\u00edaco y elevar la presi\u00f3n arterial en gatos con insuficiencia card\u00edaca experimental inducida por pentobarbital s\u00f3dico. El \u00e1cido p-cum\u00e1rico (4) tiene efectos antioxidantes, antiinflamatorios, de regulaci\u00f3n inmunitaria, antitumorales, antiagregantes plaquetarios, de protecci\u00f3n cardiovascular, de prevenci\u00f3n y mejora de la diabetes y neuroprotectores. Los flavonoides como la naringenina (7), el kaempferol (9), la quercetina (14), la 3-O-metil quercetina (15) y la quercetina-3-O - \u03b1 - L-rhamnopiranosil - (1 \u2192 6) - \u03b2 - D-glucopiran\u00f3sido (16) tienen una amplia gama de actividades farmacol\u00f3gicas, como antioxidante, antiinflamatoria, antitumoral, antiinfecciosa, de protecci\u00f3n cardiovascular y de regulaci\u00f3n de la glucemia. Kaempferol-3-O-rhamnoside (11) tiene una buena actividad anti Helicobacter pylori y puede reducir la CMI de la ampicilina contra Helicobacter pylori, proporcionando una base te\u00f3rica para el uso popular de la flor blanca de Bauhinia como medicina. La lipasa pancre\u00e1tica participa principalmente en la descomposici\u00f3n y el metabolismo de los l\u00edpidos, promoviendo la digesti\u00f3n de triglic\u00e9ridos, colesterol, fosfol\u00edpidos, etc. en el duodeno, lo que permite que la grasa de la dieta se digiera y absorba completamente, tratando as\u00ed enfermedades metab\u00f3licas como la obesidad. Los compuestos 10, 12, 13, 14 y 17 aislados en grandes cantidades fueron sometidos a un cribado para determinar su actividad inhibidora sobre la lipasa pancre\u00e1tica en cerdos, y los resultados mostraron que tienen cierta actividad inhibidora, pero su actividad inhibidora es m\u00e1s d\u00e9bil en comparaci\u00f3n con el f\u00e1rmaco positivo orlistat. Sin embargo, la flor blanca de Bauhinia contiene muchos flavonoides, que tienen un gran valor potencial en el desarrollo de productos para la salud, como antioxidantes y antienvejecimiento.<\/p>","protected":false},"excerpt":{"rendered":"<p>Research on the Chemical Composition and Pancreatic Lipase Inhibition Activity of the White Bauhinia Flower in the Leguminosae Genus There are about 600 species of Bauhinia plants in the Leguminosae family, distributed in tropical regions around the world. In China, there are 40 species, 4 subspecies, and 11 varieties, mainly produced in the southern and [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Study on the Chemical Composition and Pancreatic Lipase Inhibition Activity of White Bauhinia Flower - China Chemical Manufacturer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/longchangextracts.com\/es\/white-bauhinia-flower\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Study on the Chemical Composition and Pancreatic Lipase Inhibition Activity of White Bauhinia Flower - China Chemical Manufacturer\" \/>\n<meta property=\"og:description\" content=\"Research on the Chemical Composition and Pancreatic Lipase Inhibition Activity of the White Bauhinia Flower in the Leguminosae Genus There are about 600 species of Bauhinia plants in the Leguminosae family, distributed in tropical regions around the world. In China, there are 40 species, 4 subspecies, and 11 varieties, mainly produced in the southern and [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/longchangextracts.com\/es\/white-bauhinia-flower\/\" \/>\n<meta property=\"og:site_name\" content=\"China Chemical Manufacturer\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-11T17:47:22+00:00\" \/>\n<meta name=\"author\" content=\"Longchang Chemical\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Longchang Chemical\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/longchangextracts.com\/white-bauhinia-flower\/\",\"url\":\"https:\/\/longchangextracts.com\/white-bauhinia-flower\/\",\"name\":\"Study on the Chemical Composition and Pancreatic Lipase Inhibition Activity of White Bauhinia Flower - China Chemical Manufacturer\",\"isPartOf\":{\"@id\":\"https:\/\/longchangextracts.com\/#website\"},\"datePublished\":\"2024-08-11T17:47:22+00:00\",\"dateModified\":\"2024-08-11T17:47:22+00:00\",\"author\":{\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\"},\"breadcrumb\":{\"@id\":\"https:\/\/longchangextracts.com\/white-bauhinia-flower\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/longchangextracts.com\/white-bauhinia-flower\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/longchangextracts.com\/white-bauhinia-flower\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/longchangextracts.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Study on the Chemical Composition and Pancreatic Lipase Inhibition Activity of White Bauhinia Flower\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/longchangextracts.com\/#website\",\"url\":\"https:\/\/longchangextracts.com\/\",\"name\":\"China Chemical Manufacturer\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/longchangextracts.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\",\"name\":\"Longchang Chemical\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"caption\":\"Longchang Chemical\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudio sobre la composici\u00f3n qu\u00edmica y la actividad inhibidora de la lipasa pancre\u00e1tica de la flor de bauhinia blanca - China Fabricante de Productos Qu\u00edmicos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/longchangextracts.com\/es\/white-bauhinia-flower\/","og_locale":"es_ES","og_type":"article","og_title":"Study on the Chemical Composition and Pancreatic Lipase Inhibition Activity of White Bauhinia Flower - China Chemical Manufacturer","og_description":"Research on the Chemical Composition and Pancreatic Lipase Inhibition Activity of the White Bauhinia Flower in the Leguminosae Genus There are about 600 species of Bauhinia plants in the Leguminosae family, distributed in tropical regions around the world. In China, there are 40 species, 4 subspecies, and 11 varieties, mainly produced in the southern and [&hellip;]","og_url":"https:\/\/longchangextracts.com\/es\/white-bauhinia-flower\/","og_site_name":"China Chemical Manufacturer","article_published_time":"2024-08-11T17:47:22+00:00","author":"Longchang Chemical","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Longchang Chemical","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/longchangextracts.com\/white-bauhinia-flower\/","url":"https:\/\/longchangextracts.com\/white-bauhinia-flower\/","name":"Estudio sobre la composici\u00f3n qu\u00edmica y la actividad inhibidora de la lipasa pancre\u00e1tica de la flor de bauhinia blanca - China Fabricante de Productos Qu\u00edmicos","isPartOf":{"@id":"https:\/\/longchangextracts.com\/#website"},"datePublished":"2024-08-11T17:47:22+00:00","dateModified":"2024-08-11T17:47:22+00:00","author":{"@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869"},"breadcrumb":{"@id":"https:\/\/longchangextracts.com\/white-bauhinia-flower\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/longchangextracts.com\/white-bauhinia-flower\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/longchangextracts.com\/white-bauhinia-flower\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/longchangextracts.com\/"},{"@type":"ListItem","position":2,"name":"Study on the Chemical Composition and Pancreatic Lipase Inhibition Activity of White Bauhinia Flower"}]},{"@type":"WebSite","@id":"https:\/\/longchangextracts.com\/#website","url":"https:\/\/longchangextracts.com\/","name":"China Fabricante de productos qu\u00edmicos","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/longchangextracts.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869","name":"Longchang Chemical","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","caption":"Longchang Chemical"}}]}},"_links":{"self":[{"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/posts\/8017"}],"collection":[{"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/comments?post=8017"}],"version-history":[{"count":1,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/posts\/8017\/revisions"}],"predecessor-version":[{"id":8018,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/posts\/8017\/revisions\/8018"}],"wp:attachment":[{"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/media?parent=8017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/categories?post=8017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/tags?post=8017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}