{"id":7832,"date":"2024-08-08T16:01:52","date_gmt":"2024-08-08T16:01:52","guid":{"rendered":"https:\/\/longchangextracts.com\/?p=7832"},"modified":"2024-08-08T16:01:52","modified_gmt":"2024-08-08T16:01:52","slug":"oil-decoloration","status":"publish","type":"post","link":"https:\/\/longchangextracts.com\/es\/decoloracion-del-aceite\/","title":{"rendered":"\u00bfQu\u00e9 es la decoloraci\u00f3n del aceite?"},"content":{"rendered":"<p>La decoloraci\u00f3n es un proceso de lavado, as\u00ed que \u00bfcu\u00e1les son las impurezas que espera eliminar y en qu\u00e9 medida? Se describe de la siguiente manera:<\/p>\n<p><strong>Productos de oxidaci\u00f3n del aceite y la grasa<\/strong><\/p>\n<p>El proceso de decoloraci\u00f3n por adsorci\u00f3n pretende eliminar por completo los productos de oxidaci\u00f3n de grasas y aceites, incluida la oxidaci\u00f3n autom\u00e1tica de grasas y aceites, la oxidaci\u00f3n enzim\u00e1tica de productos de oxidaci\u00f3n primaria (hidroper\u00f3xidos) y su descomposici\u00f3n de la formaci\u00f3n de productos de oxidaci\u00f3n secundaria, as\u00ed como tocoferoles, esteroles, pigmentos y otros productos de oxidaci\u00f3n lip\u00eddica. Estas sustancias existen en el aceite que se va a decolorar y, si no se pueden eliminar, la estabilidad del aceite se ver\u00e1 seriamente afectada.<\/p>\n<p>Productos de oxidaci\u00f3n por lo general tienen una cierta polaridad, puede ser adsorbido eficazmente por la arcilla blanca y eliminado, al mismo tiempo, la activaci\u00f3n de la arcilla blanca puede ser hidroper\u00f3xidos y compuestos epoxi, tales como la degradaci\u00f3n en aldeh\u00eddos vol\u00e1tiles y cetonas, lo que garantiza que estos compuestos en el siguiente paso del proceso de desodorizaci\u00f3n para eliminar de manera eficiente. Esta es la primera tarea de decoloraci\u00f3n.<\/p>\n<p><strong>Metales traza<\/strong><\/p>\n<p>Los metales traza, como el hierro y el cobre, est\u00e1n presentes de forma natural en las semillas oleaginosas, ya sea procedentes de la plantaci\u00f3n o de las instalaciones de procesado del aceite; estos metales traza deben eliminarse en la mayor medida posible mediante adsorci\u00f3n antes de la desodorizaci\u00f3n para garantizar la estabilidad y la calidad de los aceites desodorizados. Especialmente en el caso de la decoloraci\u00f3n posterior de aceites hidrogenados, el objetivo principal es eliminar las trazas de metales catalizadores.<\/p>\n<p><strong>Jab\u00f3n<\/strong><\/p>\n<p>La decoloraci\u00f3n por adsorci\u00f3n es la mejor forma de eliminar las trazas de jab\u00f3n. Aunque la mayor parte del jab\u00f3n de sodio soluble en agua se puede eliminar mediante el lavado con agua del aceite de refinado alcalino, todav\u00eda existe una peque\u00f1a cantidad de jab\u00f3n met\u00e1lico insoluble en agua, como el jab\u00f3n de calcio\/magnesio, etc. en el aceite. Los fosfol\u00edpidos tambi\u00e9n pueden hidrolizarse parcialmente en el proceso de refinado alcalino para hacer que el residuo de jab\u00f3n de calcio\/magnesio del aceite de refinado alcalino aumente. Estas sustancias deben decolorarse para maximizar su eliminaci\u00f3n.<\/p>\n<p><strong>Fosfol\u00edpidos y glicol\u00edpidos residuales<\/strong><\/p>\n<p>El aceite de soja, el aceite de colza, el aceite de girasol, el aceite de cacahuete y el aceite de algod\u00f3n tienen un alto contenido en fosfol\u00edpidos, el aceite de palma, el aceite de palmiste y el aceite de coco tienen un bajo contenido en fosfol\u00edpidos pero contienen una cierta cantidad de glicol\u00edpidos, y la mayor\u00eda de los aceites y grasas seguir\u00e1n dejando una peque\u00f1a cantidad de fosfol\u00edpidos o glicol\u00edpidos tras el desgomado.<\/p>\n<p>Recientemente, la investigaci\u00f3n del aceite de salvado de arroz descubri\u00f3 que hay un tipo especial de glicol\u00edpidos en el aceite - glicol\u00edpidos que contienen f\u00f3sforo, que son casi imposibles de eliminar por los m\u00e9todos tradicionales de desgomado, pero pueden ser eliminados al m\u00e1ximo por adsorbentes adecuados.<\/p>\n<p><strong>Hidrocarburos arom\u00e1ticos polic\u00edclicos y residuos de plaguicidas<\/strong><\/p>\n<p>Los contaminantes ambientales del petr\u00f3leo incluyen principalmente residuos de pesticidas y HAP, y la adsorci\u00f3n y decoloraci\u00f3n tambi\u00e9n pueden eliminarlos sustancialmente.<\/p>\n<p>Los residuos de plaguicidas proceden principalmente de los plaguicidas aplicados durante el crecimiento de los cultivos oleaginosos y del suelo y el agua contaminados, los plaguicidas que contienen f\u00f3sforo y nitr\u00f3geno son absorbidos por el petr\u00f3leo tras su biodegradaci\u00f3n, y entran en el petr\u00f3leo por la producci\u00f3n de petr\u00f3leo, y pueden eliminarse por adsorci\u00f3n de arcilla blanca en el proceso de decoloraci\u00f3n; los plaguicidas organoclorados son dif\u00edciles de biodegradar, y tienen un largo periodo de contaminaci\u00f3n del suelo y el agua, y aunque el uso de estos plaguicidas se ha prohibido en muchos pa\u00edses, el medio ambiente sigue contaminado, y ser\u00e1 dif\u00edcil utilizar la adsorci\u00f3n para eliminarlos una vez que entren en el petr\u00f3leo. Una vez en el aceite es dif\u00edcil de eliminar por adsorci\u00f3n, s\u00f3lo se puede eliminar en la desodorizaci\u00f3n.<\/p>\n<p>Los hidrocarburos arom\u00e1ticos polic\u00edclicos proceden principalmente del proceso de combusti\u00f3n de contaminantes, como el aceite de secado de gases de combusti\u00f3n, que aumentar\u00e1 el contenido de hidrocarburos arom\u00e1ticos polic\u00edclicos en el aceite, en particular en el aceite de coco. En general, la arcilla blanca no puede adsorber los HAP no polares, pero el carb\u00f3n activado puede adsorber los HAP pesados con m\u00e1s de 4 anillos, y los HAP ligeros restantes pueden eliminarse durante la desodorizaci\u00f3n.<\/p>\n<p><strong>Pigmentaci\u00f3n<\/strong><\/p>\n<p>La eliminaci\u00f3n parcial del color (decoloraci\u00f3n) es, por supuesto, uno de los objetivos de la decoloraci\u00f3n de grasas y aceites.<\/p>\n<p>Los pigmentos de los aceites y grasas pueden dividirse en pigmentos primarios y pigmentos reci\u00e9n nacidos.<\/p>\n<p>Los primeros son los carotenoides y la clorofila en su estado natural, as\u00ed como el fenol algodonoso del aceite de semilla de algod\u00f3n. Las clorofilas se eliminan principalmente mediante el proceso de decoloraci\u00f3n, y las clorofilas son un tipo de pigmento natural que esperamos eliminar al m\u00e1ximo durante el proceso de decoloraci\u00f3n. Los carotenoides son sensibles al calor y pueden eliminarse eficazmente mediante craqueo t\u00e9rmico durante la desodorizaci\u00f3n. La arcilla blanca no adsorbe el algod\u00f3n-fenol, pero el algod\u00f3n-fenol es \u00e1cido, puede eliminarse por neutralizaci\u00f3n en el refinado alcalino.<\/p>\n<p>Estos \u00faltimos son los productos de descomposici\u00f3n oxidativa de pigmentos primarios o sus productos de reacci\u00f3n con otros l\u00edpidos, que son pigmentos reci\u00e9n nacidos en el proceso. Pigmento reci\u00e9n nacido est\u00e1 en el proceso de decoloraci\u00f3n esperanza completamente eliminado, pero m\u00e1s dif\u00edcil.<\/p>\n<p>La eliminaci\u00f3n de pigmento en el aceite no depende totalmente del proceso de decoloraci\u00f3n, la eliminaci\u00f3n de pigmento en el aceite, a lo largo del proceso de refinado, desgomado, refinado alcalino, refinado \u00e1cido, proceso de desodorizaci\u00f3n tienen el efecto de eliminar el pigmento, se acompa\u00f1an de una reducci\u00f3n en el color del aceite y la grasa, lo que reduce relativamente la necesidad de eliminar un gran n\u00famero de pigmentos de la secci\u00f3n de decoloraci\u00f3n. De hecho, para el aceite de palma y el aceite de soja, el proceso de decoloraci\u00f3n no juega un papel importante en la mejora del color del aceite.<\/p>\n<p>En resumen, el prop\u00f3sito de decoloraci\u00f3n, es hacer que el aceite decolorado en la mejora del color, no te\u00f3ricamente eliminar todos los pigmentos en el aceite, e incluso a veces el objetivo principal no es eliminar el pigmento, pero para reducir los productos de oxidaci\u00f3n en el aceite, f\u00f3sforo residual, jab\u00f3n residual y metales traza, residuos agr\u00edcolas y otras impurezas, mejorando as\u00ed el sabor y la estabilidad a la oxidaci\u00f3n del aceite para mejorar el papel del aceite para el siguiente paso del proceso de desodorizaci\u00f3n para proporcionar aceite de materia prima calificada. Por lo tanto, el proceso de decoloraci\u00f3n no se puede omitir, incluso si el color bruto del aceite es muy ligero. De lo contrario, el sabor del aceite totalmente refinado es f\u00e1cil de deteriorar.<\/p>\n<p>En t\u00e9rminos de seguridad del aceite comestible, el color es peque\u00f1o, el sabor (estabilidad) es grande, por lo que la tarea del proceso de decoloraci\u00f3n es: eliminar asuntos varios, y la eliminaci\u00f3n del pigmento puede ser moderada.<\/p>","protected":false},"excerpt":{"rendered":"<p>Decolorization is a washing process, so what are the impurities it hopes to remove and to what extent? It is described as follows: Oxidation products of oil and grease Adsorption decolorization process hopes to completely remove the oxidation products of fats and oils, including automatic oxidation of fats and oils, enzyme oxidation of primary oxidation [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>What is oil decoloration? - China Chemical Manufacturer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/longchangextracts.com\/es\/decoloracion-del-aceite\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"What is oil decoloration? - China Chemical Manufacturer\" \/>\n<meta property=\"og:description\" content=\"Decolorization is a washing process, so what are the impurities it hopes to remove and to what extent? It is described as follows: Oxidation products of oil and grease Adsorption decolorization process hopes to completely remove the oxidation products of fats and oils, including automatic oxidation of fats and oils, enzyme oxidation of primary oxidation [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/longchangextracts.com\/es\/decoloracion-del-aceite\/\" \/>\n<meta property=\"og:site_name\" content=\"China Chemical Manufacturer\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-08T16:01:52+00:00\" \/>\n<meta name=\"author\" content=\"Longchang Chemical\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Longchang Chemical\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/longchangextracts.com\/oil-decoloration\/\",\"url\":\"https:\/\/longchangextracts.com\/oil-decoloration\/\",\"name\":\"What is oil decoloration? - China Chemical Manufacturer\",\"isPartOf\":{\"@id\":\"https:\/\/longchangextracts.com\/#website\"},\"datePublished\":\"2024-08-08T16:01:52+00:00\",\"dateModified\":\"2024-08-08T16:01:52+00:00\",\"author\":{\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\"},\"breadcrumb\":{\"@id\":\"https:\/\/longchangextracts.com\/oil-decoloration\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/longchangextracts.com\/oil-decoloration\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/longchangextracts.com\/oil-decoloration\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/longchangextracts.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"What is oil decoloration?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/longchangextracts.com\/#website\",\"url\":\"https:\/\/longchangextracts.com\/\",\"name\":\"China Chemical Manufacturer\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/longchangextracts.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\",\"name\":\"Longchang Chemical\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"caption\":\"Longchang Chemical\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 es la decoloraci\u00f3n del aceite? - China Fabricante de productos qu\u00edmicos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/longchangextracts.com\/es\/decoloracion-del-aceite\/","og_locale":"es_ES","og_type":"article","og_title":"What is oil decoloration? - China Chemical Manufacturer","og_description":"Decolorization is a washing process, so what are the impurities it hopes to remove and to what extent? It is described as follows: Oxidation products of oil and grease Adsorption decolorization process hopes to completely remove the oxidation products of fats and oils, including automatic oxidation of fats and oils, enzyme oxidation of primary oxidation [&hellip;]","og_url":"https:\/\/longchangextracts.com\/es\/decoloracion-del-aceite\/","og_site_name":"China Chemical Manufacturer","article_published_time":"2024-08-08T16:01:52+00:00","author":"Longchang Chemical","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Longchang Chemical","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/longchangextracts.com\/oil-decoloration\/","url":"https:\/\/longchangextracts.com\/oil-decoloration\/","name":"\u00bfQu\u00e9 es la decoloraci\u00f3n del aceite? - China Fabricante de productos qu\u00edmicos","isPartOf":{"@id":"https:\/\/longchangextracts.com\/#website"},"datePublished":"2024-08-08T16:01:52+00:00","dateModified":"2024-08-08T16:01:52+00:00","author":{"@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869"},"breadcrumb":{"@id":"https:\/\/longchangextracts.com\/oil-decoloration\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/longchangextracts.com\/oil-decoloration\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/longchangextracts.com\/oil-decoloration\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/longchangextracts.com\/"},{"@type":"ListItem","position":2,"name":"What is oil decoloration?"}]},{"@type":"WebSite","@id":"https:\/\/longchangextracts.com\/#website","url":"https:\/\/longchangextracts.com\/","name":"China Fabricante de productos qu\u00edmicos","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/longchangextracts.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869","name":"Longchang Chemical","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","caption":"Longchang Chemical"}}]}},"_links":{"self":[{"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/posts\/7832"}],"collection":[{"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/comments?post=7832"}],"version-history":[{"count":1,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/posts\/7832\/revisions"}],"predecessor-version":[{"id":7833,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/posts\/7832\/revisions\/7833"}],"wp:attachment":[{"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/media?parent=7832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/categories?post=7832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/longchangextracts.com\/es\/wp-json\/wp\/v2\/tags?post=7832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}