{"id":8851,"date":"2024-08-15T08:11:18","date_gmt":"2024-08-15T08:11:18","guid":{"rendered":"https:\/\/longchangextracts.com\/?p=8851"},"modified":"2024-08-15T08:11:18","modified_gmt":"2024-08-15T08:11:18","slug":"medicinal-food","status":"publish","type":"post","link":"https:\/\/longchangextracts.com\/de\/heilnahrung\/","title":{"rendered":"Was sind medizinische Lebensmittel\uff1f?"},"content":{"rendered":"<p>Der genaue Ursprung und Zeitpunkt des Begriffs \"Medizin und Nahrung zusammen\", der eine moderne Zusammenfassung der Beziehung zwischen Medizin und Nahrung und deren Anwendungen darstellt, ist nicht klar. Aus der Literaturrecherche in den Datenbanken von China Knowledge, Wipo, Wanfang und National Library Reference and Consultation Union geht hervor, dass der Begriff erstmals in \"A Brief Discussion of Dietary Therapies for Tumor Patients\" (Eine kurze Diskussion \u00fcber Ern\u00e4hrungstherapien f\u00fcr Tumorpatienten) aus dem Jahr 1984 auftauchte.<\/p>\n<p>Seitdem das Konzept der Homologie von Arzneimitteln und Lebensmitteln zum ersten Mal vorgeschlagen wurde, hat die Forschung im Allgemeinen einen Aufw\u00e4rtstrend gezeigt und wurde in den letzten Jahren stark ausgebaut.<\/p>\n<p>Die Gr\u00fcnde daf\u00fcr sind zum einen, dass medizinische Lebensmittel der Marktnachfrage entsprechen. Die Alterung der Bev\u00f6lkerung, die Bedrohung durch ungesunde und chronische Krankheiten haben dazu gef\u00fchrt, dass \"Ern\u00e4hrung\" und \"Vorbeugung\" in den Mittelpunkt der t\u00e4glichen Gesundheitsf\u00fcrsorge des modernen Menschen ger\u00fcckt sind und die Menschen mehr und mehr dazu neigen, zur Natur zur\u00fcckzukehren und eine medizinische Behandlung und Gesundheitsf\u00fcrsorge im Einklang mit den Gesetzen der Natur zu suchen. Lebensmittel sind die beste Medizin, Lebensmittel statt Medikamente und andere Konzepte zur F\u00f6rderung funktioneller Lebensmittel haben sich zu einer beliebten Form der Ern\u00e4hrung entwickelt. Im Jahr 1987 ver\u00f6ffentlichten das damalige Gesundheitsministerium und die staatliche Verwaltung f\u00fcr traditionelle chinesische Medizin (TCM) gemeinsam die erste \"Liste von Sorten, die sowohl Lebensmittel als auch Arzneimittel sind\", die den Anwendungsbereich von medizinischen Lebensmitteln und medizinischen Lebensmitteln klarstellte und die Forschung \u00fcber medizinische Lebensmittel und medizinische Lebensmittel f\u00f6rderte.<\/p>\n<p><strong>Die Entwicklung von medizinischen Lebensmitteln und homologen Substanzen auf dem internationalen Markt<\/strong><\/p>\n<p>In den letzten Jahren hat sich die traditionelle chinesische Kultur mit dem Erstarken Chinas in der Welt verbreitet, und insbesondere die Wirksamkeit der Physiotherapie der chinesischen Medizin bei der Vorbeugung und Behandlung von Volkskrankheiten, Mehrfacherkrankungen, chronischen Krankheiten und schweren Krankheiten wird von der internationalen Gemeinschaft zunehmend anerkannt und akzeptiert. Gegenw\u00e4rtig ist die chinesische Medizin in fast 200 L\u00e4ndern und Regionen der Welt verbreitet, und der internationale Einfluss der chinesischen Medizin nimmt zu.<\/p>\n<p>In Japan gibt es eine \u00e4hnliche Theorie wie in China: \"Medizin und Nahrung sind dasselbe\". Die Japaner akzeptieren voll und ganz die Wirksamkeit der Ern\u00e4hrung, um die Gesundheit des K\u00f6rpers zu erhalten, und bef\u00fcrworten die Verschmelzung von chinesischer und westlicher Ern\u00e4hrungstherapie zur Gesundheitsvorsorge.<\/p>\n<p>Zu Beginn des 20. Jahrhunderts nahmen die Vereinigten Staaten pflanzliche Arzneimittel in ihr Arzneibuch auf, wobei sie \"sichere, wirksame und kontrollierte Mischungen\" zulie\u00dfen, d. h. sowohl einzelne Arzneimittel als auch Mischungen mehrerer Kr\u00e4uter anerkannten. Die Vereinigten Staaten sind der weltweit gr\u00f6\u00dfte Markt f\u00fcr Nahrungserg\u00e4nzungsmittel, und pflanzliche Arzneimittel nehmen eine gewisse Gr\u00f6\u00dfe ein. China ist der wichtigste Lieferant von Rohstoffen f\u00fcr chinesische Kr\u00e4uter.<\/p>\n<p>In Europa haben Deutschland, die Schweiz, das Vereinigte K\u00f6nigreich, Frankreich und andere L\u00e4nder gemeinsam die Europ\u00e4ische Phytotherapie-Allianz gegr\u00fcndet, die die Anerkennung und Entwicklung von pflanzlichen funktionellen Lebensmitteln in Europa f\u00f6rdert.<\/p>\n<p>Japan, S\u00fcdkorea, Singapur und andere s\u00fcdostasiatische Regionen haben mit China eine gemeinsame kulturelle Wahrnehmung des Konzepts der Gesundheitsf\u00fcrsorge mit Lebensmitteln und Medizin, und die Lebensmittel- und Medizinindustrie ist im Wesentlichen synchronisiert.<\/p>\n<p><strong>Sorten chinesischer Kr\u00e4uter mit der gleichen Quelle f\u00fcr Nahrung und Medizin<\/strong><\/p>\n<p>Die verschiedenen Arten von chinesischen pflanzlichen Arzneimitteln, die die gleiche Quelle f\u00fcr Medizin und Nahrungsmittel haben, werden in der Arzneimittelpraxis der Werkt\u00e4tigen zusammengefasst und vervollkommnet, was eine empirische Zusammenfassung darstellt. Mit der Entwicklung von Wissenschaft und Technik, insbesondere der Entwicklung der Medizintechnik, sind sich die Menschen mehr und mehr \u00fcber die Identifizierung der Wirkstoffe chinesischer pflanzlicher Arzneimittel im Klaren und k\u00f6nnen eindeutig bestimmen, welche Bestandteile chinesischer pflanzlicher Arzneimittel f\u00fcr Nahrungserg\u00e4nzungsmittel verwendet werden k\u00f6nnen und welche Nebenwirkungen haben. Daher m\u00fcssen medizinische Lebensmittel mit chinesischen Kr\u00e4utersorten von den nationalen Beh\u00f6rden anerkannt werden.<br \/>\n<strong>1. Liste der Gegenst\u00e4nde, die nach der Tradition sowohl Lebensmittel als auch chinesische Kr\u00e4uter sind (Medizin und Lebensmittel mit Ursprung)<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-8852\" src=\"https:\/\/longchangextracts.com\/wp-content\/uploads\/2024\/08\/1-355-650x255.png\" alt=\"\" width=\"650\" height=\"255\" srcset=\"https:\/\/longchangextracts.com\/wp-content\/uploads\/2024\/08\/1-355-650x255.png 650w, https:\/\/longchangextracts.com\/wp-content\/uploads\/2024\/08\/1-355-18x7.png 18w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/p>\n<p>Hinweis: Rot gekennzeichnete Zutaten in der Verwendung als Gew\u00fcrze und W\u00fcrzmittel<\/p>\n<p><strong>2. Chinesische Kr\u00e4uter, die nur in gesunden Lebensmitteln verwendet werden d\u00fcrfen, wie von der Gesundheits- und Wohlfahrtskommission angek\u00fcndigt.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-8853\" src=\"https:\/\/longchangextracts.com\/wp-content\/uploads\/2024\/08\/2-296-650x370.png\" alt=\"\" width=\"650\" height=\"370\" \/><\/p>\n<p>Bemerkungen: Alle chinesischen pflanzlichen Arzneimittel, die nicht in der von der Gesundheitskommission ver\u00f6ffentlichten Liste der Arzneimittel und Lebensmittel mit doppeltem Verwendungszweck aufgef\u00fchrt sind, d\u00fcrfen nicht in Lebensmitteln verwendet werden. \u00c4ndert sich die Einstufung der rot markierten Artikel in den nachfolgenden Dokumenten, so sind die nachfolgenden Dokumente ma\u00dfgebend.<\/p>\n<p><strong>Aktueller Stand der Entwicklung medizinischer Lebensmittelprodukte<\/strong><\/p>\n<p>Medizinische Lebensmittel haben haupts\u00e4chlich die Funktionen, die Lebensenergie zu f\u00f6rdern und die Essenz zu st\u00e4rken, den K\u00f6rper zu erleichtern und das Leben zu verl\u00e4ngern, das Herz zu n\u00e4hren und den Intellekt zu f\u00f6rdern, die Haut zu versch\u00f6nern und zu sch\u00fctzen, das Feuer zu lindern und den \u00c4rger zu beseitigen sowie den Appetit zu steigern und den Geschmack zu verbessern. Der derzeitige Markt f\u00fcr medizinische Lebensmittel umfasst vor allem folgende Produkte:<\/p>\n<p><strong>1, Ersatztee<\/strong><\/p>\n<p>Substitute Tee, bezieht sich auf die Verwendung einer chinesischen Kr\u00e4utermedizin oder mehrere Arten von chinesischen Kr\u00e4utermedizin und Tee und andere mischen und mischen, brauen oder kochen ein Getr\u00e4nk. Dies ist Chinas traditionelle medizinische Produkte. Teeersatz hat die Wirkung, die Lebensenergie zu f\u00f6rdern und die Essenz zu tonisieren, das Herz zu n\u00e4hren und \u00c4rger zu beseitigen. Auf dem heutigen Markt gibt es jedoch Hunderte von Sorten. Fisch und Drachen sind gemischt, die Qualit\u00e4t ist unterschiedlich. Einige Ersatzteebeutel verwenden sogar die R\u00e4nder chinesischer Kr\u00e4uter als Zutaten, und einige chinesische Kr\u00e4uter m\u00fcssen vor dem Aufbr\u00fchen zusammenger\u00fchrt werden, aber um die Gesch\u00e4ftskosten zu senken, gibt es kein Zusammenr\u00fchren. Daher spielt er nicht die erwartete Wirksamkeit des medizinischen Teeersatzes.<\/p>\n<p><strong>2. Funktionelle Getr\u00e4nke<\/strong><\/p>\n<p>Funktionelle Getr\u00e4nke, die aus der gleichen Quelle von Lebensmitteln und Arzneimitteln hergestellt werden, werden haupts\u00e4chlich aus einer oder mehreren Arten von chinesischen pflanzlichen Arzneimitteln hergestellt, und die Wirkstoffe werden durch Erhitzen, Pressen oder Extrahieren extrudiert, um sie zu direkten Getr\u00e4nken zu machen. Gegenw\u00e4rtig haben einige Hersteller auch feste medizinische Lebensmittelgetr\u00e4nke entwickelt. Die Extraktion von Inhaltsstoffen aus medizinischen Zutaten zur Herstellung von Getr\u00e4nken ist zu einer neuen Mode und einem Trend geworden, der bei jungen Leuten sehr beliebt ist.<\/p>\n<p><strong>3\u3001Snacks<\/strong><\/p>\n<p>Snacks, auch als Freizeitnahrung bekannt, werden von alten, mittelalten, jungen, gro\u00dfen und kleinen Menschen gerne gegessen, k\u00f6nnen in Flugzeugen genossen werden, B\u00fcroangestellte k\u00f6nnen auch als Mahlzeit verwendet werden, von Menschen aus allen Lebensbereichen weithin begr\u00fc\u00dft. Kr\u00e4utersnacks k\u00f6nnen als Mahlzeit, aber auch als besonderer N\u00e4hrstoff zur Verbesserung der K\u00f6rperfunktionen verwendet werden. Pflanzliche Snacks sind auf dem aktuellen Markt der einzelnen Arten h\u00e4ufiger, aber weniger synthetische Sorten.<\/p>\n<p><strong>4, Hautpflegeprodukte<\/strong><\/p>\n<p>Chinesische pflanzliche Hautpflege-Produkte und die aktuelle vor allem chemische Rohstoffe Hautpflege-Produkte im Vergleich zu dem Wesen aus der Pflanze in der feuchtigkeitsspendenden Wartung der Haut, Hautaufhellung, feuchtigkeitsspendende und Pflege muss einen gr\u00f6\u00dferen Vorteil haben.<\/p>\n<p><strong>5, medizinische Ern\u00e4hrung<\/strong><\/p>\n<p>Medizinische Ern\u00e4hrung ist ein feines Produkt, das den gleichen Ursprung wie Lebensmittel und Medizin hat, die Krone der traditionellen chinesischen Medizinindustrie, eine der hellsten Perlen, der gro\u00dfe Beitrag unseres Volkes zur Lebensmittel- und Getr\u00e4nkekultur. Die medizinische Ern\u00e4hrung steht unter der wissenschaftlichen Leitung der chinesischen Medizin, der kulinarischen Wissenschaft und der Ern\u00e4hrungstheorie, wobei der medizinische Wert der chinesischen Kr\u00e4utermedizin voll zur Geltung kommt, mit anderen Lebensmitteln abgestimmt wird und einzigartige Kochtechniken verwendet werden, um Lebensmittel mit spezifischer tonischer Wirkung herzustellen.<\/p>\n<p><strong>Forschung und Entwicklung von Lebensmittelarzneimitteln<\/strong><\/p>\n<p>1\u3001Nutzen Sie das traditionellste Konzept der Homologie von Lebensmitteln und Medizin in Kombination mit der fortschrittlichsten Kochtechnologie, Forschung und Entwicklung neuer Produkte der Homologie von Lebensmitteln und Medizin.<\/p>\n<p>Die Medizin der gleichen Quelle von Lebensmitteln und Medizin bezieht sich haupts\u00e4chlich auf chinesische pflanzliche Arzneimittel, und chinesische pflanzliche Arzneimittel sind die wichtigsten Rohstoffe der chinesischen Medizinindustrie. Die Leitideologie der gleichen Quelle von Lebensmitteln und Medizin muss das Konzept der traditionellen chinesischen Medizin fest verankern.<\/p>\n<p>2, die kontinuierliche Entwicklung der gleichen Quelle der Medizin und Lebensmittel, zur F\u00f6rderung der Bl\u00fcte der hundert Blumen, hundert Schulen des Denkens, medizinische Lebensmittel allein.<\/p>\n<p>Der Mensch steht im Mittelpunkt, das Grundbed\u00fcrfnis der Menschen ist Leben und Gesundheit, \"Nahrung f\u00fcr das Volk\", ein Wort, Nahrung ist das erste Bed\u00fcrfnis des Volkes. Nahrung ist das erste Bed\u00fcrfnis des Volkes. Die beste Nahrung ist die medizinische Nahrung. Medizinische Lebensmittel sind das Ziel der gesamten Kette der chinesischen Medizinindustrie, und sie sind das Ziel der gesamten Industrie. Die chinesische Medizinindustrie strebt nicht danach, wie gut die Medizin ist, sondern wie gut die Nahrung ist, Nahrung anstelle von Medizin, Nahrung zur Vorbeugung von Krankheiten, Konditionierung an erster Stelle, nach der Behandlung. Dies ist auch Sun Tzu's Kunst des Krieges \"ohne zu k\u00e4mpfen und nachgeben, das Gute der guten\", die Argumentation, die Krankheit nicht ausgebrochen ist, wurde vor der Konditionierung, unwissentlich die Beseitigung der im Keim ersticken, den kulturellen Kern der wie \u00e4hnlich! Der gleiche Ursprung, eine Abstammung. Medizin vom Gericht zum Volk, von der Nahrung zur Kultur, es ist die Verantwortung der aktuellen Entwicklung der gleichen Quelle der Medizin und Nahrung.<\/p>\n<p>Kurz gesagt, die volle Nutzung der Lebensmitteleigenschaften authentischer chinesischer Kr\u00e4uter, die Erschlie\u00dfung der Essenz des Gedankens der Homologie chinesischer Kr\u00e4uter mit Lebensmitteln und Medizin, die Herstellung medizinischer Mahlzeiten mit chinesischen Merkmalen, die Maximierung des Dienstes am Leben und an der Gesundheit der Menschen - das ist die gr\u00f6\u00dfte Verantwortung der traditionellen chinesischen Medizinindustrie in China und auch der gr\u00f6\u00dfte Beitrag zur Gesundheit der Menschen in der Welt.<\/p>","protected":false},"excerpt":{"rendered":"<p>Der genaue Ursprung und die Zeit des Begriffs \"Medizin und Nahrung zusammen\", der eine moderne Zusammenfassung der Beziehung zwischen Medizin und Nahrung und deren Anwendungen darstellt, ist nicht klar. Aus der Literaturrecherche in den Datenbanken von China Knowledge, Wipo, Wanfang und National Library Reference and Consultation Union geht hervor, dass die [...]<\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>What is medicinal food\uff1f - China Chemical Manufacturer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/longchangextracts.com\/de\/heilnahrung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"What is medicinal food\uff1f - China Chemical Manufacturer\" \/>\n<meta property=\"og:description\" content=\"The exact origin and time of the term \u201cmedicine and food together\u201d, which is a modern summary of the relationship between medicine and food and their applications, is not clear. From the literature search in the databases of China Knowledge, Wipo, Wanfang and National Library Reference and Consultation Union, it can be seen that the [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/longchangextracts.com\/de\/heilnahrung\/\" \/>\n<meta property=\"og:site_name\" content=\"China Chemical Manufacturer\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-15T08:11:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/longchangextracts.com\/wp-content\/uploads\/2024\/08\/1-355-650x255.png\" \/>\n<meta name=\"author\" content=\"Mrzhao\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mrzhao\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/longchangextracts.com\/medicinal-food\/\",\"url\":\"https:\/\/longchangextracts.com\/medicinal-food\/\",\"name\":\"What is medicinal food\uff1f - China Chemical Manufacturer\",\"isPartOf\":{\"@id\":\"https:\/\/longchangextracts.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/longchangextracts.com\/medicinal-food\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/longchangextracts.com\/medicinal-food\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/longchangextracts.com\/wp-content\/uploads\/2024\/08\/1-355-650x255.png\",\"datePublished\":\"2024-08-15T08:11:18+00:00\",\"dateModified\":\"2024-08-15T08:11:18+00:00\",\"author\":{\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80f128fa4967f2080f7577af46a2bfb3\"},\"breadcrumb\":{\"@id\":\"https:\/\/longchangextracts.com\/medicinal-food\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/longchangextracts.com\/medicinal-food\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/longchangextracts.com\/medicinal-food\/#primaryimage\",\"url\":\"https:\/\/longchangextracts.com\/wp-content\/uploads\/2024\/08\/1-355-650x255.png\",\"contentUrl\":\"https:\/\/longchangextracts.com\/wp-content\/uploads\/2024\/08\/1-355-650x255.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/longchangextracts.com\/medicinal-food\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/longchangextracts.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"What is medicinal food\uff1f\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/longchangextracts.com\/#website\",\"url\":\"https:\/\/longchangextracts.com\/\",\"name\":\"China Chemical Manufacturer\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/longchangextracts.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80f128fa4967f2080f7577af46a2bfb3\",\"name\":\"Mrzhao\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5b7d172a0978697481379e6a4a769a17?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5b7d172a0978697481379e6a4a769a17?s=96&d=mm&r=g\",\"caption\":\"Mrzhao\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Was sind medizinische Lebensmittel\uff1f - China Chemical Manufacturer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/longchangextracts.com\/de\/heilnahrung\/","og_locale":"de_DE","og_type":"article","og_title":"What is medicinal food\uff1f - China Chemical Manufacturer","og_description":"The exact origin and time of the term \u201cmedicine and food together\u201d, which is a modern summary of the relationship between medicine and food and their applications, is not clear. From the literature search in the databases of China Knowledge, Wipo, Wanfang and National Library Reference and Consultation Union, it can be seen that the [&hellip;]","og_url":"https:\/\/longchangextracts.com\/de\/heilnahrung\/","og_site_name":"China Chemical Manufacturer","article_published_time":"2024-08-15T08:11:18+00:00","og_image":[{"url":"https:\/\/longchangextracts.com\/wp-content\/uploads\/2024\/08\/1-355-650x255.png"}],"author":"Mrzhao","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Mrzhao","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/longchangextracts.com\/medicinal-food\/","url":"https:\/\/longchangextracts.com\/medicinal-food\/","name":"Was sind medizinische Lebensmittel\uff1f - China Chemical Manufacturer","isPartOf":{"@id":"https:\/\/longchangextracts.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/longchangextracts.com\/medicinal-food\/#primaryimage"},"image":{"@id":"https:\/\/longchangextracts.com\/medicinal-food\/#primaryimage"},"thumbnailUrl":"https:\/\/longchangextracts.com\/wp-content\/uploads\/2024\/08\/1-355-650x255.png","datePublished":"2024-08-15T08:11:18+00:00","dateModified":"2024-08-15T08:11:18+00:00","author":{"@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80f128fa4967f2080f7577af46a2bfb3"},"breadcrumb":{"@id":"https:\/\/longchangextracts.com\/medicinal-food\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/longchangextracts.com\/medicinal-food\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/longchangextracts.com\/medicinal-food\/#primaryimage","url":"https:\/\/longchangextracts.com\/wp-content\/uploads\/2024\/08\/1-355-650x255.png","contentUrl":"https:\/\/longchangextracts.com\/wp-content\/uploads\/2024\/08\/1-355-650x255.png"},{"@type":"BreadcrumbList","@id":"https:\/\/longchangextracts.com\/medicinal-food\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/longchangextracts.com\/"},{"@type":"ListItem","position":2,"name":"What is medicinal food\uff1f"}]},{"@type":"WebSite","@id":"https:\/\/longchangextracts.com\/#website","url":"https:\/\/longchangextracts.com\/","name":"China Chemische Hersteller","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/longchangextracts.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80f128fa4967f2080f7577af46a2bfb3","name":"Mrzhao","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5b7d172a0978697481379e6a4a769a17?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b7d172a0978697481379e6a4a769a17?s=96&d=mm&r=g","caption":"Mrzhao"}}]}},"_links":{"self":[{"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/posts\/8851"}],"collection":[{"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/comments?post=8851"}],"version-history":[{"count":1,"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/posts\/8851\/revisions"}],"predecessor-version":[{"id":8854,"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/posts\/8851\/revisions\/8854"}],"wp:attachment":[{"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/media?parent=8851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/categories?post=8851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/tags?post=8851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}