{"id":8181,"date":"2024-08-11T19:56:19","date_gmt":"2024-08-11T19:56:19","guid":{"rendered":"https:\/\/longchangextracts.com\/?p=8181"},"modified":"2024-08-11T19:56:19","modified_gmt":"2024-08-11T19:56:19","slug":"endophytic-aspergillus-in-nine-fragrant-insects","status":"publish","type":"post","link":"https:\/\/longchangextracts.com\/de\/endophytische-aspergillus-in-neun-duftenden-insekten\/","title":{"rendered":"Studie \u00fcber sekund\u00e4re Metaboliten und antibakterielle Aktivit\u00e4t von endophytischen Aspergillus in neun duftenden Insekten"},"content":{"rendered":"<p>Studie \u00fcber sekund\u00e4re Metaboliten und antibakterielle Aktivit\u00e4t von endophytischen Aspergillus in neun duftenden Insekten<br \/>\nDie Sekund\u00e4rmetaboliten von Mikroorganismen sind die Quelle verschiedener bioaktiver Verbindungen, wie z. B. Antibiotika, und haben einen erheblichen medizinischen Wert. In den letzten Jahren sind sie auch zu einem wichtigen Thema in der Forschung der nat\u00fcrlichen medizinischen Chemie geworden. Insektensymbionten sind Pilze, die ihren gesamten Lebenszyklus oder einen Teil davon im Wirtsinsekt verbracht haben, ohne nennenswerte Infektionssymptome im Wirt zu verursachen. Sie k\u00f6nnen organische Bestandteile abbauen, um den Wirt mit N\u00e4hrstoffen zu versorgen, ihm helfen, sich gegen fremde mikrobielle Invasionen zu wehren, und die Immunantwort des Wirts ausl\u00f6sen. Im Laufe der langfristigen Evolution haben die Pilze eine Reihe von Methoden entwickelt, um sich an die Darmumgebung anzupassen und stabile symbiotische Beziehungen mit ihren Wirten einzugehen. Sie haben bestimmte Eigenheiten bei der Wirtsauswahl und Kolonisierung.<br \/>\nDer Jiuxiang-K\u00e4fer, gemeinhin als \"Stinkende Wanze\" bekannt, ist eine Insektenart der traditionellen chinesischen Medizin mit einer langen Geschichte medizinischer Verwendung, die in Arzneib\u00fcchern verzeichnet ist. In manchen Gegenden ist er auch ein k\u00f6stliches Nahrungsmittel. Im Compendium of Materia Medica hei\u00dft es, dass Jiuxiangchong haupts\u00e4chlich zur Behandlung von Qi-Stagnation im Zwerchfell und im Epigastrium, bei Milz- und Nierenmangel und zur St\u00e4rkung des Yang verwendet wird. Es kann bei Nierenmangel, Impotenz, Schmerzen und Schw\u00e4che in der Taille und den Knien sowie bei Bl\u00e4hungen und Schmerzen bei Gastritis eingesetzt werden. Die Forschung hat gezeigt, dass die n\u00e4hrende Wirkung der neun Gew\u00fcrzw\u00fcrmer mit ihrem Reichtum an Vitaminen, Spurenelementen, Phospholipiden, Aminos\u00e4uren, Proteinen, Lipiden und N-Acetyldopamin-Substanzen zusammenh\u00e4ngen k\u00f6nnte. Dar\u00fcber hinaus hat der Extrakt von neun Gew\u00fcrzw\u00fcrmern antibakterielle Wirkungen auf Staphylococcus aureus, Salmonella typhi, Salmonella paratyphoid A und Shigella flexneri, und in ihrer H\u00e4molymphe wurden auch neue antimikrobielle Peptide gefunden. Diese antibakteriellen Wirkstoffe stehen m\u00f6glicherweise im Zusammenhang mit der Behandlung von Gastritis mit neun Gew\u00fcrzw\u00fcrmern. Die antibakterielle Wirkung des Jiuxiang-Insekts deutet darauf hin, dass seine endophytischen Pilze ebenfalls Sekund\u00e4rmetaboliten mit antibakterieller Wirkung produzieren k\u00f6nnen. Gegenw\u00e4rtig gibt es einen Mangel an relevanten Berichten \u00fcber die endophytischen Pilze und ihre Metaboliten des Neun-Gew\u00fcrz-K\u00e4fers. In dieser Studie wurde der Neun-Gew\u00fcrz-K\u00e4fer als Forschungsobjekt ausgew\u00e4hlt, ein Aspergillus-Stamm aus seinem Darm isoliert und ein festes Reiskulturmedium f\u00fcr eine gro\u00df angelegte Fermentation verwendet. Die sekund\u00e4ren Metaboliten wurden isoliert, gereinigt und strukturell identifiziert, und ihre antibakterielle Aktivit\u00e4t wurde getestet, um Metaboliten mit guter antibakterieller Aktivit\u00e4t zu erhalten und die chemische Zusammensetzung und biologische Aktivit\u00e4tsforschung von Insektenendophyten zu bereichern.<\/p>\n<p>&nbsp;<\/p>\n<p>In dieser Studie wurden Kieselgel-, MCI-, Gels\u00e4ulenchromatographie- und semipr\u00e4parative Fl\u00fcssigkeitsmethoden zur Trennung und Reinigung der Sekund\u00e4rmetaboliten des endophytischen Aspergillus septentrionalis verwendet. Aus ihnen wurden sechs Verbindungen isoliert, darunter eine neue Verbindung und f\u00fcnf bekannte Verbindungen, bei denen es sich um Polyketide handelt. Je nach Strukturtyp lassen sie sich weiter in Pyranone, Diphenylether und Butyrolactone unterteilen. Die Verbindungen 1 und 2 wurden zum ersten Mal aus Aspergillus isoliert. Diphenylether-Verbindung 4 weist eine gewisse antibakterielle Aktivit\u00e4t auf, und auch in der Literatur wird berichtet, dass solche Verbindungen eine gute antibakterielle Aktivit\u00e4t aufweisen, insbesondere bei st\u00e4rkeren Halogensubstitutionseffekten. Daher ist es m\u00f6glich, \u00e4hnliche Verbindungen aus anderen Teilen des Bakterienextrakts zu isolieren und zu reinigen, unter denen es viele Verbindungen mit herausragender Aktivit\u00e4t gibt, die es wert sind, untersucht zu werden. In der Literatur wird berichtet, dass Quercetin (3) gute antioxidative und br\u00e4unungshemmende biologische Aktivit\u00e4ten aufweist, die auf \u00e4hnliche biologische Aktivit\u00e4ten untersucht werden k\u00f6nnen. Von Aspergillus-Pilzen wurde berichtet, dass sie verschiedene Arten bioaktiver Substanzen synthetisieren, aber ihre Sekund\u00e4rmetaboliten sind nicht essentielle Substanzen mit relativ geringen Ertr\u00e4gen. In einem sp\u00e4teren Stadium k\u00f6nnen gro\u00df angelegte Fermentationen, verbesserte Kulturmedien, induzierte Biosynthese und genomische Modifikationstechniken eingesetzt werden, um die wahren Sekund\u00e4rmetaboliten von Aspergillus-Pilzen weiter zu erforschen, um mehr gute aktive Metaboliten zu erhalten und Referenzen f\u00fcr die rationelle Entwicklung und Nutzung von entomopathogenen Pilzressourcen zu liefern.<\/p>","protected":false},"excerpt":{"rendered":"<p>Study on Secondary Metabolites and Antibacterial Activity of Endophytic Aspergillus in Nine Fragrant Insects The secondary metabolites of microorganisms are the source of various bioactive compounds such as antibiotics, and have significant medicinal value. In recent years, they have also become a hot topic in natural medicinal chemistry research. Insect symbiotic fungi refer to fungi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Study on Secondary Metabolites and Antibacterial Activity of Endophytic Aspergillus in Nine Fragrant Insects - China Chemical Manufacturer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/longchangextracts.com\/de\/endophytische-aspergillus-in-neun-duftenden-insekten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Study on Secondary Metabolites and Antibacterial Activity of Endophytic Aspergillus in Nine Fragrant Insects - China Chemical Manufacturer\" \/>\n<meta property=\"og:description\" content=\"Study on Secondary Metabolites and Antibacterial Activity of Endophytic Aspergillus in Nine Fragrant Insects The secondary metabolites of microorganisms are the source of various bioactive compounds such as antibiotics, and have significant medicinal value. In recent years, they have also become a hot topic in natural medicinal chemistry research. Insect symbiotic fungi refer to fungi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/longchangextracts.com\/de\/endophytische-aspergillus-in-neun-duftenden-insekten\/\" \/>\n<meta property=\"og:site_name\" content=\"China Chemical Manufacturer\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-11T19:56:19+00:00\" \/>\n<meta name=\"author\" content=\"Longchang Chemical\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Longchang Chemical\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/longchangextracts.com\/endophytic-aspergillus-in-nine-fragrant-insects\/\",\"url\":\"https:\/\/longchangextracts.com\/endophytic-aspergillus-in-nine-fragrant-insects\/\",\"name\":\"Study on Secondary Metabolites and Antibacterial Activity of Endophytic Aspergillus in Nine Fragrant Insects - China Chemical Manufacturer\",\"isPartOf\":{\"@id\":\"https:\/\/longchangextracts.com\/#website\"},\"datePublished\":\"2024-08-11T19:56:19+00:00\",\"dateModified\":\"2024-08-11T19:56:19+00:00\",\"author\":{\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\"},\"breadcrumb\":{\"@id\":\"https:\/\/longchangextracts.com\/endophytic-aspergillus-in-nine-fragrant-insects\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/longchangextracts.com\/endophytic-aspergillus-in-nine-fragrant-insects\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/longchangextracts.com\/endophytic-aspergillus-in-nine-fragrant-insects\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/longchangextracts.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Study on Secondary Metabolites and Antibacterial Activity of Endophytic Aspergillus in Nine Fragrant Insects\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/longchangextracts.com\/#website\",\"url\":\"https:\/\/longchangextracts.com\/\",\"name\":\"China Chemical Manufacturer\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/longchangextracts.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\",\"name\":\"Longchang Chemical\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"caption\":\"Longchang Chemical\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Studie \u00fcber sekund\u00e4re Metaboliten und antibakterielle Aktivit\u00e4t von endophytischen Aspergillus in neun duftenden Insekten - China Chemical Manufacturer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/longchangextracts.com\/de\/endophytische-aspergillus-in-neun-duftenden-insekten\/","og_locale":"de_DE","og_type":"article","og_title":"Study on Secondary Metabolites and Antibacterial Activity of Endophytic Aspergillus in Nine Fragrant Insects - China Chemical Manufacturer","og_description":"Study on Secondary Metabolites and Antibacterial Activity of Endophytic Aspergillus in Nine Fragrant Insects The secondary metabolites of microorganisms are the source of various bioactive compounds such as antibiotics, and have significant medicinal value. In recent years, they have also become a hot topic in natural medicinal chemistry research. Insect symbiotic fungi refer to fungi [&hellip;]","og_url":"https:\/\/longchangextracts.com\/de\/endophytische-aspergillus-in-neun-duftenden-insekten\/","og_site_name":"China Chemical Manufacturer","article_published_time":"2024-08-11T19:56:19+00:00","author":"Longchang Chemical","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Longchang Chemical","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/longchangextracts.com\/endophytic-aspergillus-in-nine-fragrant-insects\/","url":"https:\/\/longchangextracts.com\/endophytic-aspergillus-in-nine-fragrant-insects\/","name":"Studie \u00fcber sekund\u00e4re Metaboliten und antibakterielle Aktivit\u00e4t von endophytischen Aspergillus in neun duftenden Insekten - China Chemical Manufacturer","isPartOf":{"@id":"https:\/\/longchangextracts.com\/#website"},"datePublished":"2024-08-11T19:56:19+00:00","dateModified":"2024-08-11T19:56:19+00:00","author":{"@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869"},"breadcrumb":{"@id":"https:\/\/longchangextracts.com\/endophytic-aspergillus-in-nine-fragrant-insects\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/longchangextracts.com\/endophytic-aspergillus-in-nine-fragrant-insects\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/longchangextracts.com\/endophytic-aspergillus-in-nine-fragrant-insects\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/longchangextracts.com\/"},{"@type":"ListItem","position":2,"name":"Study on Secondary Metabolites and Antibacterial Activity of Endophytic Aspergillus in Nine Fragrant Insects"}]},{"@type":"WebSite","@id":"https:\/\/longchangextracts.com\/#website","url":"https:\/\/longchangextracts.com\/","name":"China Chemische Hersteller","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/longchangextracts.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869","name":"Longchang Chemical","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","caption":"Longchang Chemical"}}]}},"_links":{"self":[{"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/posts\/8181"}],"collection":[{"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/comments?post=8181"}],"version-history":[{"count":1,"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/posts\/8181\/revisions"}],"predecessor-version":[{"id":8182,"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/posts\/8181\/revisions\/8182"}],"wp:attachment":[{"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/media?parent=8181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/categories?post=8181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/tags?post=8181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}