{"id":8100,"date":"2024-08-11T19:08:20","date_gmt":"2024-08-11T19:08:20","guid":{"rendered":"https:\/\/longchangextracts.com\/?p=8100"},"modified":"2024-08-11T19:08:20","modified_gmt":"2024-08-11T19:08:20","slug":"huanglian-2","status":"publish","type":"post","link":"https:\/\/longchangextracts.com\/de\/huanglian-2\/","title":{"rendered":"Studie \u00fcber den Mechanismus der Huanglian Banxia Medizin bei der Behandlung von chronischer atrophischer Gastritis"},"content":{"rendered":"<p>Studie \u00fcber den Mechanismus der Huanglian Banxia Medizin bei der Behandlung von chronischer atrophischer Gastritis<br \/>\nDie chronische atrophische Gastritis geh\u00f6rt in der traditionellen chinesischen Medizin zur Kategorie der \"Magen\u00fcberbl\u00e4hung\" und der \"Magenschmerzen\". Die \u00c4tiologie wird oft durch unzureichendes positives Qi, in den Magen eingedrungene \u00e4u\u00dfere Krankheitserreger, emotionale St\u00f6rungen und Ern\u00e4hrungsfehler verursacht. Die Krankheit ist in Milz und Magen angesiedelt, und die Natur der Krankheit ist oft eine Mischung aus Mangel und \u00dcberschuss. \"Qi-Stagnation, Qi-Mangel, feuchte Hitze, Blutstau\" ziehen sich durch den gesamten Krankheitsverlauf und werden in verschiedenen Stadien betont. Bei der Behandlung werden h\u00e4ufig Methoden wie die Beseitigung von Hitze und Schleim, die Ern\u00e4hrung von Qi und Yin, die F\u00f6rderung der Blutzirkulation und die Entstauung der Kollateralen eingesetzt. Huanglian und Banxia geh\u00f6ren zu den h\u00e4ufig verwendeten Medikamenten in der klinischen Praxis der traditionellen chinesischen Medizin und sind auch die empfohlenen Bestandteile von Lianpuyin, Huanglian Wendan Tang und Banxia Xiexin Tang im Konsens der traditionellen chinesischen Medizin und der integrierten traditionellen chinesischen und westlichen Medizin zur Diagnose und Behandlung der chronischen atrophischen Gastritis. Sie haben eine solide klinische Grundlage f\u00fcr die Behandlung der chronischen atrophischen Gastritis. In verwandten Studien wurde festgestellt, dass die Aktivierung des Signalwegs Januskinase 2 (JAK2)\/Signaltransducer und Aktivator der Transkription 3 (STAT3) w\u00e4hrend der Pathogenese der chronisch atrophischen Gastritis zu abnormaler Proliferation, Angiogenese und maligner Transformation von Magenschleimhautzellen f\u00fchren kann, was letztlich zum Auftreten und zur Entwicklung maligner Tumore f\u00fchrt; Die positive Rate des Yes-assoziierten Proteins 1 (YAP1) in der Magenschleimhaut von Magenkrebspatienten ist deutlich h\u00f6her als die der normalen Magenschleimhaut, der chronisch atrophischen Gastritis und der Patienten mit intestinaler Metaplasie. Seine \u00dcberexpression in der Magenschleimhaut steht in engem Zusammenhang mit dem Fortschreiten, der Lymphknotenmetastasierung und der schlechten Prognose von Magenkrebs; die Angiogenese ist ein wichtiger Faktor, der die Prognose der chronisch atrophischen Gastritis und der Pr\u00e4kanzerosen von Magenkrebs beeinflusst. Ausgehend davon wurde in dieser Studie zun\u00e4chst mittels molekularem Docking die Beziehung zwischen den Wirkstoffen der Huanglian Banxia Medizin und den Schl\u00fcsselzielen von Interleukin-1 \u03b2 (IL-1 \u03b2) und Interleukin-6 (IL-6) in der Pathogenese der chronischen atrophischen Gastritis untersucht, IL-6) \u3001YAP1\u3001STAT3\u3001JAK2\u3001 Die Bindungsaffinit\u00e4t des vaskul\u00e4ren endothelialen Wachstumsfaktors (VEGF) und des epidermalen Wachstumsfaktorrezeptors (EGFR); Dann wurde ein Rattenmodell der chronischen atrophischen Gastritis durch Tierversuche etabliert, und die Interventionsbehandlung wurde mit der Abkochung von Huanglian und Banxia durchgef\u00fchrt; Schlie\u00dflich wollen wir durch die Erkennung der Expression relevanter Targets im Blut und im Magenschleimhautgewebe den Wirkmechanismus des Medikaments bei der Vorbeugung und Behandlung der chronischen atrophischen Gastritis erforschen und damit den Grundstein f\u00fcr die weitere Forschung legen.<\/p>\n<p>&nbsp;<\/p>\n<p>Huanglian und Banxia, die in der traditionellen chinesischen Medizin in Banxia Xiexin Tang, Lianpu Yin und Huanglian Wendan Tang verwendet werden, spielen in verschiedenen Pr\u00e4paraten die Rolle von \"Herrscher und Minister\". Huanglian ist eine mehrj\u00e4hrige krautige Pflanze, die zur Familie der Hahnenfu\u00dfgew\u00e4chse (Ranunculaceae) geh\u00f6rt. Sie enth\u00e4lt haupts\u00e4chlich Alkaloide, Flavonoide, Lignane, saure Bestandteile usw. Sie wirkt hitzel\u00f6schend, feuchtigkeitstrocknend, feuerl\u00f6schend und entgiftend. Pinellia ternata geh\u00f6rt zur Familie der Araceae, der Ordnung der Araceae. Sie enth\u00e4lt verschiedene chemische Bestandteile wie Alkaloide, organische S\u00e4uren, Sterole, Aminos\u00e4uren, \u00e4therische \u00d6le und anorganische Elemente. Sie wirkt feuchtigkeitstrocknend, schleiml\u00f6send und lindert \u00dcbelkeit und Erbrechen. Huanglian Pinellia ternata ist eine Kombination aus warmen und kalten Kr\u00e4utern, ohne die Sorge um \u00fcberm\u00e4\u00dfige medizinische Eigenschaften. Es ist eine Kombination aus bitteren und bitteren Kr\u00e4utern, die Bitterkeit reduzieren, den Qi-Fluss regulieren und Feuchtigkeit kl\u00e4ren und beseitigen k\u00f6nnen. Zusammen hat es die Wirkung, \u00dcbelkeit zu stoppen, Hitze und Schleim zu beseitigen, Stagnation zu vertreiben, zu entgiften und Schwellungen zu reduzieren, und steht im Einklang mit der \u00c4tiologie und Pathogenese der chronischen atrophischen Gastritis. In dieser Studie wurden 13 Hauptwirkstoffe in Huanglian und Banxia nach strengen Lipinski-Regeln untersucht, darunter 8 Huanglian und 5 Banxia. Durch molekulares Docking wurde festgestellt, dass die Hauptwirkstoffe, die durch Berberin, Methylcoptisin usw. repr\u00e4sentiert werden, an die Kernziele der chronischen atrophischen Gastritis, IL-1 \u03b2, IL-6, YAP1, STAT3, JAK2, VEGF, EGFR, binden k\u00f6nnen, die bis zu einem gewissen Grad die wichtigste pharmakologische Substanzbasis von Huanglian und Banxia bei der Pr\u00e4vention und Behandlung der chronischen atrophischen Gastritis darstellen.<\/p>\n<p>Die moderne Forschung hat herausgefunden, dass die Entz\u00fcndung als wichtigste pathologische Ver\u00e4nderung im Fr\u00fchstadium der chronisch atrophischen Gastritis die b\u00f6sartige Umwandlung des erkrankten Magenschleimhautgewebes unter der Wirkung einer \"unkontrollierten Entz\u00fcndung\" f\u00f6rdert und die fr\u00fche Angiogenese von Krebs beschleunigt. Klinische und experimentelle Studien haben best\u00e4tigt, dass die Aktivierung von Entz\u00fcndungssignalwegen wie JAK2\/STAT3, die Hochregulierung von pro-inflammatorischen Zytokinen (IL-6, IL-1 \u03b2, etc.) und die Aktivierung von Angiogenesewegen (VEGF, EGFR, etc.) eine wichtige Rolle bei der Entwicklung der chronisch atrophischen Gastritis der Magenschleimhaut spielen. YAP1 ist ein wichtiger transkriptioneller Co-Aktivator im Hippo-Signalweg und reguliert Zellwachstum, Proliferation und Apoptose. Unter normalen Umst\u00e4nden liegt YAP1 im Zytoplasma in Form von Phosphorylierungen vor und ist an der Regulierung der Organ- und Geweberegeneration beteiligt. Unter dem Einfluss von vorgelagerten anormalen Signalen wie unkontrollierten Entz\u00fcndungen wird YAP1 dephosphoryliert und gelangt in den Zellkern, wo es die Expression verwandter Krebsgene und die Zellproliferation f\u00f6rdert und das Ausma\u00df der karzinogenen Aktivit\u00e4t bestimmt. AKT1 ist an der Entstehung, Entwicklung, Infiltration und Metastasierung von Magenkrebs beteiligt. Eine St\u00f6rung der AKT1-Expression kann die Proliferation und Migration von Magenkrebszellen hemmen. Daher spielen IL-1 \u03b2, IL-6, YAP1, STAT3, JAK2, AKT1, VEGF und EGFR eine wichtige Rolle in der Pathogenese der chronischen atrophischen Gastritis und sind wichtige Ziele f\u00fcr die Verhinderung und Behandlung des Fortschreitens in Richtung Malignit\u00e4t.<\/p>\n<p>In diesem Experiment wurde unter der langfristigen Stimulation komplexer Bedingungen wie MNNG-L\u00f6sung, hei\u00dfem Salz, Ethanol sowie Hunger- und S\u00e4ttigungsst\u00f6rungen Futtermittel mit Ranitidin (einem in der klinischen Praxis h\u00e4ufig verwendeten selektiven H2-Rezeptor-Antagonisten) zugesetzt, um die Magens\u00e4uresekretion bei den Modelltieren zu hemmen, die schnelle Umwandlung von Nitrat in Nitrit nach dem Trinken in den Magen zu f\u00f6rdern und die Modellierung zu beschleunigen. Durch die pathologische Untersuchung von HE wurde festgestellt, dass mit dieser Methode erfolgreich ein Modell der chronischen atrophischen Gastritis geschaffen wurde. Vitamin-Enzym-Extrakt ist ein g\u00e4ngiges westliches Medikament zur Behandlung der chronischen atrophischen Gastritis, das haupts\u00e4chlich aus Riboflavin, Flavin-Mononukleotid, verschiedenen Vitaminen und Aminos\u00e4uren besteht. Es f\u00f6rdert die Regeneration des Magenschleimhautepithels und des Dr\u00fcsenepithels und hat eine starke vergleichende Bedeutung mit der traditionellen chinesischen Mehrkomponentenmedizin. Nach der Pr\u00fcfung verschiedener Indikatoren wurde festgestellt, dass die entz\u00fcndlichen Zytokine IL-6 und IL-1 \u03b2 im Blut der Ratten signifikant erh\u00f6ht waren und eine entz\u00fcndliche Mikroumgebung bildeten; Verursachung eines Anstiegs der p-JAK2- und pSTAT3-Werte, Aktivierung des JAK2\/STAT3-Signalwegs, F\u00f6rderung einer unkontrollierten Entz\u00fcndung, was zur Aktivierung von VEGF und EGFR f\u00fchrt, Beschleunigung der fr\u00fchen Angiogenese bei Krebs und Ausl\u00f6sung der Dephosphorylierung von YAP1 (p-YAP1), was zu einer \u00dcberexpression von AKT1 f\u00fchrt, Sch\u00e4digung der Morphologie des Magenschleimhautgewebes und Ausl\u00f6sung einer chronischen atrophischen Gastritis, die sich zu b\u00f6sartigen Tumoren entwickelt. Nach der Intervention und Behandlung mit mehreren Wirkstoffen der Huanglian-Banxia-Medizin wurde die Expression der Entz\u00fcndungszytokine IL-6 und IL-1 \u03b2 im Serum signifikant gehemmt und das Phosphorylierungsniveau von Schl\u00fcsselindikatoren des JAK2\/STAT3-Signalweges im Magenschleimhautgewebe wurde reduziert. Die Aktivierung des Signalwegs wurde gehemmt, die entz\u00fcndliche Mikroumgebung wurde verbessert, die Expression von VEGF und EGFR im Gewebe wurde reduziert und die Tumorangiogenese wurde beeintr\u00e4chtigt. Die \u00dcberexpression von YAP1 und AKT1 wurde reguliert, um die gesch\u00e4digte Gewebemorphologie zu reparieren, die maligne Transformation der chronisch atrophischen Gastritis zu verz\u00f6gern oder zu blockieren und somit eine therapeutische Wirkung auf die chronisch atrophische Gastritis auszu\u00fcben. In diesem Prozess hatte die Kombination von Huanglian Banxia in einer mittleren Dosis signifikante Vorteile und war dem Vitamin E \u00fcberlegen, und es wurde keine Dosisabh\u00e4ngigkeit festgestellt. Daher glauben wir, dass Huanglian und Banxia die wichtigsten Medikamente zur Vorbeugung und Behandlung der chronischen atrophischen Gastritis sind, und dass ihre Wirkmechanismen eng mit der Regulierung von Entz\u00fcndungssignalwegen, der Hemmung der Tumorangiogenese und anderen Wegen verbunden sind.<\/p>","protected":false},"excerpt":{"rendered":"<p>Study on the mechanism of Huanglian Banxia medicine in the treatment of chronic atrophic gastritis Chronic atrophic gastritis belongs to the category of &#8220;gastric distension&#8221; and &#8220;stomach pain&#8221; in traditional Chinese medicine. The etiology is often caused by insufficient positive qi, external pathogens invading the stomach, emotional disorders, and dietary disorders. The disease is in [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Study on the mechanism of Huanglian Banxia medicine in the treatment of chronic atrophic gastritis - China Chemical Manufacturer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/longchangextracts.com\/de\/huanglian-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Study on the mechanism of Huanglian Banxia medicine in the treatment of chronic atrophic gastritis - China Chemical Manufacturer\" \/>\n<meta property=\"og:description\" content=\"Study on the mechanism of Huanglian Banxia medicine in the treatment of chronic atrophic gastritis Chronic atrophic gastritis belongs to the category of &#8220;gastric distension&#8221; and &#8220;stomach pain&#8221; in traditional Chinese medicine. The etiology is often caused by insufficient positive qi, external pathogens invading the stomach, emotional disorders, and dietary disorders. The disease is in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/longchangextracts.com\/de\/huanglian-2\/\" \/>\n<meta property=\"og:site_name\" content=\"China Chemical Manufacturer\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-11T19:08:20+00:00\" \/>\n<meta name=\"author\" content=\"Longchang Chemical\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Longchang Chemical\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/longchangextracts.com\/huanglian-2\/\",\"url\":\"https:\/\/longchangextracts.com\/huanglian-2\/\",\"name\":\"Study on the mechanism of Huanglian Banxia medicine in the treatment of chronic atrophic gastritis - China Chemical Manufacturer\",\"isPartOf\":{\"@id\":\"https:\/\/longchangextracts.com\/#website\"},\"datePublished\":\"2024-08-11T19:08:20+00:00\",\"dateModified\":\"2024-08-11T19:08:20+00:00\",\"author\":{\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\"},\"breadcrumb\":{\"@id\":\"https:\/\/longchangextracts.com\/huanglian-2\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/longchangextracts.com\/huanglian-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/longchangextracts.com\/huanglian-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/longchangextracts.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Study on the mechanism of Huanglian Banxia medicine in the treatment of chronic atrophic gastritis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/longchangextracts.com\/#website\",\"url\":\"https:\/\/longchangextracts.com\/\",\"name\":\"China Chemical Manufacturer\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/longchangextracts.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869\",\"name\":\"Longchang Chemical\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g\",\"caption\":\"Longchang Chemical\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Studie \u00fcber den Mechanismus der Huanglian Banxia Medizin bei der Behandlung von chronischer atrophischer Gastritis - China Chemical Manufacturer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/longchangextracts.com\/de\/huanglian-2\/","og_locale":"de_DE","og_type":"article","og_title":"Study on the mechanism of Huanglian Banxia medicine in the treatment of chronic atrophic gastritis - China Chemical Manufacturer","og_description":"Study on the mechanism of Huanglian Banxia medicine in the treatment of chronic atrophic gastritis Chronic atrophic gastritis belongs to the category of &#8220;gastric distension&#8221; and &#8220;stomach pain&#8221; in traditional Chinese medicine. The etiology is often caused by insufficient positive qi, external pathogens invading the stomach, emotional disorders, and dietary disorders. The disease is in [&hellip;]","og_url":"https:\/\/longchangextracts.com\/de\/huanglian-2\/","og_site_name":"China Chemical Manufacturer","article_published_time":"2024-08-11T19:08:20+00:00","author":"Longchang Chemical","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Longchang Chemical","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/longchangextracts.com\/huanglian-2\/","url":"https:\/\/longchangextracts.com\/huanglian-2\/","name":"Studie \u00fcber den Mechanismus der Huanglian Banxia Medizin bei der Behandlung von chronischer atrophischer Gastritis - China Chemical Manufacturer","isPartOf":{"@id":"https:\/\/longchangextracts.com\/#website"},"datePublished":"2024-08-11T19:08:20+00:00","dateModified":"2024-08-11T19:08:20+00:00","author":{"@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869"},"breadcrumb":{"@id":"https:\/\/longchangextracts.com\/huanglian-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/longchangextracts.com\/huanglian-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/longchangextracts.com\/huanglian-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/longchangextracts.com\/"},{"@type":"ListItem","position":2,"name":"Study on the mechanism of Huanglian Banxia medicine in the treatment of chronic atrophic gastritis"}]},{"@type":"WebSite","@id":"https:\/\/longchangextracts.com\/#website","url":"https:\/\/longchangextracts.com\/","name":"China Chemische Hersteller","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/longchangextracts.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80933ac6926ad63fea74ec33f8d04869","name":"Longchang Chemical","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c1e84ee0759373263198c58e8f338f80?s=96&d=mm&r=g","caption":"Longchang Chemical"}}]}},"_links":{"self":[{"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/posts\/8100"}],"collection":[{"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/comments?post=8100"}],"version-history":[{"count":1,"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/posts\/8100\/revisions"}],"predecessor-version":[{"id":8101,"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/posts\/8100\/revisions\/8101"}],"wp:attachment":[{"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/media?parent=8100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/categories?post=8100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/tags?post=8100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}