{"id":6670,"date":"2024-08-06T12:58:25","date_gmt":"2024-08-06T12:58:25","guid":{"rendered":"https:\/\/longchangextracts.com\/?p=6670"},"modified":"2024-08-06T12:58:25","modified_gmt":"2024-08-06T12:58:25","slug":"hydrocolloids","status":"publish","type":"post","link":"https:\/\/longchangextracts.com\/de\/hydrocolloids\/","title":{"rendered":"Welche Anwendungen gibt es f\u00fcr Hydrokolloide in Getr\u00e4nken?"},"content":{"rendered":"<p>Die Anwendung von Hydrokolloiden kann bis ins alte \u00c4gypten zur\u00fcckverfolgt werden, die Europ\u00e4er sind seit langem mit Johannisbrot, dass Akaziengummi vertraut. Chinas Jin-Dynastie hat damit begonnen, Konjak zu kultivieren, (Shu Du Fu) in den Wolken seiner G\u00e4rtnerei ist eine Medizin Jian, Kapsel Jian bezieht sich auf Konjak (die verwendet werden k\u00f6nnen, um hydrophile Kolloid Konjak-Gummi zu produzieren), mit dem Fortschritt der sozialen Produktion mehr und mehr hydrophile Kolloide sind im Bereich der Lebensmittel und Medizin verwendet.<\/p>\n<p>Bislang gibt es weltweit mehr als 40 Arten von Hydrokolloiden, die in der Lebensmittelindustrie verwendet werden k\u00f6nnen, und ihre Herkunft und Verbreitung ist sehr vielf\u00e4ltig. Hydrokolloid ist eine Art von gro\u00dfen in Polysaccharid, seine grundlegende chemische Zusammensetzung Einheit ist Monosaccharid und seine Derivate. Einige Hydrokolloide enthalten auch Nicht-Zuckeranteile, diese besondere chemische Zusammensetzung verleiht den Hydrokolloiden ganz besondere Eigenschaften. Sie k\u00f6nnen in der Regel als Geliermittel, Verdickungsmittel, Emulgatoren, Filmbildner, Wasserhaltemittel, Klebstoffe, Suspensionsmittel, Kl\u00e4rmittel, Kristallverhinderer, Schaumstabilisatoren, Schmiermittel usw. f\u00fcr Lebensmittel verwendet werden.<\/p>\n<p>Es gibt weitere Arten von Hydrokolloiden, wie Alginat, Carrageen, Xanthan, Johannisbrotkernmehl, Guarkernmehl und Pektin.<\/p>\n<p>Bei der Herstellung von Getr\u00e4nken kann es nicht nur als Verdickungs- und Geliermittel verwendet werden, sondern auch, um die Flie\u00dff\u00e4higkeit und Textur von fl\u00fcssigen Lebensmitteln zu steuern, die Verformbarkeit von halbfesten Lebensmitteln zu ver\u00e4ndern und so weiter.<\/p>\n<p>In der Regel die Konzentration von 0,025-0,5% kann Viskosit\u00e4t und Gelbildung zu produzieren, um effektiv zu verbessern die organoleptischen Eigenschaften von Getr\u00e4nken und erh\u00f6hen die Stabilit\u00e4t von Getr\u00e4nken, Getr\u00e4nkeherstellung sollte die geeignete Art von Kolloid w\u00e4hlen, die <strong>Bei der Auswahl eines hydrophilen Kolloids sollten vor allem die folgenden Faktoren ber\u00fccksichtigt werden:<\/strong> die Stabilit\u00e4t der gleichen pH-Bedingungen, die Auswirkungen von Elektrolyten auf das Kolloid und andere Bestandteile des Lebensmittels (Zucker, Salze, Proteine und andere Zusatzstoffe) der Synergie, Produktorganisation und Morphologie. Synergien, Produktgestaltung (Transparenz, Tr\u00fcbung) und Geschmack (Knusprigkeit, F\u00fclle), Benutzerfreundlichkeit (L\u00f6slichkeit, Lagerstabilit\u00e4t), Preis oder relative Kosten. Vorschriften f\u00fcr Lebensmittelzusatzstoffe, etc.<\/p>\n<p>Oft kann ein einziges Kolloid nicht alle Bedingungen f\u00fcr die Verwendung in einem Getr\u00e4nk erf\u00fcllen. Daher sollten verschiedene essbare Kolloide gemischt werden, um 1+1&gt;2, 1+1=2 oder sogar 1+1&lt;2 zu erzeugen, um die gew\u00fcnschte Anwendung zu erreichen. Mit Blick auf den Markt f\u00fcr verschiedene Arten g\u00e4ngiger Getr\u00e4nke wird \u00fcber die Anwendungsmerkmale von Hydrokolloiden gesprochen.<\/p>\n<p><strong>S\u00e4uerliche Obst- und Gem\u00fcsesaftgetr\u00e4nke<\/strong><\/p>\n<p>Der pH-Wert von sauren Fruchtsaftgetr\u00e4nken liegt in der Regel unter 4,0, da hitzebest\u00e4ndige Bakterien bei einem pH-Wert von 4,0 oder darunter nur schwer wachsen und sich vermehren k\u00f6nnen. Daher ist sein Sterilisationsobjekt meist weniger hitzebest\u00e4ndige Schimmelpilzoberfl\u00e4che oder Hefe, um die Frische des Saftes zu erhalten, in der Regel mit Pasteurisierung oder atmosph\u00e4rischem Druck.<\/p>\n<p>Kochendes Wasser Sterilisation und die meisten der sauren sp\u00e4rlichen Gem\u00fcsesaft pH-Wert von etwa 5,0, aufgrund seiner relativ hohen pH-Wert. Daher ist die Sterilisation Objekt thermophilen Bakterien, hohe Temperatur und Hochdruck-Sterilisation verwendet werden muss, daher, sauren Fruchtsaft Getr\u00e4nke und sauren Gem\u00fcsesaft Getr\u00e4nke sollten f\u00fcr die Wahl der Stabilisatoren unterschiedlich sein: die erste sollte ausgew\u00e4hlt werden, um s\u00e4urebest\u00e4ndige Stabilisatoren, wie Instant Pektin, Instant Xanthan Gum, Propylenglykol Alginat und so weiter verwenden. Letztere sollten einen st\u00e4rker hitzebest\u00e4ndigen Stabilisator wie Instant-Xanthangummi und Instant-CMC w\u00e4hlen.<\/p>\n<p>Dar\u00fcber hinaus haben Obst- und Gem\u00fcses\u00e4fte in der Regel hohe Anforderungen an den Geschmack, nicht nur um ein Gef\u00fchl der F\u00fclle haben und muss knackig sein, so dass die Viskosit\u00e4t sollte ausgew\u00e4hlt werden und relativ schwach Gel-Eigenschaften des Stabilisators. Wie z.B. Instant-Xanthan, Propylenglykol-Seebleichs\u00e4ureester und Instant-CMC. Enth\u00e4lt der Saft eine gro\u00dfe Anzahl von Fruchtfleisch oder Fruchtfasern, sollte eine h\u00f6here Viskosit\u00e4t und eine gewisse Gelf\u00e4higkeit des Kolloids gew\u00e4hlt werden, z. B. Agar vom Typ Niedertemperatur-Aktivierung, Instant-Pektin und das entsprechende Verbundkolloid.<\/p>\n<p><strong>Milchhaltige Getr\u00e4nke<\/strong><\/p>\n<p>Milchhaltige Getr\u00e4nke bestehen in der Regel aus Fruchtsaft, frischer Milch oder Milchprodukten (fermentierter Milch), S\u00fc\u00dfungsmitteln und Stabilisatoren. Aufgrund der fl\u00fcssigen Milch im Produktions- und Lagerungsprozess treten h\u00e4ufig Qualit\u00e4tsm\u00e4ngel auf (z. B. neutrale fl\u00fcssige Milchprodukte neigen zu schlechtem Geschmack, Fettaufschwemmung, Eiwei\u00dfgerinnung, Transparenz, fehlendem Milchgeschmack, Delamination, Sedimentation und anderen Ph\u00e4nomenen).<\/p>\n<p>Saure fl\u00fcssige Milcherzeugnisse neigen zu saurem Geschmack, Molkeausf\u00e4llung, Fettausschwimmen, Eiwei\u00dfausf\u00e4llung, Schichtung, schlechtem Geschmack, Milcharoma und anderen Ph\u00e4nomenen). Milchgetr\u00e4nke, die aus fl\u00fcssiger Milch oder reduzierter fl\u00fcssiger Milch hergestellt werden, haben daher auch das gleiche Potenzial f\u00fcr die oben genannten Qualit\u00e4tsm\u00e4ngel. Gleichzeitig kann das Milcheiwei\u00df leicht koagulieren und sich mit dem Fruchtsaft in der Fruchts\u00e4ure, dem Pektin, dem Tannin und anderen Substanzen niederschlagen. Daher ist die Wahl des richtigen Stabilisators zur L\u00f6sung der oben genannten Probleme die erste Priorit\u00e4t bei der Entwicklung von Milchgetr\u00e4nkeformulierungen.<\/p>\n<p>Instant-Pektin, Instant-Xanthangummi, Propylenglykol-Alginat und Instant-CMC k\u00f6nnen als Emulsionsstabilisatoren verwendet werden, um die Stabilit\u00e4t von Milchgetr\u00e4nken zu erh\u00f6hen. Dar\u00fcber hinaus k\u00f6nnen wir auch Stabilisatoren f\u00fcr neutrale milchhaltige Getr\u00e4nke wie Erdnussmilch, Kokosnussmilch, Walnussmilch, Mandelmilch, Sesammilch, s\u00fc\u00dfe Milch, Sojamilch, Kaffeemilch, Schokoladenmilch usw. und Stabilisatoren f\u00fcr saure milchhaltige Getr\u00e4nke (die in der Lage sind, Proteine zu sch\u00fctzen und die Geschmeidigkeit von Getr\u00e4nken unter sauren Erhitzungsbedingungen zu verbessern) anbieten.<\/p>\n<p><strong>Kohlens\u00e4urehaltige Getr\u00e4nke<\/strong><\/p>\n<p>Bei der Herstellung von kohlens\u00e4urehaltigen Getr\u00e4nken ist es in der Regel erforderlich, emulgierte Aromen oder Hauptbestandteile aus \u00e4therischen \u00d6len herzustellen, so dass emulgierende Stabilisatoren eine wichtige Rolle bei der Herstellung von kohlens\u00e4urehaltigen Getr\u00e4nken spielen. Unter den Hydrokolloiden sind Gummiarabikum und modifizierte St\u00e4rke die am h\u00e4ufigsten verwendeten Hydrokolloide f\u00fcr die Herstellung solcher emulgierten Aromen oder Hauptbestandteile.<\/p>\n<p>Dar\u00fcber hinaus, um die Emulgierf\u00e4higkeit von Gummi arabicum auf der Grundlage der traditionellen Gummi arabicum f\u00fcr die Pfropfung Modifikation, die Produktion von modifizierten Gummi arabicum, f\u00fcr die Herstellung einer hohen Anzahl von emulgierten Aromen und emulgierten Aromen, um die Kosten f\u00fcr die Formulierung der M\u00f6glichkeit der emulgierten Aromen.<\/p>\n<p><strong>Funktionelle Getr\u00e4nke<\/strong><\/p>\n<p>Mit der Beliebtheit von Kr\u00e4utertee ist eine Reihe von funktionellen Gesundheitsgetr\u00e4nken und Ersatzgetr\u00e4nken auf dem Markt entstanden. Hydrokolloide spielen bei der Herstellung solcher Getr\u00e4nke eine wichtige Rolle. Erstens k\u00f6nnen Hydrokolloide im Rahmen der Vorschriften als Ballaststoffe wie Gummi arabicum, Inulin und desodoriertes Guarkernmehl usw. den Getr\u00e4nken zugesetzt werden. Zweitens haben Hydrokolloide auch die Funktion, die Sedimentation und Delaminierung zu verhindern, das Getreideprotein zu sch\u00fctzen, die Wasserabsorption und Quellung der Rohfasern zu kontrollieren und die Alterung der St\u00e4rke w\u00e4hrend der Haltbarkeit zu verhindern, usw. in den Lebensmitteln und Getr\u00e4nkesubstituten aus Getreide, die eine gro\u00dfe Menge an Rohfasern enthalten. Alterung der St\u00e4rke w\u00e4hrend der Lagerzeit. Zusammengesetzte Stabilisatoren sind eine gute Wahl, um derartige Probleme der Produktqualit\u00e4t zu l\u00f6sen.<\/p>\n<p><strong>Feste Getr\u00e4nke<\/strong><\/p>\n<p>Hydrokolloide in festen Getr\u00e4nken haben die Funktion, den Geschmack zu verbessern und die feinen festen Partikel (wie Teepulver, Kaffeepulver, Kakaopulver), die sich nur schwer in Wasser aufl\u00f6sen lassen, zu suspendieren. Da feste Getr\u00e4nke sehr wichtig f\u00fcr die Zubereitung und den Verzehr sind, m\u00fcssen wir eine starke Sofortl\u00f6slichkeit w\u00e4hlen, und die mikrobielle Kontrolle ist strenger als bei kolloidalen Produkten. Wie z. B. Instant-Xanthan, instant, desodoriertes Guarkernmehl und Carrageen.<\/p>\n<p><strong>Andere<\/strong><\/p>\n<p>In Bier und anderen alkoholischen Getr\u00e4nken kann Propylenglykolalginat als Schaumstabilisator verwendet werden. In Getr\u00e4nken, die nat\u00fcrliche oder k\u00fcnstliche suspendierte Zellstoff kann als suspendierte Kolloid wird einen Platz haben, in den pH-Wert von nur 1,5-2,1 der m\u00fcndlichen Spray-Typ fl\u00fcssige S\u00fc\u00dfigkeiten (ein Low-S\u00e4ure-Getr\u00e4nke) in der Notwendigkeit f\u00fcr s\u00e4urebest\u00e4ndig stark Instant-Xanthan und Pektin und so weiter.<\/p>\n<p>In den letzten Jahren ist die Geschwindigkeit der Getr\u00e4nke-Innovation ist schneller, viele neue und interessante nahrhafte und leckere Getr\u00e4nke weiterhin auf dem Markt auftauchen, so dass die Anwendung von Hydrokolloiden in Getr\u00e4nken wird zwangsl\u00e4ufig mehr und mehr, und die Anwendung der Technologie muss durch die Getr\u00e4nke Formulierung Entwickler und Hydrokolloid Entwicklung und Anwendung der gemeinsamen Anstrengungen des Personals perfektioniert werden.<\/p>","protected":false},"excerpt":{"rendered":"<p>The application of hydrocolloids can be traced back to ancient Egypt, Europeans have long been familiar with St. John&#8217;s bread that acacia bean gum. China&#8217;s Jin Dynasty has begun to cultivate konjac, (Shu Du Fu) in the clouds of its nursery is a medicine Jian, capsule Jian refers to konjac (which can be used to [&hellip;]<\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>What are the applications of hydrocolloids in beverages? - China Chemical Manufacturer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/longchangextracts.com\/de\/hydrocolloids\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"What are the applications of hydrocolloids in beverages? - China Chemical Manufacturer\" \/>\n<meta property=\"og:description\" content=\"The application of hydrocolloids can be traced back to ancient Egypt, Europeans have long been familiar with St. John&#8217;s bread that acacia bean gum. China&#8217;s Jin Dynasty has begun to cultivate konjac, (Shu Du Fu) in the clouds of its nursery is a medicine Jian, capsule Jian refers to konjac (which can be used to [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/longchangextracts.com\/de\/hydrocolloids\/\" \/>\n<meta property=\"og:site_name\" content=\"China Chemical Manufacturer\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-06T12:58:25+00:00\" \/>\n<meta name=\"author\" content=\"Mrzhao\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mrzhao\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/longchangextracts.com\/hydrocolloids\/\",\"url\":\"https:\/\/longchangextracts.com\/hydrocolloids\/\",\"name\":\"What are the applications of hydrocolloids in beverages? - China Chemical Manufacturer\",\"isPartOf\":{\"@id\":\"https:\/\/longchangextracts.com\/#website\"},\"datePublished\":\"2024-08-06T12:58:25+00:00\",\"dateModified\":\"2024-08-06T12:58:25+00:00\",\"author\":{\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80f128fa4967f2080f7577af46a2bfb3\"},\"breadcrumb\":{\"@id\":\"https:\/\/longchangextracts.com\/hydrocolloids\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/longchangextracts.com\/hydrocolloids\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/longchangextracts.com\/hydrocolloids\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/longchangextracts.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"What are the applications of hydrocolloids in beverages?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/longchangextracts.com\/#website\",\"url\":\"https:\/\/longchangextracts.com\/\",\"name\":\"China Chemical Manufacturer\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/longchangextracts.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/80f128fa4967f2080f7577af46a2bfb3\",\"name\":\"Mrzhao\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5b7d172a0978697481379e6a4a769a17?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5b7d172a0978697481379e6a4a769a17?s=96&d=mm&r=g\",\"caption\":\"Mrzhao\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Was sind die Anwendungen von Hydrokolloiden in Getr\u00e4nken? - China Chemischer Hersteller","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/longchangextracts.com\/de\/hydrocolloids\/","og_locale":"de_DE","og_type":"article","og_title":"What are the applications of hydrocolloids in beverages? - China Chemical Manufacturer","og_description":"The application of hydrocolloids can be traced back to ancient Egypt, Europeans have long been familiar with St. John&#8217;s bread that acacia bean gum. China&#8217;s Jin Dynasty has begun to cultivate konjac, (Shu Du Fu) in the clouds of its nursery is a medicine Jian, capsule Jian refers to konjac (which can be used to [&hellip;]","og_url":"https:\/\/longchangextracts.com\/de\/hydrocolloids\/","og_site_name":"China Chemical Manufacturer","article_published_time":"2024-08-06T12:58:25+00:00","author":"Mrzhao","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Mrzhao","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/longchangextracts.com\/hydrocolloids\/","url":"https:\/\/longchangextracts.com\/hydrocolloids\/","name":"Was sind die Anwendungen von Hydrokolloiden in Getr\u00e4nken? - China Chemischer Hersteller","isPartOf":{"@id":"https:\/\/longchangextracts.com\/#website"},"datePublished":"2024-08-06T12:58:25+00:00","dateModified":"2024-08-06T12:58:25+00:00","author":{"@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80f128fa4967f2080f7577af46a2bfb3"},"breadcrumb":{"@id":"https:\/\/longchangextracts.com\/hydrocolloids\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/longchangextracts.com\/hydrocolloids\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/longchangextracts.com\/hydrocolloids\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/longchangextracts.com\/"},{"@type":"ListItem","position":2,"name":"What are the applications of hydrocolloids in beverages?"}]},{"@type":"WebSite","@id":"https:\/\/longchangextracts.com\/#website","url":"https:\/\/longchangextracts.com\/","name":"China Chemische Hersteller","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/longchangextracts.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/80f128fa4967f2080f7577af46a2bfb3","name":"Mrzhao","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/longchangextracts.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5b7d172a0978697481379e6a4a769a17?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b7d172a0978697481379e6a4a769a17?s=96&d=mm&r=g","caption":"Mrzhao"}}]}},"_links":{"self":[{"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/posts\/6670"}],"collection":[{"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/comments?post=6670"}],"version-history":[{"count":1,"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/posts\/6670\/revisions"}],"predecessor-version":[{"id":6671,"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/posts\/6670\/revisions\/6671"}],"wp:attachment":[{"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/media?parent=6670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/categories?post=6670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/longchangextracts.com\/de\/wp-json\/wp\/v2\/tags?post=6670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}